[{"id":4677,"date":"2026-04-28T09:12:44","date_gmt":"2026-04-28T14:12:44","guid":{"rendered":"https:\/\/fabricinnovation.ca\/funding-recognition\/"},"modified":"2026-05-09T00:28:30","modified_gmt":"2026-05-09T05:28:30","slug":"funding-recognition","status":"publish","type":"page","link":"https:\/\/fabricinnovation.ca\/fr\/funding-recognition\/","title":{"rendered":"Reconnaissance du financement"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4677\" class=\"elementor elementor-4677 elementor-4674\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-62c7302 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"62c7302\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-63cb52d\" data-id=\"63cb52d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;,&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d92d97a elementor-widget elementor-widget-heading\" data-id=\"d92d97a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><b>Reconnaissance <\/b>du financement<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e522e77 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e522e77\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5e4dc8d\" data-id=\"5e4dc8d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1249584 elementor-widget elementor-widget-spacer\" data-id=\"1249584\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7df8567 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7df8567\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-22b363e\" data-id=\"22b363e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a85741 elementor-widget elementor-widget-text-editor\" data-id=\"6a85741\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les projets financ\u00e9s sont encourag\u00e9s \u00e0 afficher le soutien de FABrIC \/ CMC \/ Gouvernement du Canada sur leur site Web. Afin de tenir compte des contraintes d\u2019espace, trois options bilingues de combinaison de logos sont offertes\u202f: en couleur (option privil\u00e9gi\u00e9e), en noir et blanc et en blanc (version d\u00e9tour\u00e9e) pour les arri\u00e8re\u2011plans fonc\u00e9s. <\/p><p>Vous pouvez t\u00e9l\u00e9charger les logos <a href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/FABrIC_logo_lockup.zip\">ici<\/a>.<\/p><p>Le texte passe\u2011partout de FABrIC est pr\u00e9sent\u00e9 ci\u2011dessous. Ce texte comprend \u00e9galement nos identifiants de m\u00e9dias sociaux. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3996b9c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3996b9c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9157cc6\" data-id=\"9157cc6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a04b26 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3a04b26\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dac5603 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dac5603\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1780b8d\" data-id=\"1780b8d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a3163e9 elementor-widget elementor-widget-heading\" data-id=\"a3163e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FABrIC boilerplate \u2014 Fran\u00e7ais<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e402ba elementor-widget elementor-widget-heading\" data-id=\"5e402ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">FABrIC : un investissement g\u00e9n\u00e9rationnel du gouvernement du Canada<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a61ce8 elementor-widget elementor-widget-text-editor\" data-id=\"7a61ce8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>FABrIC est une initiative du Fonds de r\u00e9ponse strat\u00e9gique du gouvernement du Canada visant \u00e0 renforcer les capacit\u00e9s nationales en conception et en fabrication avanc\u00e9es de semi\u2011conducteurs.<\/p><p>G\u00e9r\u00e9 par CMC Microsyst\u00e8mes, FABrIC mobilise les forces nationales en photonique, en MEMS, en semi\u2011conducteurs compos\u00e9s et en technologies quantiques. Le programme acc\u00e9l\u00e8re la commercialisation et renforce les avantages concurrentiels du Canada en maximisant les retomb\u00e9es \u00e9conomiques de son secteur des semi\u2011conducteurs.<\/p><p>Parmi les programmes phares figurent le financement par d\u00e9fis, le Bac \u00e0 sable d\u2019informatique quantique et la formation. Le financement par d\u00e9fis soutient le d\u00e9veloppement de proc\u00e9d\u00e9s de fabrication et de produits IdO (Internet des objets) qui renforcent les capacit\u00e9s nationales. Le bac \u00e0 sable d\u2019informatique quantique est le premier programme au Canada \u00e0 offrir un acc\u00e8s \u00e0 des plateformes de calcul quantique de pointe. Le portefeuille de formation FABrIC propose le d\u00e9veloppement de comp\u00e9tences sp\u00e9cialis\u00e9es aux \u00e9tudiantes et \u00e9tudiants aux cycles sup\u00e9rieurs ainsi qu\u2019aux professionnelles et professionnels en d\u00e9but et en milieu de carri\u00e8re, dans les proc\u00e9d\u00e9s hautement techniques et exigeants du secteur des semi\u2011conducteurs.   <\/p><p><a href=\"https:\/\/www.linkedin.com\/company\/cmc-microsystems\/\">Linkedin<\/a> <br\/><a href=\"https:\/\/www.facebook.com\/cmc.microsystems\">Facebook<\/a> <br\/><a href=\"https:\/\/www.instagram.com\/cmcmicrosystems\/\">Instagram<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-92a0833 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"92a0833\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fd8289b\" data-id=\"fd8289b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63a88c1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"63a88c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1f89ffc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1f89ffc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b706199\" data-id=\"b706199\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b5f544 elementor-widget elementor-widget-heading\" data-id=\"7b5f544\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FABrIC boilerplate \u2014 Anglais<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0be7bf9 elementor-widget elementor-widget-heading\" data-id=\"0be7bf9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">FABrIC: A generational investment by the Government of Canada<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ab4de7 elementor-widget elementor-widget-text-editor\" data-id=\"6ab4de7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>FABrIC is a Strategic Response Fund initiative of the Government of Canada to advance domestic capabilities in advanced semiconductor design and manufacturing.<\/p><p>Managed by CMC Microsystems, FABrIC galvanizes national strengths in photonics, MEMS, compound semiconductors and quantum technologies, accelerating commercialization and amplifying Canada\u2019s competitive advantages by maximizing the economic impact of its semiconductor sector. <\/p><p>Marquee programs include Challenge funding, the Quantum Computing Sandbox and Training. Challenge funding supports the development of fabrication processes and IoT products that build national capacity. The Quantum Computing Sandbox is Canada\u2019s first program to enable access to state-of-the-art quantum computing platforms. The FABrIC training portfolio provides specialized skills development for graduate students, early and mid-career professionals in the highly technical and demanding processes of the semiconductor sector.   <\/p><p><a href=\"https:\/\/www.linkedin.com\/company\/cmc-microsystems\/\">Linkedin<\/a> <br\/><a href=\"https:\/\/www.facebook.com\/cmc.microsystems\">Facebook<\/a> <br\/><a href=\"https:\/\/www.instagram.com\/cmcmicrosystems\/\">Instagram<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fcaa1bd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fcaa1bd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ab13165\" data-id=\"ab13165\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a7bd79f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a7bd79f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Reconnaissance du financement Les projets financ\u00e9s sont encourag\u00e9s \u00e0 afficher le soutien de FABrIC \/ CMC \/ Gouvernement du Canada sur leur site Web. Afin de tenir compte des contraintes [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-4677","page","type-page","status-publish","hentry"],"acf":[],"featured_image_src":null,"featured_image_src_square":null,"_links":{"self":[{"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/pages\/4677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/comments?post=4677"}],"version-history":[{"count":0,"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/pages\/4677\/revisions"}],"wp:attachment":[{"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/media?parent=4677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":4382,"date":"2026-03-11T08:09:08","date_gmt":"2026-03-11T13:09:08","guid":{"rendered":"https:\/\/fabricinnovation.ca\/mining\/"},"modified":"2026-03-12T13:47:33","modified_gmt":"2026-03-12T18:47:33","slug":"mining","status":"publish","type":"page","link":"https:\/\/fabricinnovation.ca\/fr\/mining\/","title":{"rendered":"Secteur minier"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4382\" class=\"elementor elementor-4382 elementor-4379\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bfa8c68 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bfa8c68\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-88b40c9\" data-id=\"88b40c9\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2996623 elementor-widget elementor-widget-spacer\" data-id=\"2996623\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c68aaac\" data-id=\"c68aaac\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef01de0 elementor-widget elementor-widget-spacer\" data-id=\"ef01de0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2ddf220\" data-id=\"2ddf220\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;background_motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b7ec17 elementor-widget__width-initial elementor-widget elementor-widget-spacer\" data-id=\"7b7ec17\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7809859 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7809859\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bb936d0\" data-id=\"bb936d0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-18a813b elementor-widget elementor-widget-heading\" data-id=\"18a813b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><b>Secteur minier<\/b><br>\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-01d2b71 elementor-widget elementor-widget-spacer\" data-id=\"01d2b71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e3d5b8b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e3d5b8b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-bb75235\" data-id=\"bb75235\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-662cb6f elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"662cb6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/elementor\/thumbs\/mining-rkcp2bhqehmtv8ujhg653z57epmx99iqg0exag7qwg.jpg\" title=\"mining\" alt=\"mining\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c961c29\" data-id=\"c961c29\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d36d9a6 elementor-widget elementor-widget-heading\" data-id=\"d36d9a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Secteur minier<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3086eea elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3086eea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a61d7b9 elementor-widget elementor-widget-text-editor\" data-id=\"a61d7b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le succ\u00e8s, la s\u00e9curit\u00e9 et la durabilit\u00e9 du secteur minier canadien sont rendus possibles gr\u00e2ce aux semi\u2011conducteurs \u2013 les industries mini\u00e8re et des semi\u2011conducteurs entretiennent un lien profond et symbiotique.<\/p><p>L\u2019industrie mini\u00e8re b\u00e9n\u00e9ficie de la technologie des semi\u2011conducteurs sur le terrain, que ce soit pour l\u2019exploration ou pour les op\u00e9rations mini\u00e8res actives.<\/p><p>Des capteurs avanc\u00e9s, des syst\u00e8mes robotiques et des syst\u00e8mes miniers autonomes sont remplis de technologies \u00e0 semi\u2011conducteurs. Ils alimentent l\u2019intelligence qui sous\u2011tend l\u2019automatisation des \u00e9quipements, les communications haute performance, la maintenance pr\u00e9dictive et la surveillance environnementale. Les op\u00e9rations mini\u00e8res int\u00e8grent des dispositifs \u00e0 base de semi\u2011conducteurs pour le suivi en temps r\u00e9el de l\u2019\u00e9tat des \u00e9quipements, le tri du minerai, le forage autonome et la gestion de la s\u00e9curit\u00e9.  <\/p><p>En dehors de la mine, les jumeaux num\u00e9riques aliment\u00e9s par l\u2019IA et l\u2019analyse de donn\u00e9es reposent sur des microprocesseurs \u00e0 haute capacit\u00e9 de traitement. Ils am\u00e9liorent la productivit\u00e9 mini\u00e8re, r\u00e9duisent les co\u00fbts, assurent la conformit\u00e9 r\u00e9glementaire et favorisent la durabilit\u00e9.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ee2faf2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ee2faf2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1e253a2\" data-id=\"1e253a2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab0c52a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ab0c52a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-267ed49 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"267ed49\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4fdf1d2\" data-id=\"4fdf1d2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29ac106 elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"29ac106\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/elementor\/thumbs\/iStock-1436493161-scaled-qqm7617g4ck1ma8ebsfssacjqlqhtnf1e2efb5dzg4.jpg\" title=\"Scientist hold in fingers fitness tracker smart watch component with different sensors array\" alt=\"Scientist hold in fingers fitness tracker smart watch component with different sensors array, pulse optical heart rate, skin temperature, blood oxygen saturation SpO2\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a2b9439\" data-id=\"a2b9439\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39c78da elementor-widget elementor-widget-heading\" data-id=\"39c78da\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Les capteurs \u00e0 semi\u2011conducteurs rendent les mines plus s\u00fbres<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f99a0ac elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f99a0ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30a215e elementor-widget elementor-widget-text-editor\" data-id=\"30a215e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les mines utilisent une vaste gamme de capteurs connect\u00e9s qui assurent l\u2019int\u00e9grit\u00e9 des sites miniers et la s\u00e9curit\u00e9 des travailleurs. Les capteurs sont essentiels pour des mines plus intelligentes et plus s\u00fbres. <\/p><p>Ils surveillent en continu les mines afin de d\u00e9tecter les dangers potentiels. Lorsqu\u2019un risque est identifi\u00e9, ils envoient des alertes instantan\u00e9es pour permettre des interventions rapides, r\u00e9duire les erreurs humaines et limiter les risques d\u2019accidents et de blessures. <\/p><p>Les capteurs intelligents prot\u00e8gent \u00e0 la fois la sant\u00e9 des travailleurs et celle des \u00e9quipements miniers. Ils soutiennent la maintenance pr\u00e9dictive, r\u00e9duisant ainsi les temps d\u2019arr\u00eat et les perturbations susceptibles d\u2019affecter la rentabilit\u00e9 de la mine et de l\u2019ensemble de l\u2019entreprise mini\u00e8re. <\/p><p>De nombreux types de capteurs utilis\u00e9s dans les op\u00e9rations mini\u00e8res sont rendus possibles gr\u00e2ce aux avanc\u00e9es de la technologie des semi\u2011conducteurs :<\/p><ul style=\"list-style-type: square;\"><li>Capteurs de vibration et sismiques : Les acc\u00e9l\u00e9rom\u00e8tres et capteurs sismiques mont\u00e9s en surface (SMT) d\u00e9tectent l\u2019instabilit\u00e9 m\u00e9canique, les mouvements du sol et les premiers signes d\u2019\u00e9boulements ou d\u2019effondrements.<\/li><li>Capteurs de flux d\u2019air et de pression : Ils permettent de surveiller la ventilation des puits de mine et les syst\u00e8mes hydrauliques afin de maintenir des conditions de travail s\u00fbres et de pr\u00e9venir les d\u00e9faillances d\u2019\u00e9quipement. Le contr\u00f4le du flux d\u2019air r\u00e9duit les risques d\u2019accumulation de gaz ou d\u2019asphyxie. <\/li><li>D\u00e9tecteurs de gaz et de fum\u00e9e : Les capteurs \u00e0 semi\u2011conducteurs d\u00e9tectent des gaz dangereux comme le monoxyde de carbone, le m\u00e9thane ou les d\u00e9buts d\u2019incendie, d\u00e9clenchant des alertes pour \u00e9vacuation ou intervention afin de r\u00e9duire les risques d\u2019empoisonnement ou d\u2019explosion.<\/li><li>Capteurs de temp\u00e9rature et d\u2019humidit\u00e9 : Ces capteurs sp\u00e9cialis\u00e9s surveillent la temp\u00e9rature et l\u2019humidit\u00e9 souterraines pour identifier les risques de maladies li\u00e9es \u00e0 la chaleur chez les travailleurs et pr\u00e9venir la surchauffe des \u00e9quipements.<\/li><li>Dispositifs de s\u00e9curit\u00e9 portables : Les appareils mains libres \u00e0 base de semi\u2011conducteurs suivent la localisation des travailleurs, leurs signes vitaux et leur exposition environnementale, alertant les op\u00e9rateurs en cas de d\u00e9faillance d\u2019\u00e9quipement, de fuite de gaz ou d\u2019entr\u00e9e dans une zone dangereuse.<\/li><li>Capteurs d\u2019imagerie et de cartographie : Les radars \u00e0 ondes millim\u00e9triques, les capteurs visuels avanc\u00e9s et les puces de cartographie g\u00e9n\u00e8rent des mod\u00e8les 3D en temps r\u00e9el des environnements miniers. Ils aident \u00e0 d\u00e9tecter fissures, failles et obstructions \u2014 particuli\u00e8rement utile dans les conditions de faible visibilit\u00e9 o\u00f9 les cam\u00e9ras traditionnelles et le LiDAR sont insuffisants. <\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5fb1c77 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5fb1c77\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ceca97b\" data-id=\"ceca97b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a861d7 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2a861d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-39bb531 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"39bb531\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6751345\" data-id=\"6751345\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bf89cb6 elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"bf89cb6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/elementor\/thumbs\/iStock-1147796744-scaled-r6tt0upngra99gnoetl8ba753j3ow8mfiufxvsk3as.jpg\" title=\"MEMS\" alt=\"abstract\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-402792d\" data-id=\"402792d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b8066a6 elementor-widget elementor-widget-heading\" data-id=\"b8066a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">MEMS : id\u00e9aux pour la surveillance mini\u00e8re<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4133980 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4133980\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d59d0a elementor-widget elementor-widget-text-editor\" data-id=\"3d59d0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les syst\u00e8mes micro\u2011\u00e9lectrom\u00e9caniques (MEMS) bas\u00e9s sur des semi\u2011conducteurs \u2014 des dispositifs qui combinent de minuscules composants m\u00e9caniques et \u00e9lectroniques \u00e0 l\u2019\u00e9chelle microscopique et construits sur une technologie de semi\u2011conducteurs \u2014 sont particuli\u00e8rement utiles. Les dispositifs \u00e0 base de MEMS sont largement utilis\u00e9s dans les syst\u00e8mes industriels de surveillance conditionnelle pour la maintenance pr\u00e9dictive. <\/p><p>Les acc\u00e9l\u00e9rom\u00e8tres MEMS mesurent les vibrations selon plusieurs axes, permettant une d\u00e9tection haute r\u00e9solution des variations de fr\u00e9quence, d\u2019amplitude ou des signatures vibratoires qui pr\u00e9c\u00e8dent une d\u00e9faillance mat\u00e9rielle, comme la d\u00e9gradation de roulements, le d\u00e9salignement d\u2019engrenages ou le d\u00e9s\u00e9quilibre d\u2019un arbre. Ces acc\u00e9l\u00e9rom\u00e8tres sont petits, \u00e9conomiques, offrent une sortie num\u00e9rique int\u00e9gr\u00e9e et une sensibilit\u00e9 stable malgr\u00e9 les variations de temp\u00e9rature. <\/p><p>Les donn\u00e9es vibratoires sont collect\u00e9es en continu et envoy\u00e9es aux syst\u00e8mes de surveillance, o\u00f9 des algorithmes comparent les mesures en temps r\u00e9el \u00e0 des r\u00e9f\u00e9rences de fonctionnement normal. Les signes pr\u00e9curseurs incluent une augmentation des vibrations \u00e0 certaines harmoniques, des pics d\u2019amplitude ou des \u00e9v\u00e9nements de fr\u00e9quence irr\u00e9guliers indiquant des d\u00e9fauts \u00e9mergents. <\/p><p>Lorsque des anomalies sont d\u00e9tect\u00e9es par les donn\u00e9es de l\u2019acc\u00e9l\u00e9rom\u00e8tre MEMS, des alertes automatis\u00e9es sont d\u00e9clench\u00e9es pour inspection manuelle ou maintenance pr\u00e9dictive, permettant une intervention rapide avant une d\u00e9faillance compl\u00e8te.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-33a5582 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"33a5582\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b55fd42\" data-id=\"b55fd42\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-80a6aff elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"80a6aff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7cb798f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7cb798f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7483d0c\" data-id=\"7483d0c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17e24c7 elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"17e24c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/elementor\/thumbs\/iStock-929318450-scaled-r6tt5cdw49dl4bfu0i3gd9zdxce47kj4dvf1c11yx4.jpg\" title=\"Semi-conducteurs\" alt=\"abstract\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9f8d048\" data-id=\"9f8d048\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f755fc elementor-widget elementor-widget-heading\" data-id=\"1f755fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La technologie des semi\u2011conducteurs pour l\u2019exploitation mini\u00e8re privil\u00e9gie la fiabilit\u00e9<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ef6a13 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1ef6a13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0bdda60 elementor-widget elementor-widget-text-editor\" data-id=\"0bdda60\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les normes de fiabilit\u00e9 des semi\u2011conducteurs destin\u00e9s au secteur minier vont bien au\u2011del\u00e0 des normes g\u00e9n\u00e9riques appliqu\u00e9es dans la plupart des industries. Ils doivent tol\u00e9rer des chocs m\u00e9caniques fr\u00e9quents, de fortes vibrations, des interf\u00e9rences \u00e9lectromagn\u00e9tiques, de larges variations de temp\u00e9rature, l\u2019humidit\u00e9 et des atmosph\u00e8res corrosives.  <\/p><p>Les tests et mod\u00e8les de fiabilit\u00e9 pour la technologie des semi\u2011conducteurs dans le domaine minier sont adapt\u00e9s aux conditions r\u00e9elles d\u2019exploitation. Cela inclut les cycles thermiques, les profils de chocs, les sch\u00e9mas de tension\/charge et l\u2019exposition environnementale. <\/p><p>La technologie \u00e0 base de semi\u2011conducteurs utilis\u00e9e dans les environnements miniers est sp\u00e9cifique \u00e0 chaque application. Elle n\u00e9cessite des tests approfondis, un durcissement environnemental et une surveillance dynamique pour garantir des op\u00e9rations s\u00fbres et ininterrompues. Non seulement la technologie des semi\u2011conducteurs pour le secteur minier doit durer de nombreuses ann\u00e9es, mais elle doit aussi r\u00e9sister \u00e0 des conditions difficiles et impr\u00e9visibles, dans des lieux o\u00f9 les remplacements et r\u00e9parations sont co\u00fbteux et dangereux.   <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4d420f9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4d420f9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5ab8f75\" data-id=\"5ab8f75\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-861ad71 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"861ad71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a0381d4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a0381d4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3d3ddaf\" data-id=\"3d3ddaf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b3ff6bd elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"b3ff6bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/elementor\/thumbs\/vecteezy_a-photo-of-a-self-driving-car-navigating-through-a_26805780-ra765jdbc3libopp4j9pn9jtlx2iilutju8om0qmeo.jpg\" title=\"Une photo d&rsquo;une voiture autonome circulant dans un paysage urbain, illustrant les progr\u00e8s r\u00e9alis\u00e9s dans le domaine de la technologie des v\u00e9hicules autonomes. IA g\u00e9n\u00e9rative\" alt=\"Une photo d&#039;une voiture autonome circulant dans un paysage urbain, illustrant les progr\u00e8s r\u00e9alis\u00e9s dans le domaine de la technologie des v\u00e9hicules autonomes gr\u00e2ce \u00e0 l&#039;IA g\u00e9n\u00e9rative.\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e86d36d\" data-id=\"e86d36d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-60fb8a2 elementor-widget elementor-widget-heading\" data-id=\"60fb8a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Les v\u00e9hicules autonomes maintiennent les mines en mouvement<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a98eb3 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1a98eb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df402d2 elementor-widget elementor-widget-text-editor\" data-id=\"df402d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les v\u00e9hicules autonomes r\u00e9volutionnent l\u2019industrie mini\u00e8re \u2014 et les semi\u2011conducteurs alimentent l\u2019intelligence qui les fait fonctionner. Les camions miniers autonomes am\u00e9liorent l\u2019efficacit\u00e9, la s\u00e9curit\u00e9 et la durabilit\u00e9. <\/p><p>La gestion avanc\u00e9e des flottes pilot\u00e9e par l\u2019IA, les capteurs, le LiDAR et l\u2019analyse de donn\u00e9es en temps r\u00e9el permettent aux v\u00e9hicules miniers autonomes de fonctionner 24 heures sur 24. Cela r\u00e9duit l\u2019exposition des travailleurs aux conditions dangereuses et limite la surcharge de travail. Gr\u00e2ce \u00e0 des syst\u00e8mes de navigation de pr\u00e9cision et \u00e0 des r\u00e9seaux 5G robustes assurant coordination en temps r\u00e9el et op\u00e9rations \u00e0 distance, ces v\u00e9hicules diminuent l\u2019impact environnemental gr\u00e2ce \u00e0 des op\u00e9rations mini\u00e8res plus intelligentes et continues, g\u00e9r\u00e9es \u00e0 distance par l\u2019IA et des capteurs avanc\u00e9s. Les groupes motopropulseurs \u00e9lectrifi\u00e9s et hybrides contribuent \u00e9galement \u00e0 r\u00e9duire les \u00e9missions.   <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2d46c7f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2d46c7f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-47dd879\" data-id=\"47dd879\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29cf5fe elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"29cf5fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6dc83f1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6dc83f1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-789fcf7\" data-id=\"789fcf7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a83d2ab elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"a83d2ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/elementor\/thumbs\/iStock-1204583853-scaled-rix2c66d27azlffg4dxxco0rthnjbputun9t77nfxc.jpg\" title=\"IA\" alt=\"IA\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7e0a349\" data-id=\"7e0a349\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e53091e elementor-widget elementor-widget-heading\" data-id=\"e53091e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">IA, calcul haute performance et informatique quantique<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-883deba elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"883deba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35c1a10 elementor-widget elementor-widget-text-editor\" data-id=\"35c1a10\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L\u2019IA et le calcul haute performance sont largement d\u00e9ploy\u00e9s tout au long de la cha\u00eene de valeur mini\u00e8re pour optimiser l\u2019efficacit\u00e9, accro\u00eetre la productivit\u00e9, assurer la s\u00e9curit\u00e9 et favoriser la durabilit\u00e9.<\/p><ul style=\"list-style-type: square;\"><li>Les algorithmes d\u2019apprentissage automatique peuvent pr\u00e9voir la demande en min\u00e9raux, r\u00e9duisant le gaspillage et les forages inutiles en analysant les donn\u00e9es g\u00e9ologiques pour cibler avec pr\u00e9cision les gisements.<\/li><li>La vision par ordinateur peut automatiser le tri et la classification du minerai, acc\u00e9l\u00e9rant consid\u00e9rablement le processus et am\u00e9liorant la pr\u00e9cision par rapport aux m\u00e9thodes manuelles.<\/li><li>La consommation d\u2019\u00e9nergie et d\u2019eau dans les installations mini\u00e8res peut \u00eatre optimis\u00e9e, permettant d\u2019importantes \u00e9conomies de ressources et une r\u00e9duction de l\u2019impact environnemental.<\/li><li>Les syst\u00e8mes de maintenance pr\u00e9dictive minimisent les temps d\u2019arr\u00eat en analysant les donn\u00e9es des capteurs pour anticiper les d\u00e9faillances des machines.<\/li><\/ul><p>L\u2019informatique quantique dans le secteur minier \u00e9volue du th\u00e9orique vers le pratique pour aider \u00e0 relever des d\u00e9fis industriels critiques et soutenir l\u2019innovation dans la d\u00e9couverte, l\u2019extraction et la gestion des ressources.<\/p><p>L\u2019informatique quantique est \u00e9galement explor\u00e9e pour divers aspects de l\u2019exploitation mini\u00e8re, notamment l\u2019exploration min\u00e9rale et l\u2019optimisation des \u00e9quipements, car elle d\u00e9passe les capacit\u00e9s du calcul classique. Les ordinateurs quantiques peuvent traiter d\u2019immenses ensembles de donn\u00e9es provenant de capteurs satellitaires et terrestres. Cela permet de d\u00e9velopper des mod\u00e8les g\u00e9ologiques extr\u00eamement pr\u00e9cis capables de d\u00e9tecter plus efficacement les gisements \u2014 r\u00e9duisant les forages inutiles et am\u00e9liorant les rendements d\u2019exploration.  <\/p><p>La combinaison de capteurs quantiques avec l\u2019IA et les m\u00e9thodes classiques acc\u00e9l\u00e8re les d\u00e9lais d\u2019exploration et r\u00e9duit l\u2019impact environnemental gr\u00e2ce \u00e0 des lev\u00e9s moins invasifs. Les capteurs quantiques avanc\u00e9s offrent une imagerie souterraine haute r\u00e9solution et \u00e0 faible d\u00e9rive pour la prospection min\u00e9rale et l\u2019estimation des ressources. <\/p><p>Les op\u00e9rations mini\u00e8res peuvent \u00eatre optimis\u00e9es gr\u00e2ce \u00e0 des algorithmes quantiques capables de r\u00e9soudre des probl\u00e8mes d\u2019optimisation extr\u00eamement complexes, tels que la configuration des \u00e9quipements, la planification ou la maintenance pr\u00e9dictive. Ils permettent m\u00eame des ajustements en temps r\u00e9el des processus pour optimiser les flux de ressources et r\u00e9duire les d\u00e9chets dans l\u2019ensemble des op\u00e9rations. <\/p><p>L\u2019informatique quantique devrait \u00e9galement s\u2019\u00e9tendre \u00e0 la science des mat\u00e9riaux. Elle pourrait aider \u00e0 concevoir de nouveaux catalyseurs pour une extraction plus efficace, des alliages r\u00e9sistants \u00e0 la corrosion pour les \u00e9quipements, ainsi que des technologies vertes innovantes qui deviendront essentielles \u00e0 mesure que l\u2019exploitation mini\u00e8re \u00e0 faible carbone se d\u00e9veloppera. <\/p><p>Avec les perturbations des cha\u00eenes d\u2019approvisionnement et l\u2019incertitude g\u00e9opolitique qui bouleversent les relations commerciales mondiales, une collaboration renforc\u00e9e entre le secteur national des semi\u2011conducteurs et les op\u00e9rations mini\u00e8res permettra aux deux industries de tirer parti des nouvelles opportunit\u00e9s \u00e9mergentes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8756744 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8756744\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9ebca81\" data-id=\"9ebca81\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7eb1b4c elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7eb1b4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0319d7e elementor-widget elementor-widget-spacer\" data-id=\"0319d7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Secteur minier Secteur minier Le succ\u00e8s, la s\u00e9curit\u00e9 et la durabilit\u00e9 du secteur minier canadien sont rendus possibles gr\u00e2ce aux semi\u2011conducteurs \u2013 les industries mini\u00e8re et des semi\u2011conducteurs entretiennent un [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-4382","page","type-page","status-publish","hentry"],"acf":[],"featured_image_src":null,"featured_image_src_square":null,"_links":{"self":[{"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/pages\/4382","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/comments?post=4382"}],"version-history":[{"count":0,"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/pages\/4382\/revisions"}],"wp:attachment":[{"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/media?parent=4382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":4476,"date":"2026-03-03T14:39:37","date_gmt":"2026-03-03T19:39:37","guid":{"rendered":"https:\/\/fabricinnovation.ca\/?page_id=4476"},"modified":"2026-05-12T08:53:58","modified_gmt":"2026-05-12T13:53:58","slug":"speakers","status":"publish","type":"page","link":"https:\/\/fabricinnovation.ca\/fr\/css2026\/speakers\/","title":{"rendered":"Conf\u00e9renciers"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4476\" class=\"elementor elementor-4476 elementor-4337\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d2ed9b2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d2ed9b2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8a88636\" data-id=\"8a88636\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-771e6e5 elementor-widget elementor-widget-spacer\" data-id=\"771e6e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6261673\" data-id=\"6261673\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2866307 elementor-widget elementor-widget-spacer\" data-id=\"2866307\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5767c03\" data-id=\"5767c03\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-caafc36 elementor-widget__width-initial elementor-widget elementor-widget-spacer\" data-id=\"caafc36\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-85008e2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"85008e2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cdf47f6\" data-id=\"cdf47f6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d1759b3 elementor-widget elementor-widget-heading\" data-id=\"d1759b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Symposium canadien sur les semi-conducteurs 2026<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b8ed42 elementor-widget elementor-widget-heading\" data-id=\"0b8ed42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Conf\u00e9renciers<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-455bcbe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"455bcbe\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e28ec23\" data-id=\"e28ec23\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9e957e7 elementor-widget elementor-widget-template\" data-id=\"9e957e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"4322\" class=\"elementor elementor-4322\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f97ecfc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f97ecfc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1aa2fb9\" data-id=\"1aa2fb9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef95ed6 elementor-nav-menu__align-center elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"ef95ed6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-underline e--animation-fade\">\n\t\t\t\t<ul id=\"menu-1-ef95ed6\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4323\"><a href=\"https:\/\/fabricinnovation.ca\/css2026\/\" class=\"elementor-item menu-link\">CSS 2026<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4336\"><a href=\"https:\/\/fabricinnovation.ca\/css2026\/agenda\/\" class=\"elementor-item menu-link\">Programme<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4673\"><a href=\"https:\/\/fabricinnovation.ca\/css2026\/speakers\/\" class=\"elementor-item menu-link\">Conf\u00e9renciers<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4324\"><a href=\"https:\/\/fabricinnovation.ca\/texpo-2026\/\" class=\"elementor-item menu-link\">TEXPO 2026<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Permuter le menu\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-ef95ed6\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4323\"><a href=\"https:\/\/fabricinnovation.ca\/css2026\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">CSS 2026<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4336\"><a href=\"https:\/\/fabricinnovation.ca\/css2026\/agenda\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Programme<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4673\"><a href=\"https:\/\/fabricinnovation.ca\/css2026\/speakers\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Conf\u00e9renciers<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4324\"><a href=\"https:\/\/fabricinnovation.ca\/texpo-2026\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">TEXPO 2026<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba91426 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ba91426\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cd93a4b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cd93a4b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2f47503\" data-id=\"2f47503\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b4b3e75 elementor-widget elementor-widget-image\" data-id=\"b4b3e75\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/Manon-Duclos.jpg\" class=\"attachment-large size-large wp-image-4799\" alt=\"\" srcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/Manon-Duclos.jpg 500w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/Manon-Duclos-250x300.jpg 250w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/elementor\/thumbs\/Manon-Duclos-rbzmyxrizmn4nzg484psicm2i7zgvad0k5wjf61v3k.jpg 100w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1adb19f\" data-id=\"1adb19f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e49ce1 elementor-widget elementor-widget-menu-anchor\" data-id=\"5e49ce1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"manon\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34149a0 elementor-widget elementor-widget-heading\" data-id=\"34149a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Manon Duclos<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e65b04d elementor-widget elementor-widget-heading\" data-id=\"e65b04d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">PDG\n<br \/>Technum Qu\u00e9bec<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0a78cf3 elementor-widget elementor-widget-text-editor\" data-id=\"0a78cf3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Manon Duclos \u0153uvre dans les domaines de l\u2019innovation, de la qualit\u00e9 et de l\u2019excellence organisationnelle depuis plus de 30 ans. Ing\u00e9nieure chimique dipl\u00f4m\u00e9e de l\u2019Universit\u00e9 Laval et d\u00e9tentrice d\u2019une ma\u00eetrise en gestion de l\u2019ing\u00e9nierie de l\u2019Universit\u00e9 de Sherbrooke, elle a occup\u00e9 des r\u00f4les strat\u00e9giques dans des entreprises de pointe telles qu\u2019IBM, Mitel Semiconducteur et Teledyne DALSA.  <\/p><p>Son parcours vari\u00e9 lui a permis de d\u00e9velopper une expertise unique en gestion de projets complexes, en assurance qualit\u00e9 et en d\u00e9veloppement organisationnel, en plus de former des centaines de gestionnaires sur la culture d\u2019innovation et l\u2019importance de la qualit\u00e9 comme vecteur d\u2019excellence. Elle est \u00e9galement reconnue pour ses capacit\u00e9s \u00e0 mobiliser les acteurs de divers secteurs et \u00e0 b\u00e2tir des partenariats solides \u00e0 l\u2019\u00e9chelle locale et internationale. <br\/>Au Mouvement qu\u00e9b\u00e9cois de la qualit\u00e9, o\u00f9 elle a occup\u00e9 le poste de vice-pr\u00e9sidente \u00e0 l\u2019innovation et \u00e0 l\u2019excellence organisationnelle, elle a pilot\u00e9 des strat\u00e9gies innovantes, anim\u00e9 des r\u00e9seaux de gestionnaires \u00e0 travers le Qu\u00e9bec et contribu\u00e9 \u00e0 faire \u00e9voluer des organisations vers de nouveaux sommets. <\/p><p>R\u00e9sidente de la r\u00e9gion de Bromont depuis 30 ans, Manon conna\u00eet bien les atouts de son milieu, notamment en mati\u00e8re de qualit\u00e9 de vie et d\u2019innovation. En tant que PDG de Technum Qu\u00e9bec, une des premi\u00e8res zones d\u2019innovation du Qu\u00e9bec sp\u00e9cialis\u00e9e en \u00e9lectronique et en semi-conducteurs, elle continuera de stimuler les projets de collaboration novateurs et de positionner cette industrie comme un pilier de la transformation num\u00e9rique au Qu\u00e9bec et \u00e0 l\u2019international. <\/p><p>Manon Duclos est aussi conf\u00e9renci\u00e8re et auteure de plusieurs guides sur l\u2019innovation et l\u2019excellence organisationnelle. Elle demeure passionn\u00e9e par le d\u00e9passement de soi, la cr\u00e9ativit\u00e9 et le d\u00e9veloppement durable. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f00b5e3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f00b5e3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-030a190\" data-id=\"030a190\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef3bacb elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ef3bacb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-29cb497 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"29cb497\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2296c2b\" data-id=\"2296c2b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2c6f7a6 elementor-widget elementor-widget-image\" data-id=\"2c6f7a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/Gordon_Harling_bw.jpg\" class=\"attachment-large size-large wp-image-3295\" alt=\"\" srcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/Gordon_Harling_bw.jpg 500w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/Gordon_Harling_bw-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-798a1ad\" data-id=\"798a1ad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f0ccfe5 elementor-widget elementor-widget-menu-anchor\" data-id=\"f0ccfe5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"gord\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c792b99 elementor-widget elementor-widget-heading\" data-id=\"c792b99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Gordon Harling<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39c8c93 elementor-widget elementor-widget-heading\" data-id=\"39c8c93\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Pr\u00e9sident et directeur g\u00e9n\u00e9ral\n<br \/>CMC Microsyst\u00e8mes<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9534448 elementor-widget elementor-widget-text-editor\" data-id=\"9534448\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Gordon Harling est titulaire d&rsquo;une licence en sciences appliqu\u00e9es de l&rsquo;universit\u00e9 de Toronto et d&rsquo;une ma\u00eetrise en ing\u00e9nierie physique de Polytechnique Montr\u00e9al. Il a travaill\u00e9 dans le domaine de la recherche et du d\u00e9veloppement dans de grandes entreprises telles que Mitel, NovAtel et DALSA. Il a \u00e9t\u00e9 fondateur et PDG de plusieurs jeunes entreprises, dont Goal Semiconductor, Elliptic Technologies et Innotime Technologies.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1d9fc39 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1d9fc39\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c57e192\" data-id=\"c57e192\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d0dde6b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d0dde6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-70f6124 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"70f6124\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5836b79\" data-id=\"5836b79\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db9c7c5 elementor-widget elementor-widget-image\" data-id=\"db9c7c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/08\/paul_bw.png\" class=\"attachment-large size-large wp-image-3076\" alt=\"\" srcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/08\/paul_bw.png 500w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/08\/paul_bw-250x300.png 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5e56723\" data-id=\"5e56723\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa2d0e2 elementor-widget elementor-widget-menu-anchor\" data-id=\"aa2d0e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"paul\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df4f532 elementor-widget elementor-widget-heading\" data-id=\"df4f532\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Paul Slaby<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2bed981 elementor-widget elementor-widget-heading\" data-id=\"2bed981\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Directeur g\u00e9n\u00e9ral\n<br \/>Conseil canadien des semi-conducteurs <\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb12c06 elementor-widget elementor-widget-text-editor\" data-id=\"fb12c06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Paul Slaby est un professionnel chevronn\u00e9 de l&rsquo;industrie des semi-conducteurs et directeur g\u00e9n\u00e9ral du Conseil canadien des semi-conducteurs (CSC). Sa carri\u00e8re dans le domaine des semi-conducteurs a d\u00e9but\u00e9 par un poste de recherche postdoctorale \u00e0 l\u2019Universit\u00e9 Carleton, suivi d\u2019une d\u00e9cennie en tant que gestionnaire de R&#038;D en semi-conducteurs chez Nortel Semiconductor et BNR. Par la suite, il a fond\u00e9 et\/ou dirig\u00e9 plusieurs entreprises technologiques prosp\u00e8res, notamment ATMOS Corp, MicroSemiX, VoIPshield Systems, Kaben Wireless Silicon, Teslonix et d&rsquo;autres. R\u00e9cemment, il consacre son temps \u00e0 conseiller plusieurs jeunes entreprises technologiques \u00e9mergentes, ainsi que des acc\u00e9l\u00e9rateurs de startups tels que NewChip, Founder Institute et ventureLAB. Actuellement, Paul s\u2019est donn\u00e9 pour mission de propulser l\u2019industrie canadienne des semi-conducteurs sur la sc\u00e8ne mondiale. Il est titulaire d\u2019une ma\u00eetrise en physique appliqu\u00e9e et d\u2019un doctorat en micro\u00e9lectronique.      <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f6038ea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f6038ea\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-47584f1\" data-id=\"47584f1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c48bb8 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1c48bb8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cc48131 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cc48131\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9d9587d\" data-id=\"9d9587d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3703325 elementor-widget elementor-widget-template\" data-id=\"3703325\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"4684\" class=\"elementor elementor-4684 elementor-4679 elementor-4679\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6ec28fea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6ec28fea\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-756c11c6\" data-id=\"756c11c6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-483594d6 elementor-widget elementor-widget-heading\" data-id=\"483594d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">O\u00f9<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68b798f7 elementor-widget elementor-widget-text-editor\" data-id=\"68b798f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">H\u00f4tel Brookstreet <br\/>525, promenade Legget <br\/>Kanata, ON K2K 3G4<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75f44c23 elementor-widget elementor-widget-text-editor\" data-id=\"75f44c23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/reservations.travelclick.com\/13193?groupID=5121041\"><span data-olk-copy-source=\"MessageBody\">Restez sur place \u2013 R\u00e9servez votre chambre d\u00e8s maintenant<\/span><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1c8d7a0f\" data-id=\"1c8d7a0f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71fda329 elementor-widget elementor-widget-heading\" data-id=\"71fda329\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Billets<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f291db elementor-widget elementor-widget-text-editor\" data-id=\"4f291db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Bient\u00f4t disponible<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf868c4 elementor-widget elementor-widget-text-editor\" data-id=\"bf868c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/go.cmc.ca\/l\/947082\/2026-05-04\/3ns7d5\">Inscrivez-vous<\/a> pour \u00e9conomiser 10 % et \u00eatre inform\u00e9 de l&rsquo;ouverture des inscriptions.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30307f39 elementor-align-center elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"30307f39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.eventbrite.ca\/e\/accelerated-canadas-semiconductor-symposium-2025-tickets-1559404223009\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Inscrivez-vous d\u00e8s aujourd\u2019hui\u202f!<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f3867ec elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-icon-box\" data-id=\"5f3867ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tLe lien s\u2019ouvre dans une nouvelle fen\u00eatre\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a655a5e\" data-id=\"a655a5e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e693a89 elementor-widget elementor-widget-heading\" data-id=\"e693a89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Dates<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7300ea9 elementor-widget elementor-widget-text-editor\" data-id=\"7300ea9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>Visites de sites et r\u00e9ception :<\/strong> <br\/>Lundi 19 octobre 2026<br\/><strong>Symposium : <\/strong>20\u201321 octobre 2026<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-267dde54 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"267dde54\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-797db9dc\" data-id=\"797db9dc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52b16d9 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"52b16d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5118be0 elementor-widget elementor-widget-heading\" data-id=\"5118be0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Merci \u00e0 nos g\u00e9n\u00e9reux sponsors<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32c23f1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"32c23f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ddf45c6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ddf45c6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-af3ac70\" data-id=\"af3ac70\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc68d2b elementor-widget elementor-widget-image\" data-id=\"cc68d2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.investottawa.ca\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/elementor\/thumbs\/invest_ottawa_logo-rmqb4beoupndxmaiwaus31ck8za3ufv1ds2llajvui.png\" title=\"invest_ottawa_logo\" alt=\"invest_ottawa_logo\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-f3476c9\" data-id=\"f3476c9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-26bbd03\" data-id=\"26bbd03\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6689b393 elementor-widget elementor-widget-image\" data-id=\"6689b393\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.kanatanorthba.com\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"783\" height=\"250\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/knba_logo.webp\" class=\"attachment-full size-full wp-image-4683\" alt=\"\" srcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/knba_logo.webp 783w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/knba_logo-300x96.webp 300w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/knba_logo-768x245.webp 768w\" sizes=\"(max-width: 783px) 100vw, 783px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-0101c69\" data-id=\"0101c69\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-1d1fdfb\" data-id=\"1d1fdfb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-87b2cc4 elementor-widget elementor-widget-image\" data-id=\"87b2cc4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.phasix.co.uk\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"696\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/phasix_esd_logo-1024x696.webp\" class=\"attachment-large size-large wp-image-4797\" alt=\"\" srcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/phasix_esd_logo-1024x696.webp 1024w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/phasix_esd_logo-300x204.webp 300w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/phasix_esd_logo-768x522.webp 768w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/phasix_esd_logo-1536x1043.webp 1536w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/phasix_esd_logo-2048x1391.webp 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1a35a09 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1a35a09\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-435cead\" data-id=\"435cead\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fc30154 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"fc30154\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5297be elementor-widget elementor-widget-heading\" data-id=\"c5297be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Sponsor principal de TEXPO<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aff6fc9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aff6fc9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-de266a4\" data-id=\"de266a4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-d175585\" data-id=\"d175585\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-7e2ead1\" data-id=\"7e2ead1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cbc3519 elementor-widget elementor-widget-image\" data-id=\"cbc3519\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.comsol.com\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"55\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/Comsol_logo.jpg\" class=\"attachment-large size-large wp-image-3288\" alt=\"\" srcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/Comsol_logo.jpg 600w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/Comsol_logo-300x28.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-e3eccaa\" data-id=\"e3eccaa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-87f932b\" data-id=\"87f932b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c12afaa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c12afaa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-49dc391\" data-id=\"49dc391\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cac5768 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"cac5768\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b051ee4 elementor-widget elementor-widget-heading\" data-id=\"b051ee4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">sponsors du prix TEXPO<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c9372d5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c9372d5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-4d71f12\" data-id=\"4d71f12\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-49b1913\" data-id=\"49b1913\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-7fc4b36\" data-id=\"7fc4b36\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-006a722 elementor-widget elementor-widget-image\" data-id=\"006a722\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.c2mi.ca\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"635\" height=\"243\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/06\/c2mi_icon.jpg\" class=\"attachment-large size-large wp-image-2575\" alt=\"\" srcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/06\/c2mi_icon.jpg 635w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/06\/c2mi_icon-300x115.jpg 300w\" sizes=\"(max-width: 635px) 100vw, 635px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-d6a9321\" data-id=\"d6a9321\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-97d61b5\" data-id=\"97d61b5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6f95a6cc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6f95a6cc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ead81b1\" data-id=\"ead81b1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-291af0e7 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"291af0e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0a23bfa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0a23bfa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-269a88e\" data-id=\"269a88e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e10c458 elementor-widget elementor-widget-heading\" data-id=\"e10c458\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Commanditaire du CSS 2026<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-edaaf52 elementor-widget elementor-widget-text-editor\" data-id=\"edaaf52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\"><span data-olk-copy-source=\"MessageBody\">Contactez-nous pour en savoir plus sur les possibilit\u00e9s de parrainage et d&rsquo;exposition.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2814954\" data-id=\"2814954\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab3c30f elementor-widget elementor-widget-html\" data-id=\"ab3c30f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<iframe title=\"Contact\" width=\"300\" height=\"570\" src=\"https:\/\/go.cmc.ca\/l\/947082\/2026-03-16\/3npjq2\">\n<\/iframe>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c1d1442 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c1d1442\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5a99ac0\" data-id=\"5a99ac0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0fa48f0 elementor-widget elementor-widget-spacer\" data-id=\"0fa48f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Symposium canadien sur les semi-conducteurs 2026 Conf\u00e9renciers Manon Duclos PDG Technum Qu\u00e9bec Manon Duclos \u0153uvre dans les domaines de l\u2019innovation, de la qualit\u00e9 et de l\u2019excellence organisationnelle depuis plus de [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"parent":4320,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-4476","page","type-page","status-publish","hentry"],"acf":[],"featured_image_src":null,"featured_image_src_square":null,"_links":{"self":[{"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/pages\/4476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/comments?post=4476"}],"version-history":[{"count":0,"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/pages\/4476\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/pages\/4320"}],"wp:attachment":[{"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/media?parent=4476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":4478,"date":"2026-03-03T14:25:45","date_gmt":"2026-03-03T19:25:45","guid":{"rendered":"https:\/\/fabricinnovation.ca\/css2026\/agenda\/"},"modified":"2026-04-29T12:34:28","modified_gmt":"2026-04-29T17:34:28","slug":"agenda","status":"publish","type":"page","link":"https:\/\/fabricinnovation.ca\/fr\/css2026\/agenda\/","title":{"rendered":"Programme"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4478\" class=\"elementor elementor-4478 elementor-4334\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d2ed9b2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d2ed9b2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8a88636\" data-id=\"8a88636\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-771e6e5 elementor-widget elementor-widget-spacer\" data-id=\"771e6e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6261673\" data-id=\"6261673\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2866307 elementor-widget elementor-widget-spacer\" data-id=\"2866307\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5767c03\" data-id=\"5767c03\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-caafc36 elementor-widget__width-initial elementor-widget elementor-widget-spacer\" data-id=\"caafc36\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-85008e2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"85008e2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cdf47f6\" data-id=\"cdf47f6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d1759b3 elementor-widget elementor-widget-heading\" data-id=\"d1759b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Symposium canadien sur les semi-conducteurs 2026<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b8ed42 elementor-widget elementor-widget-heading\" data-id=\"0b8ed42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Programme<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-455bcbe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"455bcbe\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e28ec23\" data-id=\"e28ec23\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9e957e7 elementor-widget elementor-widget-template\" data-id=\"9e957e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"4322\" class=\"elementor elementor-4322\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f97ecfc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f97ecfc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1aa2fb9\" data-id=\"1aa2fb9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef95ed6 elementor-nav-menu__align-center elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"ef95ed6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-underline e--animation-fade\">\n\t\t\t\t<ul id=\"menu-1-ef95ed6\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4323\"><a href=\"https:\/\/fabricinnovation.ca\/css2026\/\" class=\"elementor-item menu-link\">CSS 2026<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4336\"><a href=\"https:\/\/fabricinnovation.ca\/css2026\/agenda\/\" class=\"elementor-item menu-link\">Programme<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4673\"><a href=\"https:\/\/fabricinnovation.ca\/css2026\/speakers\/\" class=\"elementor-item menu-link\">Conf\u00e9renciers<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4324\"><a href=\"https:\/\/fabricinnovation.ca\/texpo-2026\/\" class=\"elementor-item menu-link\">TEXPO 2026<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Permuter le menu\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-ef95ed6\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4323\"><a href=\"https:\/\/fabricinnovation.ca\/css2026\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">CSS 2026<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4336\"><a href=\"https:\/\/fabricinnovation.ca\/css2026\/agenda\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Programme<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4673\"><a href=\"https:\/\/fabricinnovation.ca\/css2026\/speakers\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Conf\u00e9renciers<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4324\"><a href=\"https:\/\/fabricinnovation.ca\/texpo-2026\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">TEXPO 2026<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba91426 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ba91426\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f714a43 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f714a43\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e1a937a\" data-id=\"e1a937a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14a9742 elementor-widget elementor-widget-heading\" data-id=\"14a9742\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Lundi 19 octobre<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f40a294 elementor-widget elementor-widget-heading\" data-id=\"f40a294\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">R\u00e9ception d'ouverture<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-77cfcb6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"77cfcb6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-56bfb72\" data-id=\"56bfb72\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3481202 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3481202\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-23468ac elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"23468ac\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7fa7547\" data-id=\"7fa7547\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d456e6 elementor-widget elementor-widget-heading\" data-id=\"0d456e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">6:30<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f8a5b36\" data-id=\"f8a5b36\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17a9ffc elementor-widget elementor-widget-heading\" data-id=\"17a9ffc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">R\u00e9ception d'ouverture<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d52066 elementor-widget elementor-widget-text-editor\" data-id=\"0d52066\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Joignez-vous \u00e0 nous pour un lancement convivial avant deux journ\u00e9es intenses lors de notre r\u00e9ception d\u2019ouverture. Connectez-vous avec les autres participants, conf\u00e9renciers invit\u00e9s, pan\u00e9listes et partenaires dans un cadre d\u00e9tendu. Ce sera une excellente occasion de r\u00e9seauter, d\u2019\u00e9changer des id\u00e9es et de cr\u00e9er de nouvelles relations.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8ed906 elementor-widget__width-initial elementor-widget elementor-widget-spacer\" data-id=\"d8ed906\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a0a2844 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a0a2844\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c81b9ca\" data-id=\"c81b9ca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0cfcecc elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"0cfcecc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-46593eb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"46593eb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8f83f08\" data-id=\"8f83f08\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8bb6a68 elementor-widget elementor-widget-heading\" data-id=\"8bb6a68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Premier jour : mardi 20 octobre<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7dd4fcf elementor-widget elementor-widget-heading\" data-id=\"7dd4fcf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Sovereignty<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f4265f elementor-widget elementor-widget-text-editor\" data-id=\"1f4265f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le symposium s\u2019ouvre par une s\u00e9rie de discussions visant \u00e0 explorer ce \u00e0 quoi pourrait ressembler un Canada plus fort, plus autonome \u2014 plus r\u00e9silient. Nous examinerons les occasions existantes et \u00e9mergentes, l\u2019importance d\u2019une strat\u00e9gie nationale coh\u00e9rente, ainsi que la mani\u00e8re dont d\u2019autres pays ont transform\u00e9 leur \u00e9conomie gr\u00e2ce \u00e0 des investissements strat\u00e9giques dans ce secteur. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f514e84 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f514e84\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-197b263\" data-id=\"197b263\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e92c849 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e92c849\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d4a95fb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d4a95fb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d3cb72a\" data-id=\"d3cb72a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b8e6e67 elementor-widget elementor-widget-heading\" data-id=\"b8e6e67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">9:00<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-479d7d4\" data-id=\"479d7d4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ec6df7 elementor-widget elementor-widget-heading\" data-id=\"4ec6df7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Bienvenue<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca9003c elementor-widget__width-initial elementor-widget elementor-widget-spacer\" data-id=\"ca9003c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6f862b1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6f862b1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-06b22f5\" data-id=\"06b22f5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-08b1975 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"08b1975\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d74a206 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d74a206\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e241c9d\" data-id=\"e241c9d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dcbd07a elementor-widget elementor-widget-heading\" data-id=\"dcbd07a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">9:30<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5e0c54a\" data-id=\"5e0c54a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab5a241 elementor-widget elementor-widget-heading\" data-id=\"ab5a241\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Conf\u00e9rence d\u2019ouverture : \u00c0 quoi ressemble un Canada plus r\u00e9silient \n<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-129f086 elementor-widget elementor-widget-text-editor\" data-id=\"129f086\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La construction d\u2019une \u00e9conomie r\u00e9siliente et prosp\u00e8re repose sur des industries \u00e0 forte productivit\u00e9, capables de fonctionner efficacement et de concurrencer \u00e0 l\u2019\u00e9chelle mondiale.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d83a00 elementor-widget__width-initial elementor-widget elementor-widget-spacer\" data-id=\"6d83a00\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1ffa582 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1ffa582\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0941396\" data-id=\"0941396\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a5b9108 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a5b9108\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4d3ab43 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4d3ab43\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8aa9d60\" data-id=\"8aa9d60\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fb23f46 elementor-widget elementor-widget-heading\" data-id=\"fb23f46\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">10:30<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1982f49\" data-id=\"1982f49\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c6a430 elementor-widget elementor-widget-heading\" data-id=\"9c6a430\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Pause matinale<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d39cfd elementor-widget__width-initial elementor-widget elementor-widget-spacer\" data-id=\"5d39cfd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c7542fb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c7542fb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b9f4418\" data-id=\"b9f4418\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d0d50fb elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d0d50fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-04c650f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"04c650f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fe403db\" data-id=\"fe403db\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-66fda71 elementor-widget elementor-widget-heading\" data-id=\"66fda71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">11:00<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-dbea2b7\" data-id=\"dbea2b7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bced74f elementor-widget elementor-widget-heading\" data-id=\"bced74f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Les semi\u2011conducteurs : une infrastructure critique au c\u0153ur de l\u2019industrie<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b14703a elementor-widget elementor-widget-text-editor\" data-id=\"b14703a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La technologie des semi\u2011conducteurs est omnipr\u00e9sente dans l\u2019ensemble des secteurs sur lesquels ce pays s\u2019appuie pour sa sant\u00e9 \u00e9conomique \u2014 et pour ce qu\u2019ils rendent possible. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-890bd3b elementor-widget__width-initial elementor-widget elementor-widget-spacer\" data-id=\"890bd3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e535c63 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e535c63\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-48b8a2d\" data-id=\"48b8a2d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5294ca2 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5294ca2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-603f977 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"603f977\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9d4908e\" data-id=\"9d4908e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b6fca2f elementor-widget elementor-widget-heading\" data-id=\"b6fca2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">11:00<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4a8b149\" data-id=\"4a8b149\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c51c546 elementor-widget elementor-widget-heading\" data-id=\"c51c546\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Conf\u00e9rence\u2011d\u00e9jeuner \u2014 Un levier pour la r\u00e9invention \u00e9conomique<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5918ce3 elementor-widget elementor-widget-text-editor\" data-id=\"5918ce3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La r\u00e9invention \u00e9conomique est non seulement possible, elle peut aussi catalyser la prosp\u00e9rit\u00e9. Un haut repr\u00e9sentant du Royaume des Pays\u2011Bas \u2014 une juridiction dot\u00e9e d\u2019un secteur des semi\u2011conducteurs solide \u2014 d\u00e9crira l\u2019importante dynamique \u00e9conomique g\u00e9n\u00e9r\u00e9e par un secteur des semi\u2011conducteurs vigoureux, ainsi que son impact \u00e9conomique et concurrentiel sur d\u2019autres industries nationales.  <\/p><p>En 2026, les Pays\u2011Bas sont un pays \u00e0 co\u00fbt de main\u2011d\u2019\u0153uvre \u00e9lev\u00e9 dot\u00e9 d\u2019un solide secteur de fabrication avanc\u00e9e. <br>Connue comme la \u00ab\u202fSilicon Valley\u202f\u00bb de l\u2019Europe, la r\u00e9gion Amsterdam\u2011Delta aux Pays\u2011Bas a vu la valeur de son \u00e9cosyst\u00e8me passer de 12\u202fG$ en 2015 \u00e0 plus de 86\u202fG$, avec un taux de croissance annuel moyen de 53\u202f%.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f69def elementor-widget__width-initial elementor-widget elementor-widget-spacer\" data-id=\"0f69def\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-21c7dd1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"21c7dd1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8a5a7df\" data-id=\"8a5a7df\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7bbc5be elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7bbc5be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-421f4bd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"421f4bd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1df8c08\" data-id=\"1df8c08\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fcffb83 elementor-widget elementor-widget-heading\" data-id=\"fcffb83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">1:15<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-856456c\" data-id=\"856456c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ea2a373 elementor-widget elementor-widget-heading\" data-id=\"ea2a373\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Cha\u00eenes d\u2019approvisionnement mondiales et opportunit\u00e9s communes intersectorielles<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65e991f elementor-widget elementor-widget-text-editor\" data-id=\"65e991f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Quelles sont les faiblesses critiques de la cha\u00eene d\u2019approvisionnement des semi\u2011conducteurs \u2014 et dans quels domaines disposons\u2011nous de l\u2019expertise et d\u2019une demande industrielle nationale significative \u2014 pour nous positionner strat\u00e9giquement\u202f? Le Canada ne peut pas tout faire, mais existe\u2011t\u2011il des proximit\u00e9s entre diff\u00e9rents secteurs d\u2019utilisation finale qui r\u00e9v\u00e8lent des besoins communs ou des domaines \u00e9vidents \u00e0 explorer\u202f? <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07d3c71 elementor-widget__width-initial elementor-widget elementor-widget-spacer\" data-id=\"07d3c71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-03b47eb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"03b47eb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-83a9c9d\" data-id=\"83a9c9d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c3db898 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c3db898\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-51e7104 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"51e7104\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-85bc983\" data-id=\"85bc983\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-04d6884 elementor-widget__width-initial elementor-widget elementor-widget-spacer\" data-id=\"04d6884\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5d52178 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5d52178\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-306e8ed\" data-id=\"306e8ed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c2f787 elementor-widget elementor-widget-heading\" data-id=\"9c2f787\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">2:15<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8f12d59\" data-id=\"8f12d59\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0eaf43c elementor-widget elementor-widget-heading\" data-id=\"0eaf43c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Canada\u2019s Semiconductor Council<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-79c130e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"79c130e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"make-column-clickable-elementor elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-f2e691d\" style=\"cursor: pointer;\" data-column-clickable=\"https:\/\/fabricinnovation.ca\/speakers\/#paul\" data-column-clickable-blank=\"_self\" data-id=\"f2e691d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b30066 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"1b30066\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/elementor\/thumbs\/paul_bw-raxjuxl7ciilyvlwzhwjzobnnz5zsxkaitmib2mfg0.png\" title=\"paul_bw\" alt=\"paul_bw\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3621281 elementor-widget elementor-widget-spacer\" data-id=\"3621281\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7d06b5 elementor-widget elementor-widget-heading\" data-id=\"c7d06b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Paul Slaby<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cbaa7e6 elementor-widget elementor-widget-text-editor\" data-id=\"cbaa7e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Directeur g\u00e9n\u00e9ral<br>Conseil canadien des semi-conducteurs<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-eceb45a\" data-id=\"eceb45a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-5234134\" data-id=\"5234134\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-85d8dc3\" data-id=\"85d8dc3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-16c81a5 elementor-widget__width-initial elementor-widget elementor-widget-spacer\" data-id=\"16c81a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-88879bb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"88879bb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cddb691\" data-id=\"cddb691\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-daaff62 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"daaff62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dbde019 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dbde019\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b3e1db6\" data-id=\"b3e1db6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-19ab5c7 elementor-widget elementor-widget-heading\" data-id=\"19ab5c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">2:35<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8150144\" data-id=\"8150144\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f544c6e elementor-widget elementor-widget-heading\" data-id=\"f544c6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Pause de l\u2019apr\u00e8s-midi<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21bfe8d elementor-widget__width-initial elementor-widget elementor-widget-spacer\" data-id=\"21bfe8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1ae33e5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1ae33e5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-96c7461\" data-id=\"96c7461\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ea9517 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3ea9517\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7069f7c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7069f7c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b361efd\" data-id=\"b361efd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a2e254b elementor-widget elementor-widget-heading\" data-id=\"a2e254b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">3:00<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5d7a96a\" data-id=\"5d7a96a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cbea93d elementor-widget elementor-widget-heading\" data-id=\"cbea93d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">D\u00e9velopper les comp\u00e9tences \u00e0 grande \u00e9chelle<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2875376 elementor-widget__width-initial elementor-widget elementor-widget-spacer\" data-id=\"2875376\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bde232f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bde232f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-94604a2\" data-id=\"94604a2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a8d65da elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a8d65da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5893f08 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5893f08\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-dac3908\" data-id=\"dac3908\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29591e4 elementor-widget elementor-widget-heading\" data-id=\"29591e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">4:00<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7026b23\" data-id=\"7026b23\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dbf6e08 elementor-widget elementor-widget-heading\" data-id=\"dbf6e08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">L\u2019\u00e9mergence du quantique<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f4e705 elementor-widget__width-initial elementor-widget elementor-widget-spacer\" data-id=\"1f4e705\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-00caba9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"00caba9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-68f998b\" data-id=\"68f998b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e0f744 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4e0f744\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2abbfa4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2abbfa4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6ccc508\" data-id=\"6ccc508\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f4c3411 elementor-widget elementor-widget-menu-anchor\" data-id=\"f4c3411\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"two\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a3ac8b elementor-widget elementor-widget-heading\" data-id=\"1a3ac8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Deuxi\u00e8me jour : mercredi 21 octobre<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ee16a5 elementor-widget elementor-widget-heading\" data-id=\"5ee16a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Prosp\u00e9rit\u00e9<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5db1ba5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5db1ba5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f1a849d\" data-id=\"f1a849d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc47034 elementor-widget elementor-widget-text-editor\" data-id=\"cc47034\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La deuxi\u00e8me journ\u00e9e met l\u2019accent sur l\u2019intersection entre le secteur des semi\u2011conducteurs et les principaux moteurs de l\u2019\u00e9conomie canadienne. Avec la participation de leaders des secteurs de l\u2019a\u00e9rospatiale et de la d\u00e9fense, de l\u2019automobile, de l\u2019exploitation mini\u00e8re, des technologies m\u00e9dicales, de la fabrication avanc\u00e9e et des industries oc\u00e9aniques, nous examinerons les enjeux d\u2019innovation auxquels ils sont confront\u00e9s et les domaines o\u00f9 la technologie des semi\u2011conducteurs peut jouer un r\u00f4le d\u00e9terminant. Le symposium explore comment l\u2019expertise canadienne en semi\u2011conducteurs peut renforcer la capacit\u00e9 de ces industries nationales essentielles \u00e0 innover et \u00e0 demeurer comp\u00e9titives.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9629fb elementor-widget elementor-widget-spacer\" data-id=\"d9629fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-300361b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"300361b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e051790\" data-id=\"e051790\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-127e23b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"127e23b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5d3a1fc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5d3a1fc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-62a0382\" data-id=\"62a0382\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-85f7d50 elementor-widget elementor-widget-heading\" data-id=\"85f7d50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">9:00<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3c92f9b\" data-id=\"3c92f9b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78b0798 elementor-widget elementor-widget-heading\" data-id=\"78b0798\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Bienvenue<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c522d9 elementor-widget__width-initial elementor-widget elementor-widget-spacer\" data-id=\"8c522d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5828eb3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5828eb3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e656fed\" data-id=\"e656fed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f425dee elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f425dee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a0bbf61 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a0bbf61\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e1d53f1\" data-id=\"e1d53f1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e346de8 elementor-widget elementor-widget-heading\" data-id=\"e346de8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">9:30<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2c64573\" data-id=\"2c64573\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77685e2 elementor-widget elementor-widget-heading\" data-id=\"77685e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Conf\u00e9rence d\u2019ouverture<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae727cb elementor-widget__width-initial elementor-widget elementor-widget-spacer\" data-id=\"ae727cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a57d00 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5a57d00\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-77a3cd2\" data-id=\"77a3cd2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9b628d0 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9b628d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-eaa97c4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eaa97c4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-cb7ca0b\" data-id=\"cb7ca0b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-671e070 elementor-widget elementor-widget-heading\" data-id=\"671e070\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">10:30<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b53a79a\" data-id=\"b53a79a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a4f1fb5 elementor-widget elementor-widget-heading\" data-id=\"a4f1fb5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Pause matinale<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d6d51a elementor-widget__width-initial elementor-widget elementor-widget-spacer\" data-id=\"9d6d51a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f28de53 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f28de53\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e8b691a\" data-id=\"e8b691a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bcaeae8 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"bcaeae8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7e5114a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7e5114a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6677555\" data-id=\"6677555\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f51078 elementor-widget elementor-widget-heading\" data-id=\"2f51078\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">11:00<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a8d8493\" data-id=\"a8d8493\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b45f856 elementor-widget elementor-widget-heading\" data-id=\"b45f856\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Restez \u00e0 l\u2019\u00e9coute<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29edd83 elementor-widget__width-initial elementor-widget elementor-widget-spacer\" data-id=\"29edd83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c2438cf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c2438cf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-417dde6\" data-id=\"417dde6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ce633b5 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ce633b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-73d50ef elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"73d50ef\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9b4b478\" data-id=\"9b4b478\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e8f0318 elementor-widget elementor-widget-heading\" data-id=\"e8f0318\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">12:00<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d569650\" data-id=\"d569650\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d8bd6a elementor-widget elementor-widget-heading\" data-id=\"2d8bd6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">D\u00e9jeuner : TEXPO et remise des prix Colton<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-333e15d elementor-widget__width-initial elementor-widget elementor-widget-spacer\" data-id=\"333e15d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0add4e7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0add4e7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e9e8de7\" data-id=\"e9e8de7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ebb4e81 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ebb4e81\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-29d4efb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"29d4efb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c61ad84\" data-id=\"c61ad84\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-90c859d elementor-widget elementor-widget-heading\" data-id=\"90c859d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">1:15<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-04227b8\" data-id=\"04227b8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5aacd03 elementor-widget elementor-widget-heading\" data-id=\"5aacd03\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Restez \u00e0 l\u2019\u00e9coute<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c28264 elementor-widget__width-initial elementor-widget elementor-widget-spacer\" data-id=\"7c28264\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-75f54ac elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"75f54ac\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-10f71e3\" data-id=\"10f71e3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65373ba elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"65373ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-622c804 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"622c804\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8408c84\" data-id=\"8408c84\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e15dd48 elementor-widget elementor-widget-heading\" data-id=\"e15dd48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">2:15<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a859066\" data-id=\"a859066\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ecf7385 elementor-widget elementor-widget-heading\" data-id=\"ecf7385\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Restez \u00e0 l\u2019\u00e9coute<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d106573 elementor-widget__width-initial elementor-widget elementor-widget-spacer\" data-id=\"d106573\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ef72e06 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ef72e06\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f0c7542\" data-id=\"f0c7542\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9ee370c elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9ee370c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-24c058b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"24c058b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9f6e045\" data-id=\"9f6e045\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0fd1f0d elementor-widget elementor-widget-heading\" data-id=\"0fd1f0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">3:15<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-969b6bb\" data-id=\"969b6bb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b17ea8 elementor-widget elementor-widget-heading\" data-id=\"4b17ea8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Pause de l\u2019apr\u00e8s-midi<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b38515f elementor-widget__width-initial elementor-widget elementor-widget-spacer\" data-id=\"b38515f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ba858df elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ba858df\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dbbc13c\" data-id=\"dbbc13c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a451fe elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2a451fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-85a51d1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"85a51d1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4e11ac4\" data-id=\"4e11ac4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c93a09f elementor-widget elementor-widget-heading\" data-id=\"c93a09f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">3:30<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3853eb8\" data-id=\"3853eb8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e6e5f66 elementor-widget elementor-widget-heading\" data-id=\"e6e5f66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Que devrions\u2011nous construire\u202f?<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-767c439 elementor-widget__width-initial elementor-widget elementor-widget-spacer\" data-id=\"767c439\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1cfaaa8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1cfaaa8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4237b7a\" data-id=\"4237b7a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8c914b2 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8c914b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3d75393 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3d75393\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2845ef7\" data-id=\"2845ef7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-de89127 elementor-widget elementor-widget-heading\" data-id=\"de89127\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">4:30<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1cd9b93\" data-id=\"1cd9b93\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a5991f3 elementor-widget elementor-widget-heading\" data-id=\"a5991f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">O\u00f9 allons\u2011nous \u00e0 partir d\u2019ici\u202f?<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27fd29b elementor-widget__width-initial elementor-widget elementor-widget-spacer\" data-id=\"27fd29b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-32959c0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"32959c0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6fcddbc\" data-id=\"6fcddbc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b5dde6c elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b5dde6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cc48131 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cc48131\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9d9587d\" data-id=\"9d9587d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3703325 elementor-widget elementor-widget-template\" data-id=\"3703325\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"4684\" class=\"elementor elementor-4684 elementor-4679 elementor-4679\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6ec28fea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6ec28fea\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-756c11c6\" data-id=\"756c11c6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-483594d6 elementor-widget elementor-widget-heading\" data-id=\"483594d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">O\u00f9<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68b798f7 elementor-widget elementor-widget-text-editor\" data-id=\"68b798f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">H\u00f4tel Brookstreet <br\/>525, promenade Legget <br\/>Kanata, ON K2K 3G4<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75f44c23 elementor-widget elementor-widget-text-editor\" data-id=\"75f44c23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/reservations.travelclick.com\/13193?groupID=5121041\"><span data-olk-copy-source=\"MessageBody\">Restez sur place \u2013 R\u00e9servez votre chambre d\u00e8s maintenant<\/span><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1c8d7a0f\" data-id=\"1c8d7a0f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71fda329 elementor-widget elementor-widget-heading\" data-id=\"71fda329\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Billets<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f291db elementor-widget elementor-widget-text-editor\" data-id=\"4f291db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Bient\u00f4t disponible<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf868c4 elementor-widget elementor-widget-text-editor\" data-id=\"bf868c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/go.cmc.ca\/l\/947082\/2026-05-04\/3ns7d5\">Inscrivez-vous<\/a> pour \u00e9conomiser 10 % et \u00eatre inform\u00e9 de l&rsquo;ouverture des inscriptions.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30307f39 elementor-align-center elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"30307f39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.eventbrite.ca\/e\/accelerated-canadas-semiconductor-symposium-2025-tickets-1559404223009\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Inscrivez-vous d\u00e8s aujourd\u2019hui\u202f!<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f3867ec elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-icon-box\" data-id=\"5f3867ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tLe lien s\u2019ouvre dans une nouvelle fen\u00eatre\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a655a5e\" data-id=\"a655a5e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e693a89 elementor-widget elementor-widget-heading\" data-id=\"e693a89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Dates<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7300ea9 elementor-widget elementor-widget-text-editor\" data-id=\"7300ea9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>Visites de sites et r\u00e9ception :<\/strong> <br\/>Lundi 19 octobre 2026<br\/><strong>Symposium : <\/strong>20\u201321 octobre 2026<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-267dde54 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"267dde54\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-797db9dc\" data-id=\"797db9dc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52b16d9 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"52b16d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5118be0 elementor-widget elementor-widget-heading\" data-id=\"5118be0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Merci \u00e0 nos g\u00e9n\u00e9reux sponsors<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32c23f1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"32c23f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ddf45c6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ddf45c6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-af3ac70\" data-id=\"af3ac70\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc68d2b elementor-widget elementor-widget-image\" data-id=\"cc68d2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.investottawa.ca\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/elementor\/thumbs\/invest_ottawa_logo-rmqb4beoupndxmaiwaus31ck8za3ufv1ds2llajvui.png\" title=\"invest_ottawa_logo\" alt=\"invest_ottawa_logo\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-f3476c9\" data-id=\"f3476c9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-26bbd03\" data-id=\"26bbd03\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6689b393 elementor-widget elementor-widget-image\" data-id=\"6689b393\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.kanatanorthba.com\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"783\" height=\"250\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/knba_logo.webp\" class=\"attachment-full size-full wp-image-4683\" alt=\"\" srcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/knba_logo.webp 783w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/knba_logo-300x96.webp 300w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/knba_logo-768x245.webp 768w\" sizes=\"(max-width: 783px) 100vw, 783px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-0101c69\" data-id=\"0101c69\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-1d1fdfb\" data-id=\"1d1fdfb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-87b2cc4 elementor-widget elementor-widget-image\" data-id=\"87b2cc4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.phasix.co.uk\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"696\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/phasix_esd_logo-1024x696.webp\" class=\"attachment-large size-large wp-image-4797\" alt=\"\" srcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/phasix_esd_logo-1024x696.webp 1024w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/phasix_esd_logo-300x204.webp 300w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/phasix_esd_logo-768x522.webp 768w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/phasix_esd_logo-1536x1043.webp 1536w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/phasix_esd_logo-2048x1391.webp 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1a35a09 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1a35a09\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-435cead\" data-id=\"435cead\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fc30154 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"fc30154\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5297be elementor-widget elementor-widget-heading\" data-id=\"c5297be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Sponsor principal de TEXPO<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aff6fc9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aff6fc9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-de266a4\" data-id=\"de266a4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-d175585\" data-id=\"d175585\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-7e2ead1\" data-id=\"7e2ead1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cbc3519 elementor-widget elementor-widget-image\" data-id=\"cbc3519\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.comsol.com\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"55\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/Comsol_logo.jpg\" class=\"attachment-large size-large wp-image-3288\" alt=\"\" srcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/Comsol_logo.jpg 600w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/Comsol_logo-300x28.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-e3eccaa\" data-id=\"e3eccaa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-87f932b\" data-id=\"87f932b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c12afaa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c12afaa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-49dc391\" data-id=\"49dc391\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cac5768 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"cac5768\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b051ee4 elementor-widget elementor-widget-heading\" data-id=\"b051ee4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">sponsors du prix TEXPO<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c9372d5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c9372d5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-4d71f12\" data-id=\"4d71f12\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-49b1913\" data-id=\"49b1913\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-7fc4b36\" data-id=\"7fc4b36\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-006a722 elementor-widget elementor-widget-image\" data-id=\"006a722\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.c2mi.ca\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"635\" height=\"243\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/06\/c2mi_icon.jpg\" class=\"attachment-large size-large wp-image-2575\" alt=\"\" srcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/06\/c2mi_icon.jpg 635w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/06\/c2mi_icon-300x115.jpg 300w\" sizes=\"(max-width: 635px) 100vw, 635px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-d6a9321\" data-id=\"d6a9321\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-97d61b5\" data-id=\"97d61b5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6f95a6cc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6f95a6cc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ead81b1\" data-id=\"ead81b1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-291af0e7 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"291af0e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0a23bfa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0a23bfa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-269a88e\" data-id=\"269a88e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e10c458 elementor-widget elementor-widget-heading\" data-id=\"e10c458\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Commanditaire du CSS 2026<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-edaaf52 elementor-widget elementor-widget-text-editor\" data-id=\"edaaf52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\"><span data-olk-copy-source=\"MessageBody\">Contactez-nous pour en savoir plus sur les possibilit\u00e9s de parrainage et d&rsquo;exposition.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2814954\" data-id=\"2814954\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab3c30f elementor-widget elementor-widget-html\" data-id=\"ab3c30f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<iframe title=\"Contact\" width=\"300\" height=\"570\" src=\"https:\/\/go.cmc.ca\/l\/947082\/2026-03-16\/3npjq2\">\n<\/iframe>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c1d1442 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c1d1442\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5a99ac0\" data-id=\"5a99ac0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0fa48f0 elementor-widget elementor-widget-spacer\" data-id=\"0fa48f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Symposium canadien sur les semi-conducteurs 2026 Programme Lundi 19 octobre R\u00e9ception d&rsquo;ouverture 6:30 R\u00e9ception d&rsquo;ouverture Joignez-vous \u00e0 nous pour un lancement convivial avant deux journ\u00e9es intenses lors de notre r\u00e9ception [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"parent":4320,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-4478","page","type-page","status-publish","hentry"],"acf":[],"featured_image_src":null,"featured_image_src_square":null,"_links":{"self":[{"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/pages\/4478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/comments?post=4478"}],"version-history":[{"count":0,"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/pages\/4478\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/pages\/4320"}],"wp:attachment":[{"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/media?parent=4478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":4320,"date":"2026-02-11T09:21:56","date_gmt":"2026-02-11T14:21:56","guid":{"rendered":"https:\/\/fabricinnovation.ca\/css2026\/"},"modified":"2026-05-12T08:55:39","modified_gmt":"2026-05-12T13:55:39","slug":"css2026","status":"publish","type":"page","link":"https:\/\/fabricinnovation.ca\/fr\/css2026\/","title":{"rendered":"CSS 2026"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4320\" class=\"elementor elementor-4320 elementor-4239\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-35293ff elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"35293ff\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-08789d0\" data-id=\"08789d0\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cfa96fe elementor-widget elementor-widget-spacer\" data-id=\"cfa96fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-215721c\" data-id=\"215721c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d00a9c elementor-widget elementor-widget-spacer\" data-id=\"0d00a9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-dc4663e\" data-id=\"dc4663e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6842ef7 elementor-widget__width-initial elementor-widget elementor-widget-spacer\" data-id=\"6842ef7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c9e9132 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c9e9132\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-eb08086\" data-id=\"eb08086\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-277f865 elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"277f865\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"256\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/02\/FABrIC_CMC_logo_white_FR-1024x256.png\" class=\"attachment-large size-large wp-image-4255\" alt=\"\" srcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/02\/FABrIC_CMC_logo_white_FR-1024x256.png 1024w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/02\/FABrIC_CMC_logo_white_FR-300x75.png 300w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/02\/FABrIC_CMC_logo_white_FR-768x192.png 768w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/02\/FABrIC_CMC_logo_white_FR-1536x384.png 1536w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/02\/FABrIC_CMC_logo_white_FR-2048x512.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-853cd94 elementor-widget elementor-widget-heading\" data-id=\"853cd94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\"><b>O\u00f9 la souverainet\u00e9 rencontre la prosp\u00e9rit\u00e9<\/b><\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f644d3 elementor-widget elementor-widget-heading\" data-id=\"8f644d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Symposium canadien sur les semi-conducteurs 2026<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b4965a elementor-widget elementor-widget-spacer\" data-id=\"3b4965a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eebdbcb elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"eebdbcb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">R\u00c9CEPTION : 19 OCTOBRE\n<b><br \/>SYMPOSIUM : 20\u201321 OCTOBRE<\/b>\n<br \/>OTTAWA, ONTARIO<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6bc69db elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"6bc69db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"104\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2024\/06\/funded-by-Canada-en-fr-1024x104.webp\" class=\"attachment-large size-large wp-image-210\" alt=\"\" srcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2024\/06\/funded-by-Canada-en-fr-1024x104.webp 1024w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2024\/06\/funded-by-Canada-en-fr-300x31.webp 300w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2024\/06\/funded-by-Canada-en-fr-768x78.webp 768w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2024\/06\/funded-by-Canada-en-fr-600x61.webp 600w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2024\/06\/funded-by-Canada-en-fr.webp 1470w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f19a492 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f19a492\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1fe3658\" data-id=\"1fe3658\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c286a5 elementor-widget elementor-widget-template\" data-id=\"7c286a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"4322\" class=\"elementor elementor-4322\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f97ecfc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f97ecfc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1aa2fb9\" data-id=\"1aa2fb9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef95ed6 elementor-nav-menu__align-center elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"ef95ed6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-underline e--animation-fade\">\n\t\t\t\t<ul id=\"menu-1-ef95ed6\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4323\"><a href=\"https:\/\/fabricinnovation.ca\/css2026\/\" class=\"elementor-item menu-link\">CSS 2026<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4336\"><a href=\"https:\/\/fabricinnovation.ca\/css2026\/agenda\/\" class=\"elementor-item menu-link\">Programme<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4673\"><a href=\"https:\/\/fabricinnovation.ca\/css2026\/speakers\/\" class=\"elementor-item menu-link\">Conf\u00e9renciers<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4324\"><a href=\"https:\/\/fabricinnovation.ca\/texpo-2026\/\" class=\"elementor-item menu-link\">TEXPO 2026<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Permuter le menu\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-ef95ed6\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4323\"><a href=\"https:\/\/fabricinnovation.ca\/css2026\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">CSS 2026<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4336\"><a href=\"https:\/\/fabricinnovation.ca\/css2026\/agenda\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Programme<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4673\"><a href=\"https:\/\/fabricinnovation.ca\/css2026\/speakers\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Conf\u00e9renciers<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4324\"><a href=\"https:\/\/fabricinnovation.ca\/texpo-2026\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">TEXPO 2026<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba91426 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ba91426\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e773363 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e773363\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-213dcce\" data-id=\"213dcce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1bacc4f elementor-widget elementor-widget-spacer\" data-id=\"1bacc4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f8b9b5 elementor-widget elementor-widget-text-editor\" data-id=\"6f8b9b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le XX\u1d49 si\u00e8cle a vu le d\u00e9veloppement, l\u2019\u00e9volution rapide et la diffusion de la technologie des semi\u2011conducteurs. Leur taille, leur poids, leur efficacit\u00e9 \u00e9nerg\u00e9tique et leur fiabilit\u00e9 r\u00e9pondaient aux besoins essentiels de l\u2019apr\u00e8s\u2011guerre. Ce fut un d\u00e9clencheur \u00e9conomique majeur.  <\/p><p>Les semi\u2011conducteurs se sont rapidement r\u00e9pandus, se transformant en applications industrielles puissantes qui ont soutenu une p\u00e9riode sans pr\u00e9c\u00e9dent de prosp\u00e9rit\u00e9 \u00e9conomique.<\/p><p>Au XXI\u1d49 si\u00e8cle, d\u00e9sormais int\u00e9gr\u00e9s dans tous les aspects de la soci\u00e9t\u00e9 et de l\u2019industrie, la contribution des semi\u2011conducteurs \u00e0 la souverainet\u00e9 nationale n\u2019a fait que s\u2019amplifier.<\/p><p>Alors que le Canada revitalise son \u00e9conomie gr\u00e2ce \u00e0 des investissements industriels strat\u00e9giques visant \u00e0 renforcer sa capacit\u00e9 de production nationale, le secteur des semi\u2011conducteurs a un r\u00f4le d\u00e9terminant \u00e0 jouer.<\/p><p>Pendant deux jours, nous explorerons l\u2019\u00e9tat de l\u2019industrie et les implications pour le march\u00e9, alors que le Canada red\u00e9finit ses relations \u00e9conomiques et s\u00e9curitaires. L\u2019objectif est clair\u202f: b\u00e2tir une nation plus forte et plus r\u00e9siliente. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3235286 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3235286\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-123f5ce\" data-id=\"123f5ce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-99a9d2d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"99a9d2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44d9e29 elementor-widget elementor-widget-template\" data-id=\"44d9e29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"4684\" class=\"elementor elementor-4684 elementor-4679 elementor-4679\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6ec28fea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6ec28fea\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-756c11c6\" data-id=\"756c11c6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-483594d6 elementor-widget elementor-widget-heading\" data-id=\"483594d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">O\u00f9<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68b798f7 elementor-widget elementor-widget-text-editor\" data-id=\"68b798f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">H\u00f4tel Brookstreet <br\/>525, promenade Legget <br\/>Kanata, ON K2K 3G4<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75f44c23 elementor-widget elementor-widget-text-editor\" data-id=\"75f44c23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/reservations.travelclick.com\/13193?groupID=5121041\"><span data-olk-copy-source=\"MessageBody\">Restez sur place \u2013 R\u00e9servez votre chambre d\u00e8s maintenant<\/span><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1c8d7a0f\" data-id=\"1c8d7a0f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71fda329 elementor-widget elementor-widget-heading\" data-id=\"71fda329\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Billets<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f291db elementor-widget elementor-widget-text-editor\" data-id=\"4f291db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Bient\u00f4t disponible<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf868c4 elementor-widget elementor-widget-text-editor\" data-id=\"bf868c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/go.cmc.ca\/l\/947082\/2026-05-04\/3ns7d5\">Inscrivez-vous<\/a> pour \u00e9conomiser 10 % et \u00eatre inform\u00e9 de l&rsquo;ouverture des inscriptions.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30307f39 elementor-align-center elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"30307f39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.eventbrite.ca\/e\/accelerated-canadas-semiconductor-symposium-2025-tickets-1559404223009\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Inscrivez-vous d\u00e8s aujourd\u2019hui\u202f!<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f3867ec elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-icon-box\" data-id=\"5f3867ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tLe lien s\u2019ouvre dans une nouvelle fen\u00eatre\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a655a5e\" data-id=\"a655a5e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e693a89 elementor-widget elementor-widget-heading\" data-id=\"e693a89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Dates<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7300ea9 elementor-widget elementor-widget-text-editor\" data-id=\"7300ea9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>Visites de sites et r\u00e9ception :<\/strong> <br\/>Lundi 19 octobre 2026<br\/><strong>Symposium : <\/strong>20\u201321 octobre 2026<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-267dde54 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"267dde54\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-797db9dc\" data-id=\"797db9dc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52b16d9 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"52b16d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5118be0 elementor-widget elementor-widget-heading\" data-id=\"5118be0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Merci \u00e0 nos g\u00e9n\u00e9reux sponsors<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32c23f1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"32c23f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ddf45c6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ddf45c6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-af3ac70\" data-id=\"af3ac70\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc68d2b elementor-widget elementor-widget-image\" data-id=\"cc68d2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.investottawa.ca\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/elementor\/thumbs\/invest_ottawa_logo-rmqb4beoupndxmaiwaus31ck8za3ufv1ds2llajvui.png\" title=\"invest_ottawa_logo\" alt=\"invest_ottawa_logo\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-f3476c9\" data-id=\"f3476c9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-26bbd03\" data-id=\"26bbd03\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6689b393 elementor-widget elementor-widget-image\" data-id=\"6689b393\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.kanatanorthba.com\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"783\" height=\"250\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/knba_logo.webp\" class=\"attachment-full size-full wp-image-4683\" alt=\"\" srcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/knba_logo.webp 783w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/knba_logo-300x96.webp 300w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/knba_logo-768x245.webp 768w\" sizes=\"(max-width: 783px) 100vw, 783px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-0101c69\" data-id=\"0101c69\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-1d1fdfb\" data-id=\"1d1fdfb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-87b2cc4 elementor-widget elementor-widget-image\" data-id=\"87b2cc4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.phasix.co.uk\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"696\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/phasix_esd_logo-1024x696.webp\" class=\"attachment-large size-large wp-image-4797\" alt=\"\" srcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/phasix_esd_logo-1024x696.webp 1024w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/phasix_esd_logo-300x204.webp 300w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/phasix_esd_logo-768x522.webp 768w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/phasix_esd_logo-1536x1043.webp 1536w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/phasix_esd_logo-2048x1391.webp 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1a35a09 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1a35a09\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-435cead\" data-id=\"435cead\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fc30154 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"fc30154\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5297be elementor-widget elementor-widget-heading\" data-id=\"c5297be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Sponsor principal de TEXPO<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aff6fc9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aff6fc9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-de266a4\" data-id=\"de266a4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-d175585\" data-id=\"d175585\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-7e2ead1\" data-id=\"7e2ead1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cbc3519 elementor-widget elementor-widget-image\" data-id=\"cbc3519\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.comsol.com\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"55\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/Comsol_logo.jpg\" class=\"attachment-large size-large wp-image-3288\" alt=\"\" srcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/Comsol_logo.jpg 600w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/Comsol_logo-300x28.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-e3eccaa\" data-id=\"e3eccaa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-87f932b\" data-id=\"87f932b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c12afaa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c12afaa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-49dc391\" data-id=\"49dc391\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cac5768 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"cac5768\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b051ee4 elementor-widget elementor-widget-heading\" data-id=\"b051ee4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">sponsors du prix TEXPO<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c9372d5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c9372d5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-4d71f12\" data-id=\"4d71f12\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-49b1913\" data-id=\"49b1913\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-7fc4b36\" data-id=\"7fc4b36\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-006a722 elementor-widget elementor-widget-image\" data-id=\"006a722\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.c2mi.ca\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"635\" height=\"243\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/06\/c2mi_icon.jpg\" class=\"attachment-large size-large wp-image-2575\" alt=\"\" srcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/06\/c2mi_icon.jpg 635w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/06\/c2mi_icon-300x115.jpg 300w\" sizes=\"(max-width: 635px) 100vw, 635px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-d6a9321\" data-id=\"d6a9321\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-97d61b5\" data-id=\"97d61b5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6f95a6cc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6f95a6cc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ead81b1\" data-id=\"ead81b1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-291af0e7 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"291af0e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0a23bfa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0a23bfa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-269a88e\" data-id=\"269a88e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e10c458 elementor-widget elementor-widget-heading\" data-id=\"e10c458\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Commanditaire du CSS 2026<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-edaaf52 elementor-widget elementor-widget-text-editor\" data-id=\"edaaf52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\"><span data-olk-copy-source=\"MessageBody\">Contactez-nous pour en savoir plus sur les possibilit\u00e9s de parrainage et d&rsquo;exposition.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2814954\" data-id=\"2814954\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab3c30f elementor-widget elementor-widget-html\" data-id=\"ab3c30f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<iframe title=\"Contact\" width=\"300\" height=\"570\" src=\"https:\/\/go.cmc.ca\/l\/947082\/2026-03-16\/3npjq2\">\n<\/iframe>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-de14c45 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"de14c45\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f8213ff\" data-id=\"f8213ff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9201a76 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9201a76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5ad3b92 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5ad3b92\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8339e6d\" data-id=\"8339e6d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bb88fce elementor-widget elementor-widget-heading\" data-id=\"bb88fce\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Comit\u00e9 organisateur <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1c77f74 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1c77f74\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-a126367\" data-id=\"a126367\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-932460f\" data-id=\"932460f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-f91eac9\" data-id=\"f91eac9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d2449bb elementor-widget elementor-widget-elementskit-team\" data-id=\"d2449bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-team.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\">\t\t\t\t <div class=\"profile-square-v square-v5 no_gutters\"> \t\t\t\t\n\t\t<div class=\"profile-card elementor-animation- text-center ekit-team-style-centered_style_details\">\n\t\t\t\t\t\t\t<a aria-label=\"profile\" href=\"javascript:void(0)\" data-mfp-src=\"#ekit_team_modal_d2449bb_4320\" class=\"ekit-team-popup\">\n\t\t\t\n\t\t\t\t<div class=\"profile-header ekit-team-img \"  data-toggle=\"modal\" data-target=\"ekit_team_modal_#d2449bb_4320\" >\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"300\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/Manon-Duclos-250x300.jpg\" class=\"attachment-medium size-medium wp-image-3223\" alt=\"\" srcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/Manon-Duclos-250x300.jpg 250w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/elementor\/thumbs\/Manon-Duclos-rbzmyxrizmn4nzg484psicm2i7zgvad0k5wjf61v3k.jpg 100w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/Manon-Duclos.jpg 500w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t<\/div><!-- .profile-header END -->\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\n\t\t\t\t<div class=\"profile-body\">\n\t\t\t\t\t\n\t\t\t\t\t<h2 class=\"profile-title\">\n\t\t\t\t\t\t\t\t\t\t\t<a aria-label=\"profile\" href=\"javascript:void(0)\" data-mfp-src=\"#ekit_team_modal_d2449bb_4320\" class=\"ekit-team-popup\">\n\t\t\t\t\t\tManon Duclos\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t<p class=\"profile-designation\">Technum Qu\u00e9bec<\/p>\n\t\t\t\t\t\t\t\t\t<\/div><!-- .profile-body END -->\n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t <\/div> \t\t\t\n\t\t\t\n\t\t\t\t\t<div class=\"zoom-anim-dialog mfp-hide elementskit-team-popup team-popup-id-d2449bb\" id=\"ekit_team_modal_d2449bb_4320\" tabindex=\"-1\" role=\"dialog\" aria-modal=\"true\">\n\t\t\t\t<div class=\"modal-dialog modal-dialog-centered\" role=\"document\">\n\t\t\t\t\t<div class=\"modal-content\">\n\t\t\t\t\t\t<button type=\"button\" class=\"ekit-team-modal-close\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-times\"><\/i>\t\t\t\t\t\t<\/button>\n\n\t\t\t\t\t\t<div class=\"modal-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ekit-team-modal-img\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"300\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/Manon-Duclos-250x300.jpg\" class=\"attachment-medium size-medium wp-image-3223\" alt=\"\" srcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/Manon-Duclos-250x300.jpg 250w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/elementor\/thumbs\/Manon-Duclos-rbzmyxrizmn4nzg484psicm2i7zgvad0k5wjf61v3k.jpg 100w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/Manon-Duclos.jpg 500w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"ekit-team-modal-info has-img\">\n\t\t\t\t\t\t\t\t<h2 class=\"ekit-team-modal-title\">Manon Duclos<\/h2>\n\t\t\t\t\t\t\t\t<p class=\"ekit-team-modal-position\">Technum Qu\u00e9bec<\/p>\n\n\t\t\t\t\t\t\t\t<div class=\"ekit-team-modal-content\">\n\t\t\t\t\t\t\t\t\tManon Duclos \u0153uvre dans les domaines de l\u2019innovation, de la qualit\u00e9 et de l\u2019excellence organisationnelle depuis plus de 30 ans. Ing\u00e9nieure chimique dipl\u00f4m\u00e9e de l\u2019Universit\u00e9 Laval et d\u00e9tentrice d\u2019une ma\u00eetrise en gestion de l\u2019ing\u00e9nierie de l\u2019Universit\u00e9 de Sherbrooke, elle a occup\u00e9 des r\u00f4les strat\u00e9giques dans des entreprises de pointe telles qu\u2019IBM, Mitel Semiconducteur et Teledyne DALSA.  \n\nSon parcours vari\u00e9 lui a permis de d\u00e9velopper une expertise unique en gestion de projets complexes, en assurance qualit\u00e9 et en d\u00e9veloppement organisationnel, en plus de former des centaines de gestionnaires sur la culture d\u2019innovation et l\u2019importance de la qualit\u00e9 comme vecteur d\u2019excellence. Elle est \u00e9galement reconnue pour ses capacit\u00e9s \u00e0 mobiliser les acteurs de divers secteurs et \u00e0 b\u00e2tir des partenariats solides \u00e0 l\u2019\u00e9chelle locale et internationale.\nAu Mouvement qu\u00e9b\u00e9cois de la qualit\u00e9, o\u00f9 elle a occup\u00e9 le poste de vice-pr\u00e9sidente \u00e0 l\u2019innovation et \u00e0 l\u2019excellence organisationnelle, elle a pilot\u00e9 des strat\u00e9gies innovantes, anim\u00e9 des r\u00e9seaux de gestionnaires \u00e0 travers le Qu\u00e9bec et contribu\u00e9 \u00e0 faire \u00e9voluer des organisations vers de nouveaux sommets. \n\nR\u00e9sidente de la r\u00e9gion de Bromont depuis 30 ans, Manon conna\u00eet bien les atouts de son milieu, notamment en mati\u00e8re de qualit\u00e9 de vie et d\u2019innovation. En tant que PDG de Technum Qu\u00e9bec, une des premi\u00e8res zones d\u2019innovation du Qu\u00e9bec sp\u00e9cialis\u00e9e en \u00e9lectronique et en semi-conducteurs, elle continuera de stimuler les projets de collaboration novateurs et de positionner cette industrie comme un pilier de la transformation num\u00e9rique au Qu\u00e9bec et \u00e0 l\u2019international. \n\nManon Duclos est aussi conf\u00e9renci\u00e8re et auteure de plusieurs guides sur l\u2019innovation et l\u2019excellence organisationnelle. Elle demeure passionn\u00e9e par le d\u00e9passement de soi, la cr\u00e9ativit\u00e9 et le d\u00e9veloppement durable. \t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-08a39fe\" data-id=\"08a39fe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64d93ad elementor-widget elementor-widget-elementskit-team\" data-id=\"64d93ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-team.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\">\t\t\t\t <div class=\"profile-square-v square-v5 no_gutters\"> \t\t\t\t\n\t\t<div class=\"profile-card elementor-animation- text-center ekit-team-style-centered_style_details\">\n\t\t\t\t\t\t\t<a aria-label=\"profile\" href=\"javascript:void(0)\" data-mfp-src=\"#ekit_team_modal_64d93ad_4320\" class=\"ekit-team-popup\">\n\t\t\t\n\t\t\t\t<div class=\"profile-header ekit-team-img \"  data-toggle=\"modal\" data-target=\"ekit_team_modal_#64d93ad_4320\" >\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"300\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/08\/laura_bw-250x300.png\" class=\"attachment-medium size-medium wp-image-3047\" alt=\"\" srcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/08\/laura_bw-250x300.png 250w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/08\/laura_bw.png 500w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t<\/div><!-- .profile-header END -->\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\n\t\t\t\t<div class=\"profile-body\">\n\t\t\t\t\t\n\t\t\t\t\t<h2 class=\"profile-title\">\n\t\t\t\t\t\t\t\t\t\t\t<a aria-label=\"profile\" href=\"javascript:void(0)\" data-mfp-src=\"#ekit_team_modal_64d93ad_4320\" class=\"ekit-team-popup\">\n\t\t\t\t\t\tLaura William\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t<p class=\"profile-designation\">Disruptor<\/p>\n\t\t\t\t\t\t\t\t\t<\/div><!-- .profile-body END -->\n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t <\/div> \t\t\t\n\t\t\t\n\t\t\t\t\t<div class=\"zoom-anim-dialog mfp-hide elementskit-team-popup team-popup-id-64d93ad\" id=\"ekit_team_modal_64d93ad_4320\" tabindex=\"-1\" role=\"dialog\" aria-modal=\"true\">\n\t\t\t\t<div class=\"modal-dialog modal-dialog-centered\" role=\"document\">\n\t\t\t\t\t<div class=\"modal-content\">\n\t\t\t\t\t\t<button type=\"button\" class=\"ekit-team-modal-close\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-times\"><\/i>\t\t\t\t\t\t<\/button>\n\n\t\t\t\t\t\t<div class=\"modal-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ekit-team-modal-img\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"300\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/08\/laura_bw-250x300.png\" class=\"attachment-medium size-medium wp-image-3047\" alt=\"\" srcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/08\/laura_bw-250x300.png 250w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/08\/laura_bw.png 500w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"ekit-team-modal-info has-img\">\n\t\t\t\t\t\t\t\t<h2 class=\"ekit-team-modal-title\">Laura William<\/h2>\n\t\t\t\t\t\t\t\t<p class=\"ekit-team-modal-position\">Disruptor<\/p>\n\n\t\t\t\t\t\t\t\t<div class=\"ekit-team-modal-content\">\n\t\t\t\t\t\t\t\t\tAvec une formation en \u00e9conomie, technologie, relations internationales, \u00e9dition de livres et image de marque, Laura poss\u00e8de une expertise dans l\u2019identification et l\u2019analyse des influences sociales, culturelles et politiques qui impactent l\u2019industrie. L\u2019application de ces connaissances lui a permis d\u2019aider des organisations \u00e9tablies et \u00e9mergentes \u00e0 faire face aux changements technologiques, sociaux et commerciaux acc\u00e9l\u00e9r\u00e9s, en d\u00e9veloppant des strat\u00e9gies concurrentielles et commerciales efficaces. Elle a un talent particulier pour rep\u00e9rer des forces existantes mais n\u00e9glig\u00e9es, d\u00e9finir des opportunit\u00e9s uniques et les rendre op\u00e9rationnelles.  \n\n\nL\u2019exp\u00e9rience multidisciplinaire de Laura dans divers secteurs lui a permis de travailler largement dans le domaine de l\u2019innovation. Elle a collabor\u00e9 \u00e0 l\u2019\u00e9chelle nationale avec des organisations du secteur priv\u00e9, du milieu universitaire, du gouvernement et du secteur \u00e0 but non lucratif, occupant une grande vari\u00e9t\u00e9 de r\u00f4les li\u00e9s \u00e0 l\u2019innovation. \t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-8e8774e\" data-id=\"8e8774e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-e50d5ff\" data-id=\"e50d5ff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>O\u00f9 la souverainet\u00e9 rencontre la prosp\u00e9rit\u00e9 Symposium canadien sur les semi-conducteurs 2026 R\u00c9CEPTION : 19 OCTOBRE SYMPOSIUM : 20\u201321 OCTOBRE OTTAWA, ONTARIO Le XX\u1d49 si\u00e8cle a vu le d\u00e9veloppement, l\u2019\u00e9volution [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":4319,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-4320","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"featured_image_src":"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/03\/CSS-header-900x500-1-600x400.jpg","featured_image_src_square":"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/03\/CSS-header-900x500-1-600x500.jpg","_links":{"self":[{"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/pages\/4320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/comments?post=4320"}],"version-history":[{"count":0,"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/pages\/4320\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/media\/4319"}],"wp:attachment":[{"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/media?parent=4320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":4330,"date":"2026-02-11T09:20:08","date_gmt":"2026-02-11T14:20:08","guid":{"rendered":"https:\/\/fabricinnovation.ca\/texpo-2026\/"},"modified":"2026-05-12T08:53:29","modified_gmt":"2026-05-12T13:53:29","slug":"texpo-2026","status":"publish","type":"page","link":"https:\/\/fabricinnovation.ca\/fr\/texpo-2026\/","title":{"rendered":"TEXPO 2026"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4330\" class=\"elementor elementor-4330 elementor-4247\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-abe3d0f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"abe3d0f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1943717\" data-id=\"1943717\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ee434cb elementor-widget elementor-widget-spacer\" data-id=\"ee434cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0bf437f\" data-id=\"0bf437f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8c5cecd elementor-widget elementor-widget-spacer\" data-id=\"8c5cecd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e94da6d\" data-id=\"e94da6d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6df3781 elementor-widget__width-initial elementor-widget elementor-widget-spacer\" data-id=\"6df3781\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1589900 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1589900\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d9964e8\" data-id=\"d9964e8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d1a5810 elementor-widget elementor-widget-heading\" data-id=\"d1a5810\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Symposium canadien sur les semi-conducteurs 2026<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-696fdac elementor-widget elementor-widget-heading\" data-id=\"696fdac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\"><b>TEXPO<\/b>2026<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4efd3b5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4efd3b5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3ea45a1\" data-id=\"3ea45a1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3914425 elementor-widget elementor-widget-template\" data-id=\"3914425\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"4322\" class=\"elementor elementor-4322\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f97ecfc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f97ecfc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1aa2fb9\" data-id=\"1aa2fb9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef95ed6 elementor-nav-menu__align-center elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"ef95ed6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-underline e--animation-fade\">\n\t\t\t\t<ul id=\"menu-1-ef95ed6\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4323\"><a href=\"https:\/\/fabricinnovation.ca\/css2026\/\" class=\"elementor-item menu-link\">CSS 2026<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4336\"><a href=\"https:\/\/fabricinnovation.ca\/css2026\/agenda\/\" class=\"elementor-item menu-link\">Programme<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4673\"><a href=\"https:\/\/fabricinnovation.ca\/css2026\/speakers\/\" class=\"elementor-item menu-link\">Conf\u00e9renciers<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4324\"><a href=\"https:\/\/fabricinnovation.ca\/texpo-2026\/\" class=\"elementor-item menu-link\">TEXPO 2026<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Permuter le menu\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-ef95ed6\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4323\"><a href=\"https:\/\/fabricinnovation.ca\/css2026\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">CSS 2026<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4336\"><a href=\"https:\/\/fabricinnovation.ca\/css2026\/agenda\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Programme<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4673\"><a href=\"https:\/\/fabricinnovation.ca\/css2026\/speakers\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Conf\u00e9renciers<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4324\"><a href=\"https:\/\/fabricinnovation.ca\/texpo-2026\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">TEXPO 2026<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba91426 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ba91426\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e65ed9d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e65ed9d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-40e4946\" data-id=\"40e4946\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e039722 elementor-widget elementor-widget-heading\" data-id=\"e039722\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\"><b>TEXPO<\/b>2026<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd35866 elementor-widget elementor-widget-heading\" data-id=\"bd35866\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Sponsor principal<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5686b11 elementor-widget elementor-widget-image\" data-id=\"5686b11\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.comsol.com\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"55\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/Comsol_logo.jpg\" class=\"attachment-large size-large wp-image-3288\" alt=\"\" srcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/Comsol_logo.jpg 600w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/Comsol_logo-300x28.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a77334 elementor-widget elementor-widget-spacer\" data-id=\"7a77334\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3bd56da elementor-widget elementor-widget-text-editor\" data-id=\"3bd56da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le concours de recherche pour \u00e9tudiants dipl\u00f4m\u00e9s TEXPO 2026 est un \u00e9v\u00e9nement annuel qui offre aux \u00e9tudiants aux cycles sup\u00e9rieurs une occasion unique de pr\u00e9senter leurs applications novatrices des microsyst\u00e8mes et des nanotechnologies \u00e0 des repr\u00e9sentants de l\u2019industrie et du milieu universitaire, tout en \u00e9tant en comp\u00e9tition pour un total de 15 500\u202f$ en prix.<\/p><p>TEXPO 2026 fait partie du <a href=\"https:\/\/fabricinnovation.ca\/fr\/css2026\/\">Symposium canadien sur les semi-conducteurs 2026<\/a>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b9f01f elementor-align-center elementor-widget elementor-widget-button\" data-id=\"5b9f01f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/fabricinnovation.ca\/texpo-2026-application\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Postuler<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa7d47f elementor-widget elementor-widget-spacer\" data-id=\"fa7d47f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-94e34cd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"94e34cd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-50d0c14\" data-id=\"50d0c14\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef15975 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ef15975\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b9b65b5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b9b65b5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5d8edb9\" data-id=\"5d8edb9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ee82f7 elementor-widget elementor-widget-icon-box\" data-id=\"5ee82f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPrix\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-af0f595 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"af0f595\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6a57293\" data-id=\"6a57293\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f50d4a6 elementor-widget elementor-widget-heading\" data-id=\"f50d4a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">3 000 $<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-148f0b1\" data-id=\"148f0b1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ac1837 elementor-widget elementor-widget-heading\" data-id=\"5ac1837\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Prix d\u2019excellence pour les outils de CAD et la m\u00e9thodologie de conception en mati\u00e8re de microsyst\u00e8mes<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f569ad elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"0f569ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c8c2e5a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c8c2e5a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-94b7063\" data-id=\"94b7063\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ae85c1e elementor-widget elementor-widget-heading\" data-id=\"ae85c1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">3 000 $<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-718e2c9\" data-id=\"718e2c9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-096787a elementor-widget elementor-widget-heading\" data-id=\"096787a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Prix Gayathri Singh pour l'innovation des femmes dans les microsyst\u00e8mes<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-320f4eb elementor-widget elementor-widget-heading\" data-id=\"320f4eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Commandit\u00e9 par<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a5b328a elementor-widget elementor-widget-image\" data-id=\"a5b328a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.c2mi.ca\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"635\" height=\"243\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/06\/c2mi_icon.jpg\" class=\"attachment-full size-full wp-image-2575\" alt=\"\" srcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/06\/c2mi_icon.jpg 635w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/06\/c2mi_icon-300x115.jpg 300w\" sizes=\"(max-width: 635px) 100vw, 635px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-42db5e1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"42db5e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9705dc0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9705dc0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-45840e9\" data-id=\"45840e9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d2b54e0 elementor-widget elementor-widget-heading\" data-id=\"d2b54e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">3 000 $<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-bd44352\" data-id=\"bd44352\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d9ad73f elementor-widget elementor-widget-heading\" data-id=\"d9ad73f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Prix d\u2019excellence en mati\u00e8re de fabrication de microsyst\u00e8mes<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f2abdc elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2f2abdc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-114ee98 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"114ee98\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6c7d30e\" data-id=\"6c7d30e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c5b1cc elementor-widget elementor-widget-heading\" data-id=\"1c5b1cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">3 000 $<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2a694cb\" data-id=\"2a694cb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2715182 elementor-widget elementor-widget-heading\" data-id=\"2715182\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Prix d'excellence en algorithmes ou en informatique quantique <\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-583b503 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"583b503\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-68365e2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"68365e2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-29ff2e3\" data-id=\"29ff2e3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7dee187 elementor-widget elementor-widget-heading\" data-id=\"7dee187\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">3 500 $<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-661b9a6\" data-id=\"661b9a6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f80ccdc elementor-widget elementor-widget-heading\" data-id=\"f80ccdc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Prix Brian L. Barge pour l\u2019excellence d\u2019int\u00e9gration des microsyst\u00e8mes<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c4f520b\" data-id=\"c4f520b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5bbaa2c elementor-widget elementor-widget-icon-box\" data-id=\"5bbaa2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tInformations cl\u00e9s\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f6bd02d elementor-widget elementor-widget-toggle\" data-id=\"f6bd02d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2581\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2581\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Admissibilit\u00e9<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2581\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2581\"><p>Le pr\u00e9sentateur principal de TEXPO doit \u00eatre un \u00e9tudiant dipl\u00f4m\u00e9 inscrit dans une universit\u00e9 canadienne au moment de la soumission du r\u00e9sum\u00e9. Les directeurs de recherche, les professeurs et les boursiers postdoctoraux qui contribuent au projet sont les bienvenus en tant que pr\u00e9sentateurs secondaires dans le cadre de la comp\u00e9tition. <\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2582\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2582\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Information pour les participants<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2582\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2582\"><p>Informations importantes pour les participants de TEXPO.<\/p>\n<ul>\n<li><strong>Horaire :<\/strong>\n<ul>\n<li>Votre horaire de passage devant le jury vous sera communiqu\u00e9 avant l&rsquo;\u00e9v\u00e9nement<\/li>\n<\/ul>\n<\/li>\n<li><strong>\u00c9valuation de votre d\u00e9monstration :<\/strong>\n<ul>\n<li>Veuillez lire attentivement les crit\u00e8res d\u2019\u00e9valuation. Les informations concernant les prix se trouvent ci-dessus. Chaque page de prix comprend les crit\u00e8res d\u2019\u00e9valuation.  <\/li>\n<li>Vous disposerez de 15 minutes au total pour pr\u00e9senter votre projet aux membres du jury.<br \/>Cela comprend jusqu\u2019\u00e0 10 minutes pour votre d\u00e9monstration, suivies d\u2019une p\u00e9riode de questions et r\u00e9ponses de 5 minutes avec le jury. Chaque comp\u00e9tition compte g\u00e9n\u00e9ralement trois juges (id\u00e9alement un repr\u00e9sentant de l&rsquo;industrie canadienne, un repr\u00e9sentant du milieu universitaire et un d\u2019un organisme \u00e0 but non lucratif).  <\/li>\n<li>Votre pr\u00e9sentation sera publique pendant le processus d\u2019\u00e9valuation, toutefois, seuls les juges pourront poser des questions. <\/li>\n<\/ul>\n<\/li>\n<li><strong>Remise des prix<\/strong> :<br \/>Les gagnants seront annonc\u00e9s imm\u00e9diatement apr\u00e8s le salon TEXPO.<\/li>\n<li>Les gagnants de TEXPO sont fortement encourag\u00e9s \u00e0 utiliser les fonds du prix pour soutenir leur formation ou leur perfectionnement dans le domaine de la R-D en micro-nanosyst\u00e8mes.<br \/>Les fonds peuvent \u00eatre utilis\u00e9s pour couvrir les frais de participation \u00e0 une conf\u00e9rence ou \u00e0 un atelier, ou pour visiter un laboratoire ou toute autre installation technique, au Canada ou \u00e0 l\u2019\u00e9tranger. <\/li>\n<\/ul>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2583\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2583\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Format de pr\u00e9sentation<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2583\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2583\"><p>TBD<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2584\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2584\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Directives pour le r\u00e9sum\u00e9<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2584\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2584\"><p>Les \u00e9tudiants int\u00e9ress\u00e9s par le concours sont invit\u00e9s \u00e0 soumettre un r\u00e9sum\u00e9 avant le <strong>7 ao\u00fbt 2026<\/strong>.<\/p>\n<p>REMARQUE : les r\u00e9sum\u00e9s sont soumis avant la comp\u00e9tition et ne sont PAS pris en compte dans le processus d&rsquo;\u00e9valuation. Ils servent \u00e0 garantir la meilleure ad\u00e9quation possible entre la description du projet soumis et la cat\u00e9gorie de prix la plus pertinente. Les candidats au TEXPO seront inform\u00e9s de leur acceptation avant le <b>4 septembre 2026<\/b>.  <\/p>\n<p>Votre r\u00e9sum\u00e9 doit respecter les directives d\u00e9crites ci-dessous.<\/p>\n<p>Longueur :<b style=\"font-style: inherit;\"> deux pages, en format PDF<\/b><\/p>\n<h4>Contenu :<\/h4>\n<ul>\n<li>Un r\u00e9sum\u00e9 (150 mots) r\u00e9dig\u00e9 en langage clair, pr\u00e9sentant le projet, le probl\u00e8me abord\u00e9 et l\u2019importance des r\u00e9sultats obtenus. Ce r\u00e9sum\u00e9 doit \u00eatre compr\u00e9hensible par un public non sp\u00e9cialis\u00e9 et pourrait \u00eatre utilis\u00e9 dans les communications de TEXPO. <\/li>\n<li>Une description g\u00e9n\u00e9rale des objectifs du projet, du travail r\u00e9alis\u00e9 et des r\u00e9sultats obtenus.<br \/>Des figures et des tableaux sont autoris\u00e9s (voir ci-dessous). <\/li>\n<\/ul>\n<h4>Formatage :<\/h4>\n<p><strong>Texte des en-t\u00eates :<\/strong><br \/>Times New Roman, taille de police 14 \u00e0 16 points.<\/p>\n<p><strong>Texte principal :<\/strong><\/p>\n<ul>\n<li>Times New Roman, taille 12 points<\/li>\n<li>Une \u00e0 deux lignes d\u2019espace blanc doivent pr\u00e9c\u00e9der le texte principal.<\/li>\n<li>Les listes \u00e0 puces et les listes num\u00e9rot\u00e9es sont autoris\u00e9es.<\/li>\n<li>Les figures et les tableaux sont autoris\u00e9s et doivent \u00eatre pr\u00e9c\u00e9d\u00e9s et suivis d\u2019au moins une ligne d\u2019espace blanc ; num\u00e9rot\u00e9s ; l\u00e9gend\u00e9s ; et mentionn\u00e9s dans le corps du texte.<\/li>\n<\/ul>\n<h4>Dates limites :<\/h4>\n<p>Date limite de candidature : <strong>\u00e0 d\u00e9terminer<\/strong><br \/>Notification d&rsquo;acceptation : <strong>\u00e0 d\u00e9terminer<\/strong><\/p>\n<p>Des questions ? Contactez Sarah Neville, coordonnatrice du concours de recherche TEXPO. <a role=\"link\" href=\"mailto:sarah.neville@cmc.ca\"> sarah.neville@cmc.ca<\/a> <\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2585\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-2585\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Informations sur la candidature<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2585\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-2585\"><ul type=\"circle\">\n<li>Postulez pour un maximum de deux cat\u00e9gories de prix \u2013 (1er et 2e choix). Veuillez faire votre s\u00e9lection avec soin en fonction des crit\u00e8res d\u2019attribution. <\/li>\n<li>L\u2019admission dans les cat\u00e9gories de prix se fait selon le principe du premier arriv\u00e9, premier servi, pour les personnes r\u00e9pondant aux crit\u00e8res d\u2019admissibilit\u00e9.<\/li>\n<li>Votre deuxi\u00e8me choix de cat\u00e9gorie ne sera pris en compte que si votre premier choix est complet.<\/li>\n<li>Nombre minimum de candidatures par cat\u00e9gorie : <strong>4<\/strong><\/li>\n<li>Nombre maximum de candidatures par cat\u00e9gorie : <strong>10<\/strong><\/li>\n<\/ul>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c32a60d\" data-id=\"c32a60d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-685d50b elementor-widget elementor-widget-icon-box\" data-id=\"685d50b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDates importantes\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-96ba007 elementor-widget elementor-widget-heading\" data-id=\"96ba007\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Date limite de candidature<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0de947e elementor-widget elementor-widget-heading\" data-id=\"0de947e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">7 ao\u00fbt 2026<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f749e2d elementor-widget elementor-widget-heading\" data-id=\"f749e2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Notification d\u2019acceptation<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c3b1f07 elementor-widget elementor-widget-heading\" data-id=\"c3b1f07\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">4 septembre 2026<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f828cf9 elementor-widget elementor-widget-heading\" data-id=\"f828cf9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Date des pr\u00e9sentations<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42e6d2f elementor-widget elementor-widget-heading\" data-id=\"42e6d2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">20-21 octobre 2026<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c9246ae elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c9246ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43b4650 elementor-widget elementor-widget-heading\" data-id=\"43b4650\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.cmc.ca\/awards\/#texpo\">Laur\u00e9ats du prix TEXPO 2025<\/a><\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-563cd19 elementor-widget elementor-widget-heading\" data-id=\"563cd19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/10\/TEXPO_2025_WEB-V6-1.pdf\">Participants au TEXPO 2025<\/a><\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d425b0 elementor-widget elementor-widget-heading\" data-id=\"0d425b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.cmc.ca\/past-texpo-winners\/\">Laur\u00e9ats pr\u00e9c\u00e9dents du concours TEXPO <\/a><\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0665edb elementor-widget elementor-widget-image\" data-id=\"0665edb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"384\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/11\/TEXPO_2025_participants.png\" class=\"attachment-large size-large wp-image-3723\" alt=\"\" srcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/11\/TEXPO_2025_participants.png 1024w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/11\/TEXPO_2025_participants-300x113.png 300w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/11\/TEXPO_2025_participants-768x288.png 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d46b622 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d46b622\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30cecdd elementor-widget elementor-widget-shortcode\" data-id=\"30cecdd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"2738\" class=\"elementor elementor-2738 elementor-2736 elementor-2736\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-37b10bb7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"37b10bb7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2515d5ac\" data-id=\"2515d5ac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c82fca8 elementor-widget elementor-widget-heading\" data-id=\"c82fca8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Sarah Neville<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1af4def4 elementor-widget elementor-widget-heading\" data-id=\"1af4def4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Coordinateur principal<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6034c22d elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"6034c22d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"mailto:neville@cmc.ca\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-envelope\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e7c7a32 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e7c7a32\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c546345\" data-id=\"c546345\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6861529 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"6861529\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b44904b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b44904b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-347b53e\" data-id=\"347b53e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d18f929 elementor-widget elementor-widget-heading\" data-id=\"d18f929\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Soutenez la prochaine g\u00e9n\u00e9ration d\u2019innovateurs<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67afa63 elementor-widget elementor-widget-text-editor\" data-id=\"67afa63\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-olk-copy-source=\"MessageBody\">Devenez commanditaire de notre comp\u00e9tition \u00e9tudiante et contribuez \u00e0 fa\u00e7onner l\u2019avenir des semi-conducteurs.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-502d01e\" data-id=\"502d01e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cce650e elementor-widget elementor-widget-html\" data-id=\"cce650e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<iframe title=\"Contact\" width=\"300\" height=\"240\" src=\"https:\/\/go.cmc.ca\/l\/947082\/2025-09-25\/3n9yks\">\n<\/iframe>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f28f25c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f28f25c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-98818bd\" data-id=\"98818bd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7607943 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7607943\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-632b34e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"632b34e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-113e61a\" data-id=\"113e61a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7332340 elementor-widget elementor-widget-heading\" data-id=\"7332340\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Crit\u00e8res d\u2019attribution des prix<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d82c477 elementor-widget elementor-widget-toggle\" data-id=\"d82c477\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2261\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2261\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Prix d\u2019excellence pour les outils de CAD et la m\u00e9thodologie de conception en mati\u00e8re de microsyst\u00e8mes<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2261\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2261\"><h4>Aper\u00e7u <\/h4>\n<p>Ce prix r\u00e9compense l&rsquo;utilisation ou le d\u00e9veloppement novateur d&rsquo;outils de conception assist\u00e9e par ordinateur (CAO) ou de m\u00e9thodes de conception conduisant \u00e0 l&rsquo;am\u00e9lioration de la fabrication et de l&rsquo;application de prototypes de microsyst\u00e8mes sophistiqu\u00e9s pertinents pour l&rsquo;industrie canadienne, id\u00e9alement mis en \u00e9vidence par un collaborateur industriel.\u202fLe prix sera d\u00e9cern\u00e9 au concurrent qui aura fait la d\u00e9monstration d&rsquo;une nouvelle technologie de conception pr\u00e9sentant le plus grand potentiel d&rsquo;am\u00e9lioration substantielle de la fabrication et du d\u00e9ploiement des microsyst\u00e8mes. Voici quelques exemples :<\/p>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"4\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">Nouveaux algorithmes ou nouvelles techniques pour am\u00e9liorer la qualit\u00e9 des r\u00e9sultats ou des temps d\u2019ex\u00e9cution des outils ou des t\u00e2ches. <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"4\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"2\" data-aria-level=\"1\"><span data-contrast=\"auto\">Abstractions de conception, langages ou int\u00e9gration d\u2019environnement de conception favorisant un domaine avec plusieurs technologies ou un d\u00e9veloppement et un prototypage multidisciplinaires. <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"4\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"3\" data-aria-level=\"1\"><span data-contrast=\"auto\">Am\u00e9liorations des m\u00e9thodologies de &lsquo;conception pour\u2026&rsquo;, telles que la fabricabilit\u00e9 ou la s\u00e9curit\u00e9. <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"4\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"4\" data-aria-level=\"1\"><span data-contrast=\"auto\">Nouvelle utilisation d\u2019infrastructure en nuage permettant d\u2019acc\u00e9l\u00e9rer l\u2019utilisation des outils ou des flux existants. <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"4\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"5\" data-aria-level=\"1\"><span data-contrast=\"auto\">Le prix est destin\u00e9 aux \u00e9tudiants aux cycles sup\u00e9rieurs des universit\u00e9s canadiennes. <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<p><span data-contrast=\"auto\">Les laur\u00e9ats sont fortement encourag\u00e9s \u00e0 utiliser la r\u00e9compense en argent associ\u00e9e au Prix afin de favoriser le transfert de connaissance ou la formation associ\u00e9s \u00e0 la R-D appliqu\u00e9e aux microsyst\u00e8mes. Par exemple, pour les co\u00fbts d\u2019une conf\u00e9rence ou d\u2019un atelier ou encore pour visiter un laboratoire ou une autre installation technique au Canada ou dans un autre pays. <\/span><span data-ccp-props=\"{}\"> <\/span><\/p>\n<p aria-level=\"2\"><span data-ccp-props=\"{\"134245418\":true,\"134245529\":true,\"335559738\":160,\"335559739\":80}\"> <\/span><\/p>\n<h5 aria-level=\"2\"><span data-contrast=\"none\">Crit\u00e8res d\u2019\u00e9valuation<\/span><span data-ccp-props=\"{\"134245418\":true,\"134245529\":true,\"335559738\":160,\"335559739\":80}\"> <\/span><\/h5>\n<p><span data-contrast=\"auto\">Le jury sera compos\u00e9 de trois repr\u00e9sentants issus du monde des affaires, du milieu universitaire et d&rsquo;organisations \u00e0 but non lucratif au Canada. Les juges \u00e9valuent chaque concurrent et s\u00e9lectionnent la d\u00e9monstration qui r\u00e9pond le mieux aux crit\u00e8res suivants : <\/span><span data-ccp-props=\"{}\"> <\/span><\/p>\n<p><b><span data-contrast=\"auto\">Crit\u00e8re 1 : Excellence technique (20 points)<\/span><\/b><span data-ccp-props=\"{}\"> <\/span><\/p>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"3\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">Succ\u00e8s de la d\u00e9monstration de la technologie. Did it work\/is the technique practical? <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"3\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"2\" data-aria-level=\"1\"><span data-contrast=\"auto\">Nouvelle application de logiciel de CAO ou de techniques. <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"3\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"3\" data-aria-level=\"1\"><span data-contrast=\"auto\">Niveau de difficult\u00e9 vis\u00e9; cr\u00e9ativit\u00e9 \/ pers\u00e9v\u00e9rance pour r\u00e9soudre les probl\u00e8mes durant le d\u00e9veloppement. <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"3\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"4\" data-aria-level=\"1\"><span data-contrast=\"auto\">Est-ce que cela a men\u00e9 \u00e0 un prototype de fabrication ? <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"3\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"5\" data-aria-level=\"1\"><span data-contrast=\"auto\">Ma\u00eetrise des aspects techniques du projet par l\u2019exposant. <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"3\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"6\" data-aria-level=\"1\"><span data-contrast=\"auto\">Solide compr\u00e9hension de l\u2019importance du sujet. Par exemple, la raison pour laquelle une solution au probl\u00e8me est importante. <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<p><b><span data-contrast=\"auto\">Crit\u00e8re 2 : Application \u00e0 l\u2019industrie (20 points)<\/span><\/b><span data-ccp-props=\"{}\"> <\/span><\/p>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"2\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">Y a-t-il un collaborateur de l\u2019industrie ? Quelle est la valeur offerte au collaborateur de l\u2019industrie ? Est-ce que la solution est importante ou incr\u00e9mentielle ? Comment celle-ci se compare-t-elle aux solutions existantes ?    <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"2\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"2\" data-aria-level=\"1\"><span data-contrast=\"auto\">Quelle \u00e9tait la nature de la collaboration\/participation entre l&rsquo;entreprise et le chercheur, par exemple, travail sur site ou revues de conception ? What was the extent of investment by the industrial collaborator, e.g., time invested or students trained\/hired? <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"2\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"3\" data-aria-level=\"1\"><span data-contrast=\"auto\">Est-ce qu\u2019il existe une infrastructure pour une mise \u00e0 l\u2019\u00e9chelle commerciale ? <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"2\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"4\" data-aria-level=\"1\"><span data-contrast=\"auto\">Quel sera son impact sur la fabrication ou l&rsquo;application des micro\/nanosyst\u00e8mes au Canada, et en quoi cela permettra-t-il de les am\u00e9liorer ? (par exemple, co\u00fbt, fiabilit\u00e9, d\u00e9lai de mise sur le march\u00e9) <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"2\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"5\" data-aria-level=\"1\"><span data-contrast=\"auto\">Quel est le niveau de convivialit\u00e9 pour l\u2019utilisateur (comparativement au d\u00e9veloppeur) ? <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<p><b><span data-contrast=\"auto\">Crit\u00e8re 3 : Excellence de la pr\u00e9sentation et des moyens visuels utilis\u00e9s (10 points)<\/span><\/b><span data-ccp-props=\"{}\"> <\/span><\/p>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"1\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">Explication des informations contextuelles ou de la th\u00e9orie pour les pairs. <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"1\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"2\" data-aria-level=\"1\"><span data-contrast=\"auto\">Clart\u00e9 de l\u2019explication des points techniques. <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"1\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"3\" data-aria-level=\"1\"><span data-contrast=\"auto\">Aisance pour les explications, interactions entre les personnes de la pr\u00e9sentation. <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"1\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"4\" data-aria-level=\"1\"><span data-contrast=\"auto\">Humour, style, originalit\u00e9. <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"1\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"5\" data-aria-level=\"1\"><span data-contrast=\"auto\">R\u00e9cup\u00e9ration d\u2019un probl\u00e8me inattendu. <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"1\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"6\" data-aria-level=\"1\"><span data-contrast=\"auto\">Qualit\u00e9 et efficacit\u00e9 du mat\u00e9riel visuel et \u00e9crit. <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<p><strong>Remarque <\/strong><\/p>\n<p><span data-contrast=\"auto\">Lorsque les projets ont \u00e9t\u00e9 r\u00e9alis\u00e9s par une \u00e9quipe sur une p\u00e9riode d\u00e9termin\u00e9e, le pr\u00e9sentateur doit clairement pr\u00e9senter les contributions de chacun, y compris ses contributions personnelles.<\/span><span data-ccp-props=\"{}\"> <\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2262\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2262\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Prix Gayathri Singh pour d\u2019innovation des microsyst\u00e8mes destin\u00e9 aux femmes<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2262\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2262\"><h5 aria-level=\"2\"><span data-contrast=\"none\">Aper\u00e7u<\/span><span data-ccp-props=\"{\"134245418\":true,\"134245529\":true,\"335559738\":160,\"335559739\":80}\"> <\/span><\/h5>\n<p><span data-contrast=\"auto\">Ce prix r\u00e9compense les travaux de recherche men\u00e9s par des femmes qui contribuent \u00e0 faire progresser le domaine de la recherche sur les microsyst\u00e8mes au Canada. Ces travaux ont donn\u00e9 lieu \u00e0 des r\u00e9sultats concrets pouvant faire l&rsquo;objet de publications, pr\u00e9sentent un potentiel commercial ou ont b\u00e9n\u00e9fici\u00e9 du soutien d&rsquo;un partenaire industriel.  Les travaux interdisciplinaires ou novateurs men\u00e9s dans des laboratoires universitaires ou des salles blanches sont \u00e9galement \u00e9ligibles. <\/span><span data-ccp-props=\"{}\"> <\/span><\/p>\n<p><span data-contrast=\"auto\">Le prix est ouvert aux \u00e9tudiantes aux cycles sup\u00e9rieurs des universit\u00e9s canadiennes. <\/span><span data-ccp-props=\"{}\"> <\/span><\/p>\n<p><span data-contrast=\"auto\">Nous encourageons fortement la laur\u00e9ate \u00e0 utiliser la r\u00e9compense en argent associ\u00e9e au prix afin de favoriser le transfert de connaissance ou la formation associ\u00e9s \u00e0 la R-D appliqu\u00e9e aux microsyst\u00e8mes et aux nanosyst\u00e8mes. Par exemple, pour les co\u00fbts d\u2019une conf\u00e9rence ou d\u2019un atelier ou encore pour visiter un laboratoire ou une autre installation technique au Canada ou dans un autre pays. <\/span><span data-ccp-props=\"{}\"> <\/span><\/p>\n<p><span data-ccp-props=\"{}\"> <\/span><\/p>\n<h5 aria-level=\"2\"><span data-contrast=\"none\">Crit\u00e8res d\u2019\u00e9valuation<\/span><span data-ccp-props=\"{\"134245418\":true,\"134245529\":true,\"335559738\":160,\"335559739\":80}\"> <\/span><\/h5>\n<p><span data-contrast=\"auto\">Le jury sera compos\u00e9 de trois repr\u00e9sentants issus du monde de l&rsquo;industrie, du milieu universitaire et d&rsquo;organisations \u00e0 but non lucratif canadiens. Les juges \u00e9valuent chaque concurrent et s\u00e9lectionnent la d\u00e9monstration qui r\u00e9pond le mieux aux crit\u00e8res suivants : <\/span><span data-ccp-props=\"{}\"> <\/span><\/p>\n<p><b><span data-contrast=\"auto\">Crit\u00e8re 1 : Excellence technique (20 points)<\/span><\/b><span data-ccp-props=\"{}\"> <\/span><\/p>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"5\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">Succ\u00e8s de la d\u00e9monstration de la technologie. Est-ce que \u00e7a a march\u00e9 ? Cette technique est-elle pratique ? <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"5\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"2\" data-aria-level=\"1\"><span data-contrast=\"auto\">Originalit\u00e9 de la conception, nouveaut\u00e9 de la technique ou application innovante de logiciels de CAO ou de techniques de conception. <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"5\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"3\" data-aria-level=\"1\"><span data-contrast=\"auto\">Niveau de difficult\u00e9 vis\u00e9; cr\u00e9ativit\u00e9 \/ pers\u00e9v\u00e9rance pour r\u00e9soudre les probl\u00e8mes durant le d\u00e9veloppement. Est-ce que cela a men\u00e9 \u00e0 un prototype de fabrication ?  <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"5\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"4\" data-aria-level=\"1\"><span data-contrast=\"auto\">Ma\u00eetrise des aspects techniques du projet par l\u2019exposante; compr\u00e9hension des compromis (co\u00fbt, taille et puissance) et des consid\u00e9rations de conception (meilleur cas, pire cas). <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"5\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"5\" data-aria-level=\"1\"><span data-contrast=\"auto\">Solide compr\u00e9hension de l\u2019importance du sujet. Par exemple, la raison pour laquelle une solution au probl\u00e8me est importante. <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<p><b><span data-contrast=\"auto\">Crit\u00e8re 2 : Contribution et pertinence de la recherche en microsyst\u00e8mes au Canada (20 points)<\/span><\/b><span data-ccp-props=\"{}\"> <\/span><\/p>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"6\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">En quoi le concept de projet de microsyst\u00e8me est-il novateur ? Est-ce que la solution est importante ou incr\u00e9mentielle ? Comment celle-ci se compare-t-elle aux solutions existantes ?   <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"6\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"2\" data-aria-level=\"1\"><span data-contrast=\"auto\">Cela permettrait-il d&rsquo;attirer un partenaire industriel ? Cette application commerciale est-elle viable sur le plan de la fabrication, du format et de la rentabilit\u00e9 ? <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"6\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"3\" data-aria-level=\"1\"><span data-contrast=\"auto\">Est-ce que le r\u00f4le de la mise en bo\u00eetier ou de l\u2019int\u00e9gration a \u00e9t\u00e9 consid\u00e9r\u00e9 lors de la conception du composant ?<\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"6\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"4\" data-aria-level=\"1\"><span data-contrast=\"auto\">Quel sera son impact sur la fabrication ou l&rsquo;application des micro\/nanosyst\u00e8mes au Canada, et en quoi cela permettra-t-il de les am\u00e9liorer ? (par exemple, co\u00fbt, fiabilit\u00e9, d\u00e9lai de mise sur le march\u00e9) <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"6\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"5\" data-aria-level=\"1\"><span data-contrast=\"auto\">Si des laboratoires universitaires ont \u00e9t\u00e9 utilis\u00e9s, leurs capacit\u00e9s ont-elles \u00e9t\u00e9 exploit\u00e9es de mani\u00e8re optimale ? A-t-on envisag\u00e9 de recourir aux \u00e9quipements de plusieurs laboratoires, ou de combiner la fabrication pratique et les services de laboratoire ?  Les objectifs de recherche vis\u00e9s par la fabrication sur mesure \u00e9taient-ils tels qu&rsquo;ils n&rsquo;auraient pas pu \u00eatre atteints facilement par d&rsquo;autres moyens ? <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<p><b><span data-contrast=\"auto\">Crit\u00e8re 3 : Excellence de la pr\u00e9sentation et des moyens visuels utilis\u00e9s (10 points)<\/span><\/b><span data-ccp-props=\"{}\"> <\/span><\/p>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"7\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">Explication des informations contextuelles ou de la th\u00e9orie pour les pairs. <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"7\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"2\" data-aria-level=\"1\"><span data-contrast=\"auto\">Clart\u00e9 de l\u2019explication des points techniques. <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"7\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"3\" data-aria-level=\"1\"><span data-contrast=\"auto\">Aisance pour les explications, interactions entre les personnes de la pr\u00e9sentation. <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"7\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"4\" data-aria-level=\"1\"><span data-contrast=\"auto\">Humour, style, originalit\u00e9. <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"7\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"5\" data-aria-level=\"1\"><span data-contrast=\"auto\">R\u00e9tablissement fluide apr\u00e8s un probl\u00e8me impr\u00e9vu.<\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"7\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"6\" data-aria-level=\"1\"><span data-contrast=\"auto\">Qualit\u00e9 et efficacit\u00e9 du mat\u00e9riel visuel et \u00e9crit. <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<p><b><span data-contrast=\"auto\">Remarque<\/span><\/b><span data-ccp-props=\"{}\"> <\/span><\/p>\n<p><span data-contrast=\"auto\">Lorsque les projets ont \u00e9t\u00e9 r\u00e9alis\u00e9s par une \u00e9quipe sur une p\u00e9riode d\u00e9termin\u00e9e, la pr\u00e9sentatrice doit clairement pr\u00e9senter les contributions de chacun, y compris ses contributions personnelles.<\/span><span data-ccp-props=\"{}\"> <\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2263\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2263\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Prix d\u2019excellence en mati\u00e8re de fabrication de microsyst\u00e8mes<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2263\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2263\"><h5 aria-level=\"2\"><span data-contrast=\"none\">Aper\u00e7u<\/span><span data-ccp-props=\"{\"134245418\":true,\"134245529\":true,\"335559738\":160,\"335559739\":80}\"> <\/span><\/h5>\n<p><span data-contrast=\"auto\">Le prix d&rsquo;excellence en fabrication de microsyst\u00e8mes r\u00e9compense des travaux de recherche exceptionnels impliquant des travaux pratiques men\u00e9s dans un ou plusieurs laboratoires de fabrication d&rsquo;un \u00e9tablissement d&rsquo;enseignement sup\u00e9rieur au Canada, ou des dispositifs fabriqu\u00e9s \u00e0 l&rsquo;aide de services de fonderie commerciaux par l&rsquo;interm\u00e9diaire du CMC. Le candidat retenu aura fait preuve d&rsquo;un travail de grande qualit\u00e9 dans l&rsquo;utilisation des techniques de micro- et nanofabrication, notamment en mati\u00e8re de conception de sch\u00e9mas, de tests, de conditionnement et d&rsquo;assemblage. <\/span><span data-ccp-props=\"{}\"> <\/span><\/p>\n<p><span data-contrast=\"auto\">La priorit\u00e9 sera accord\u00e9e aux technologies \u00e9mergentes dans les cat\u00e9gories suivantes : <\/span><span data-ccp-props=\"{}\"> <\/span><\/p>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"8\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><b><span data-contrast=\"auto\">MEMS<\/span><\/b> : <span data-contrast=\"auto\">MEMS capacitifs, MEMS pi\u00e9zo\u00e9lectriques, MEMS magn\u00e9tiques, MEMS optiques, MEMS microfluidiques, bio-MEMS, etc.<\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"8\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"2\" data-aria-level=\"1\"><b><span data-contrast=\"auto\">Micro\u00e9lectronique <\/span><\/b>: <span data-contrast=\"auto\">utilisation de substrats(planar CMOS, SiGe, BiCMOS, SOI, FinFET, GaN, InPh, InAlN, SiC, SiGe, substrats flexibles, etc.); post-traitement des tranches personnalis\u00e9es \/ commerciales pour de nouvelles applications; int\u00e9gration h\u00e9t\u00e9rog\u00e8ne de mat\u00e9riaux\/substrats; \u00e9lectronique imprim\u00e9e; transistors \u00e0 couches minces; cr\u00e9ation de nouvelles nanostructures, mat\u00e9riaux 2D, etc.<\/span> <span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"8\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"3\" data-aria-level=\"1\"><b><span data-contrast=\"auto\">Photonique <\/span><\/b>: <span data-contrast=\"auto\">circuits d\u2019ondes lumineuses planaires (PLC) faits \u00e0 partir de Si, de SiN ou d\u2019autres mat\u00e9riaux, dispositifs \u00e0 puits quantique multiple III-V, dispositifs exploitant la fibre, dispositifs \u00e0 couches minces, photonique au silicium, etc.<\/span> <span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"8\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"4\" data-aria-level=\"1\"><b><span data-contrast=\"auto\">Informatique quantique<\/span><\/b> : <span data-contrast=\"auto\">dispositifs supraconducteurs, points quantiques, graph\u00e8nes, capteurs quantiques, dispositifs de communication quantique, dispositifs nanom\u00e9caniques, etc.<\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<p><span data-contrast=\"auto\">Ce prix est ouvert aux \u00e9tudiants de troisi\u00e8me cycle d&rsquo;une universit\u00e9 canadienne. Les laur\u00e9ats sont vivement encourag\u00e9s \u00e0 utiliser les fonds du prix pour financer des \u00e9tudes ou une formation li\u00e9es \u00e0 la recherche et au d\u00e9veloppement dans le domaine des micro-nanosyst\u00e8mes.  Les fonds du prix peuvent servir \u00e0 couvrir les frais li\u00e9s \u00e0 la participation \u00e0 une conf\u00e9rence ou \u00e0 un atelier, ou \u00e0 la visite d&rsquo;un laboratoire ou d&rsquo;un autre \u00e9tablissement technique, au Canada ou \u00e0 l&rsquo;\u00e9tranger. <\/span><span data-ccp-props=\"{}\"> <\/span><\/p>\n<p><span data-ccp-props=\"{}\"> <\/span><\/p>\n<h5 aria-level=\"2\"><span data-contrast=\"none\">Crit\u00e8res d\u2019\u00e9valuation<\/span><span data-ccp-props=\"{\"134245418\":true,\"134245529\":true,\"335559738\":160,\"335559739\":80}\"> <\/span><\/h5>\n<p><span data-contrast=\"auto\">Le jury sera compos\u00e9 de trois repr\u00e9sentants issus du monde des affaires, du milieu universitaire et d&rsquo;organisations \u00e0 but non lucratif au Canada. The judges assess each competitor and select the demonstration that best meets the following criteria: <\/span><span data-ccp-props=\"{}\"> <\/span><\/p>\n<p><span data-ccp-props=\"{}\"> <\/span><\/p>\n<p><b><span data-contrast=\"auto\">Crit\u00e8re 1 : Excellence technique (20 points)<\/span><\/b><span data-ccp-props=\"{}\"> <\/span><\/p>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"9\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">R\u00e9ussite technique avec des r\u00e9sultats d\u2019un dispositif fonctionnel.<\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"9\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"2\" data-aria-level=\"1\"><span data-contrast=\"auto\">Originalit\u00e9 d\u00e9montr\u00e9e ou innovation sur la mani\u00e8re d\u2019aborder le probl\u00e8me.<\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"9\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"3\" data-aria-level=\"1\"><span data-contrast=\"auto\">Approche rigoureuse concernant la conception des processus et la compr\u00e9hension de l\u2019int\u00e9gration de ceux-ci. Les pratiques peuvent inclure, sans s\u2019y limiter, la conception des exp\u00e9riences, la simulation des processus et le suivi de tranche. <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"9\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"4\" data-aria-level=\"1\"><span data-contrast=\"auto\">Compr\u00e9hension du r\u00f4le associ\u00e9 \u00e0 l\u2019aptitude \u00e0 la fabrication, comme la conception en vue des essais, la conception pour la fabricabilit\u00e9, la m\u00e9trologie, les analyses de rendement et les v\u00e9rifications de proc\u00e9d\u00e9.<\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"9\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"5\" data-aria-level=\"1\"><span data-contrast=\"auto\">Consid\u00e9ration ad\u00e9quate du r\u00f4le de la mise en bo\u00eetier et de l\u2019int\u00e9gration des composants fabriqu\u00e9s, ainsi que de l\u2019int\u00e9gration des proc\u00e9d\u00e9s avec ces composants.<\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"9\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"6\" data-aria-level=\"1\"><span data-contrast=\"auto\">Utilisation efficace des capacit\u00e9s des laboratoires, prise en compte des ensembles d\u2019outils de plusieurs laboratoires ou des prestataires de services, ou exploitation d\u2019une combinaison de fabrication concr\u00e8te et de services de laboratoire. Objectifs de recherche men\u00e9s avec une fabrication personnalis\u00e9e, avec des r\u00e9sultats qui n\u2019auraient pas pu \u00eatre obtenus autrement. <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<p><b><span data-contrast=\"auto\">Crit\u00e8re 2 : Contribution et pertinence dans le domaine de recherche (20 points)<\/span><\/b><span data-ccp-props=\"{}\"> <\/span><\/p>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"10\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">La technologie a men\u00e9 \u00e0 de nouvelles d\u00e9couvertes scientifiques ou \u00e0 des am\u00e9liorations ayant trait \u00e0 l\u2019aptitude \u00e0 la fabrication, au rendement, \u00e0 la performance ou \u00e0 l\u2019efficacit\u00e9 de co\u00fbts, comparativement aux avanc\u00e9es actuelles.<\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"10\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"2\" data-aria-level=\"1\"><span data-contrast=\"auto\">La documentation de la conception ou des processus de fabrication facilite la r\u00e9tention et le transfert des connaissances.<\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"10\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"3\" data-aria-level=\"1\"><span data-contrast=\"auto\">Si vous utilisez un laboratoire dans un \u00e9tablissement d\u2019enseignement, les utilisateurs en laboratoire travaillent efficacement avec le personnel du laboratoire afin d\u2019optimiser la recherche et les possibilit\u00e9s de r\u00e9ussite.<\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"10\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"4\" data-aria-level=\"1\"><span data-contrast=\"auto\">En cas d\u2019utilisation d\u2019une fonderie commerciale, la technologie \/ application pr\u00e9sente un potentiel commercial pouvant mener \u00e0 des am\u00e9liorations dans la soci\u00e9t\u00e9. La collaboration de l\u2019industrie dans les travaux est envisag\u00e9e de mani\u00e8re favorable. <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<p><b><span data-contrast=\"auto\">Crit\u00e8re 3 : Excellence de la pr\u00e9sentation et des moyens visuels utilis\u00e9s (10 points)<\/span><\/b><span data-ccp-props=\"{}\"> <\/span><\/p>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"11\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">Explication des informations contextuelles ou de la th\u00e9orie pour les pairs. <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"11\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"2\" data-aria-level=\"1\"><span data-contrast=\"auto\">Clart\u00e9 de l\u2019explication des points techniques. <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"11\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"3\" data-aria-level=\"1\"><span data-contrast=\"auto\">Aisance pour les explications, interactions entre les personnes de la pr\u00e9sentation. <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"11\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"4\" data-aria-level=\"1\"><span data-contrast=\"auto\">Humour, style, originalit\u00e9. <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"11\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"5\" data-aria-level=\"1\"><span data-contrast=\"auto\">R\u00e9cup\u00e9ration d\u2019un probl\u00e8me inattendu. <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"11\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"6\" data-aria-level=\"1\"><span data-contrast=\"auto\">Qualit\u00e9 et efficacit\u00e9 du mat\u00e9riel visuel et \u00e9crit. <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<p><b><span data-contrast=\"auto\">Remarque<\/span><\/b><span data-ccp-props=\"{}\"> <\/span><\/p>\n<p><span data-contrast=\"auto\">Lors de la pr\u00e9sentation d\u2019un projet collaboratif, le pr\u00e9sentateur doit pr\u00e9senter clairement ses contributions personnelles.<\/span><span data-ccp-props=\"{}\"> <\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2264\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2264\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Prix d'excellence en algorithmes ou en informatique quantique <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2264\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2264\"><h5 aria-level=\"2\"><span data-contrast=\"none\">Aper\u00e7u<\/span><span data-ccp-props=\"{\"134245418\":true,\"134245529\":true,\"335559738\":160,\"335559739\":80}\"> <\/span><\/h5>\n<p><span data-contrast=\"auto\">Ce prix r\u00e9compense des travaux de recherche et de d\u00e9veloppement exceptionnels dans le domaine des algorithmes ou de l&rsquo;informatique quantique, au sens large.<br \/>Ce prix sera d\u00e9cern\u00e9 \u00e0 un candidat qui, par le biais d\u2019un projet unique ou d\u2019un ensemble de travaux, a apport\u00e9 des contributions significatives aux algorithmes ou \u00e0 l\u2019informatique quantique.<br \/>Ces contributions doivent \u00eatre librement accessibles \u00e0 la communaut\u00e9, par exemple sous forme de publications \u00e9valu\u00e9es par des pairs, de pr\u00e9publications ou de d\u00e9p\u00f4ts de code.<br \/>Les sujets concern\u00e9s incluent, sans s\u2019y limiter :   <\/span><span data-ccp-props=\"{}\"> <\/span><\/p>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"12\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">D\u00e9veloppement d\u2019algorithmes quantiques \u00e0 court terme pour des applications sp\u00e9cifiques.<\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"12\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"2\" data-aria-level=\"1\"><span data-contrast=\"auto\">D\u00e9couverte de nouveaux codes de correction d\u2019erreurs quantiques ou am\u00e9lioration de codes existants ou d\u2019op\u00e9rations tol\u00e9rantes aux fautes.<\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"12\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"3\" data-aria-level=\"1\"><span data-contrast=\"auto\">Recherche sur les algorithmes quantiques tol\u00e9rants aux fautes, la th\u00e9orie de la complexit\u00e9 quantique ou les estimations de ressources pour les algorithmes quantiques.<\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"12\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"4\" data-aria-level=\"1\"><span data-contrast=\"auto\">Conception de protocoles d\u2019information quantique applicables \u00e0 l\u2019informatique quantique, par exemple la caract\u00e9risation, l\u2019\u00e9valuation comparative, la distribution d\u2019intrication ou la mise en r\u00e9seau.<\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"12\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"5\" data-aria-level=\"1\"><span data-contrast=\"auto\">D\u00e9monstration exp\u00e9rimentale d\u2019algorithmes quantiques ou de protocoles d\u2019information quantique.<\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<p><span data-contrast=\"auto\">Ce prix est ouvert aux \u00e9tudiants de troisi\u00e8me cycle inscrits dans une universit\u00e9 canadienne. Les laur\u00e9ats sont vivement encourag\u00e9s \u00e0 utiliser les fonds du prix pour financer des \u00e9tudes ou une formation dans le domaine des algorithmes quantiques ou de l&rsquo;informatique quantique.  Par exemple, la bourse peut servir \u00e0 couvrir les frais li\u00e9s \u00e0 la participation \u00e0 une conf\u00e9rence ou \u00e0 un atelier, ou \u00e0 la visite d&rsquo;un laboratoire ou d&rsquo;un autre \u00e9tablissement technique, au Canada ou \u00e0 l&rsquo;\u00e9tranger. <\/span><span data-ccp-props=\"{}\"> <\/span><\/p>\n<h5 aria-level=\"2\"><span data-contrast=\"none\">Crit\u00e8res d\u2019\u00e9valuation<\/span><span data-ccp-props=\"{\"134245418\":true,\"134245529\":true,\"335559738\":160,\"335559739\":80}\"> <\/span><\/h5>\n<p><span data-contrast=\"auto\">Le jury sera compos\u00e9 de trois repr\u00e9sentants issus du monde des affaires, du milieu universitaire et d&rsquo;organisations \u00e0 but non lucratif au Canada. The judges assess each competitor and select the applicant that best meets the following criteria: <\/span><span data-ccp-props=\"{}\"> <\/span><\/p>\n<p><b><span data-contrast=\"auto\">Crit\u00e8re 1 : Excellence technique (20 points)<\/span><\/b><span data-ccp-props=\"{}\"> <\/span><\/p>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"5\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"6\" data-aria-level=\"1\"><span data-contrast=\"auto\">Exactitude de l\u2019algorithme quantique, du protocole ou de la mise en \u0153uvre exp\u00e9rimentale.<\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"5\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"7\" data-aria-level=\"1\"><span data-contrast=\"auto\">Caract\u00e8re novateur de l\u2019id\u00e9e et des techniques d\u00e9velopp\u00e9es. Les id\u00e9es et techniques peuvent-elles \u00eatre r\u00e9utilis\u00e9es ailleurs ? <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"5\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"8\" data-aria-level=\"1\"><span data-contrast=\"auto\">Profondeur et complexit\u00e9 de l\u2019id\u00e9e ou de la d\u00e9monstration. De nombreux d\u00e9fis techniques ont-ils \u00e9t\u00e9 surmont\u00e9s ? <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"5\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"9\" data-aria-level=\"1\"><span data-contrast=\"auto\">Ma\u00eetrise par l\u2019exposant des aspects techniques du projet et des questions ouvertes restantes. <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<p><b><span data-contrast=\"auto\">Crit\u00e8re 2 : Contribution et pertinence dans le domaine de recherche (20 points)<\/span><\/b><span data-ccp-props=\"{}\"> <\/span><\/p>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"6\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"6\" data-aria-level=\"1\"><span data-contrast=\"auto\">Importance du d\u00e9veloppement dans son sous-domaine sp\u00e9cifique des algorithmes ou de l\u2019informatique quantique. L\u2019id\u00e9e r\u00e9sout-elle un probl\u00e8me majeur ou ouvre-t-elle une nouvelle voie de recherche <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"6\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"7\" data-aria-level=\"1\"><span data-contrast=\"auto\">Port\u00e9e de l\u2019impact dans le domaine des algorithmes et de l\u2019informatique quantique. Plusieurs axes de recherche seront-ils influenc\u00e9s, et l\u2019id\u00e9e ou la d\u00e9monstration pr\u00e9sente-t-elle un int\u00e9r\u00eat g\u00e9n\u00e9ral ? <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"6\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"8\" data-aria-level=\"1\"><span data-contrast=\"auto\">Explication du contexte de l\u2019id\u00e9e ou de la d\u00e9monstration. Les travaux ant\u00e9rieurs ont-ils \u00e9t\u00e9 correctement reconnus ? <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"6\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"9\" data-aria-level=\"1\"><span data-contrast=\"auto\">Compr\u00e9hension claire de l\u2019importance de ce projet, c\u2019est-\u00e0-dire : pourquoi cette recherche ou ce d\u00e9veloppement est-il important ?<\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<p><b><span data-contrast=\"auto\">Crit\u00e8re 3 : Excellence de la pr\u00e9sentation et des moyens visuels utilis\u00e9s (10 points)<\/span><\/b><span data-ccp-props=\"{}\"> <\/span><\/p>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"7\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"7\" data-aria-level=\"1\"><span data-contrast=\"auto\">Explication du contexte et de l\u2019importance de l\u2019id\u00e9e ou du d\u00e9veloppement. <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"7\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"8\" data-aria-level=\"1\"><span data-contrast=\"auto\">Clart\u00e9 de l\u2019explication des points techniques cl\u00e9s.<\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"7\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"9\" data-aria-level=\"1\"><span data-contrast=\"auto\">Aisance pour les explications, interactions entre les personnes de la pr\u00e9sentation. <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"7\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"10\" data-aria-level=\"1\"><span data-contrast=\"auto\">R\u00e9tablissement fluide apr\u00e8s un probl\u00e8me impr\u00e9vu.<\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"7\" data-list-defn-props=\"{\"335552541\":1,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"11\" data-aria-level=\"1\"><span data-contrast=\"auto\">Qualit\u00e9 et efficacit\u00e9 du mat\u00e9riel visuel et \u00e9crit. <\/span><span data-ccp-props=\"{}\"> <\/span><\/li>\n<\/ul>\n<p><b><span data-contrast=\"auto\">Remarque<\/span><\/b><span data-ccp-props=\"{}\"> <\/span><\/p>\n<p><span data-contrast=\"auto\">Lorsque les projets ont \u00e9t\u00e9 r\u00e9alis\u00e9s en \u00e9quipe et\/ou sur une p\u00e9riode prolong\u00e9e, le pr\u00e9sentateur doit clairement distinguer la contribution actuelle et pr\u00e9ciser les contributions individuelles.<\/span><span data-ccp-props=\"{}\"> <\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2265\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-2265\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Prix Brian L. Barge pour l\u2019excellence d\u2019int\u00e9gration des microsyst\u00e8mes<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2265\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-2265\"><h5>Aper\u00e7u<\/h5>\n<p>Ce Prix vise \u00e0 reconna\u00eetre une recherche exemplaire utilisant les technologies des microsyst\u00e8mes et des nanosyst\u00e8mes dans un environnement collaboratif et multidisciplinaire ou exploitant plusieurs technologies. Le projet de recherche doit \u00eatre \u00e0 la fois novateur et pertinent pour l\u2019industrie au Canada. Id\u00e9alement, les travaux devraient \u00eatre attest\u00e9s par un collaborateur de l\u2019industrie. Le Prix sera attribu\u00e9 au concurrent qui pr\u00e9sente le projet de recherche le plus pertinent traitant sp\u00e9cifiquement une int\u00e9gration h\u00e9t\u00e9rog\u00e8ne. Exemples :   <\/p>\n<ul>\n<li>Projet int\u00e9grant des circuits int\u00e9gr\u00e9s micro\u00e9lectroniques fabriqu\u00e9s au moyen de diff\u00e9rents n\u0153uds technologiques CMOS (par exemple, proc\u00e9d\u00e9 130 nm et 12 nm) ou des circuits int\u00e9gr\u00e9s de diff\u00e9rents domaines de la technologie des microsyst\u00e8mes (par exemple, micro\u00e9lectronique et photonique, que ce soit dans un environnement monolithique ou h\u00e9t\u00e9rog\u00e8ne).<\/li>\n<li>Projet int\u00e9grant des composants mat\u00e9riels et logiciels exploitant de nouvelles techniques ou architectures. Architectures pouvant combiner des \u00e9l\u00e9ments de traitement ou des acc\u00e9l\u00e9rateurs h\u00e9t\u00e9rog\u00e8nes. Par exemple : matrice FPGA, ASIP, processeur graphique. Les composants logiciels peuvent inclure des pilotes, des piles logicielles ou du code d\u2019application. Les projets peuvent impliquer des dispositifs embarqu\u00e9s ou en p\u00e9riph\u00e9rie de r\u00e9seau \u00e0 partir d\u2019installations en nuage.   <\/li>\n<li>Projet de microsyst\u00e8me men\u00e9 par plusieurs chercheurs provenant de disciplines diff\u00e9rentes. Par exemple, g\u00e9nie \u00e9lectrique \/ \u00e9lectronique, g\u00e9nie m\u00e9canique et biochimie.<\/li>\n<\/ul>\n<p>Les candidatures doivent pr\u00e9senter des d\u00e9monstrations fonctionnelles de prototypes avec une application de plusieurs technologies ou de plusieurs disciplines au sein d\u2019une int\u00e9gration de microsyst\u00e8mes.<\/p>\n<p>Le prix est destin\u00e9 aux \u00e9tudiants aux cycles sup\u00e9rieurs des universit\u00e9s canadiennes.<\/p>\n<p>Les laur\u00e9ats sont fortement encourag\u00e9s \u00e0 utiliser la r\u00e9compense en argent associ\u00e9e au prix afin de favoriser le transfert de connaissance ou la formation associ\u00e9s \u00e0 la R-D appliqu\u00e9e aux microsyst\u00e8mes et aux nanosyst\u00e8mes. Par exemple, pour les co\u00fbts d\u2019une conf\u00e9rence ou d\u2019un atelier ou encore pour visiter un laboratoire ou une autre installation technique au Canada ou dans un autre pays.<\/p>\n<h5>Crit\u00e8res d\u2019\u00e9valuation<\/h5>\n<p>Le jury sera constitu\u00e9 de trois repr\u00e9sentants du secteur universitaire, des organisations sans but lucratif et de l\u2019industrie au Canada. Les juges \u00e9valueront chaque concurrent et s\u00e9lectionneront le projet qui r\u00e9pond le mieux aux crit\u00e8res suivants : <\/p>\n<p><strong>Crit\u00e8re 1 : Int\u00e9gration de microsyst\u00e8mes (15 points)<\/strong><\/p>\n<ul>\n<li>Est-ce qu\u2019il y a une valeur apport\u00e9e par l\u2019int\u00e9gration de plusieurs technologies de microsyst\u00e8mes ?<\/li>\n<li>Est-ce qu\u2019il y a une int\u00e9gration multidisciplinaire manifeste dans le projet de microsyst\u00e8me ?<\/li>\n<li>Quelle est l\u2019innovation de concept du projet de microsyst\u00e8mes et est-ce que celle-ci est associ\u00e9e \u00e0 une recherche impliquant plusieurs technologies ou des chercheurs de plusieurs disciplines ?<\/li>\n<li>Est-ce que les composants int\u00e9gr\u00e9s ont \u00e9t\u00e9 produits par des fournisseurs au Canada ?<\/li>\n<\/ul>\n<p><strong>Crit\u00e8re 2 : Excellence technique (15 points)<\/strong><\/p>\n<ul>\n<li>R\u00e9ussite dans la d\u00e9monstration de la technologie. Est-ce que la technique fonctionne ou est utile ? <\/li>\n<li>Originalit\u00e9 de conception et technique novatrice.<\/li>\n<li>Degr\u00e9 d\u2019excellence pour l\u2019exploitation des fonctionnalit\u00e9s des technologies des composants ou l\u2019int\u00e9gration des fonctionnalit\u00e9s des composants.<\/li>\n<li>Niveau de difficult\u00e9 vis\u00e9; cr\u00e9ativit\u00e9 \/ pers\u00e9v\u00e9rance pour r\u00e9soudre les probl\u00e8mes durant le d\u00e9veloppement.<\/li>\n<li>Ma\u00eetrise des aspects techniques du projet par l\u2019exposant.<\/li>\n<li>Degr\u00e9 de pertinence du projet, selon la perspective des applications de microsyst\u00e8me.<\/li>\n<li>Solide compr\u00e9hension de l\u2019importance du sujet. Par exemple, la raison pour laquelle une solution au probl\u00e8me est importante.<\/li>\n<\/ul>\n<p><strong>Crit\u00e8re 3 : Application \u00e0 l\u2019industrie (10 points)<\/strong><\/p>\n<ul>\n<li>Y a-t-il eu un collaborateur industriel ? Quelle est la valeur ajout\u00e9e pour le collaborateur industriel ? S&rsquo;agit-il d&rsquo;une solution significative ou progressive ? Comment se situe-t-il par rapport aux solutions existantes ?<\/li>\n<li>Quelle est la nature des interactions ou de la participation entre l\u2019entreprise et le chercheur (par exemple, travail sur place ou r\u00e9vision de conception) ? Quelle a \u00e9t\u00e9 l\u2019ampleur de l\u2019investissement du collaborateur de l\u2019industrie (par exemple, temps, formation des \u00e9tudiants, embauche) ? <\/li>\n<li>Est-ce qu\u2019il existe une infrastructure pour une mise \u00e0 l\u2019\u00e9chelle commerciale ?<\/li>\n<li>Quel sera l\u2019impact ou quelles seraient les am\u00e9liorations potentielles de la solution sur la fabrication ou l\u2019application de microsyst\u00e8mes et de nanosyst\u00e8mes au Canada ? (Par exemple, co\u00fbt, fiabilit\u00e9, acc\u00e9l\u00e9ration de mise en march\u00e9). <\/li>\n<li>Est-ce que les interactions avec les autres mat\u00e9riaux et composants et avec l\u2019environnement ont \u00e9t\u00e9 prises en consid\u00e9ration ?<\/li>\n<li>Quel est le niveau de convivialit\u00e9 pour l\u2019utilisateur (comparativement au d\u00e9veloppeur)?<\/li>\n<\/ul>\n<p><strong>Crit\u00e8re 4 : Excellence de la pr\u00e9sentation et des moyens visuels utilis\u00e9s (10 points)<\/strong><\/p>\n<ul>\n<li>Explication des informations contextuelles ou de la th\u00e9orie pour les pairs.<\/li>\n<li>Clart\u00e9 de l\u2019explication des points techniques cl\u00e9s.<\/li>\n<li>Aisance pour les explications, interactions entre les personnes de la pr\u00e9sentation.<\/li>\n<li>Humour, style, originalit\u00e9.<\/li>\n<li>R\u00e9tablissement fluide apr\u00e8s un probl\u00e8me impr\u00e9vu.<\/li>\n<li>Qualit\u00e9 et efficacit\u00e9 du mat\u00e9riel visuel et \u00e9crit.<\/li>\n<\/ul>\n<p><strong>Remarque<\/strong> <br \/>Lorsque les projets ont \u00e9t\u00e9 r\u00e9alis\u00e9s par une \u00e9quipe sur une p\u00e9riode d\u00e9termin\u00e9e, le pr\u00e9sentateur doit clairement pr\u00e9senter les contributions de chacun, y compris ses contributions personnelles.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f052a70 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f052a70\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9351e2f\" data-id=\"9351e2f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-01178df elementor-widget elementor-widget-spacer\" data-id=\"01178df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Symposium canadien sur les semi-conducteurs 2026 TEXPO2026 TEXPO2026 Sponsor principal Le concours de recherche pour \u00e9tudiants dipl\u00f4m\u00e9s TEXPO 2026 est un \u00e9v\u00e9nement annuel qui offre aux \u00e9tudiants aux cycles sup\u00e9rieurs [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-4330","page","type-page","status-publish","hentry"],"acf":[],"featured_image_src":null,"featured_image_src_square":null,"_links":{"self":[{"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/pages\/4330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/comments?post=4330"}],"version-history":[{"count":0,"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/pages\/4330\/revisions"}],"wp:attachment":[{"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/media?parent=4330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":4236,"date":"2026-02-09T17:16:26","date_gmt":"2026-02-09T22:16:26","guid":{"rendered":"https:\/\/fabricinnovation.ca\/defence\/"},"modified":"2026-03-04T09:25:35","modified_gmt":"2026-03-04T14:25:35","slug":"defence","status":"publish","type":"page","link":"https:\/\/fabricinnovation.ca\/fr\/defence\/","title":{"rendered":"D\u00e9fense"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4236\" class=\"elementor elementor-4236 elementor-4221\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bfa8c68 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bfa8c68\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-88b40c9\" data-id=\"88b40c9\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2996623 elementor-widget elementor-widget-spacer\" data-id=\"2996623\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c68aaac\" data-id=\"c68aaac\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef01de0 elementor-widget elementor-widget-spacer\" data-id=\"ef01de0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2ddf220\" data-id=\"2ddf220\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;background_motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b7ec17 elementor-widget__width-initial elementor-widget elementor-widget-spacer\" data-id=\"7b7ec17\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7809859 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7809859\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bb936d0\" data-id=\"bb936d0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-18a813b elementor-widget elementor-widget-heading\" data-id=\"18a813b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><b>D\u00e9fense.<\/b><br>La puissante combinaison des applications de d\u00e9fense et civiles<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-01d2b71 elementor-widget elementor-widget-spacer\" data-id=\"01d2b71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e3d5b8b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e3d5b8b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-bb75235\" data-id=\"bb75235\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48c6de7 elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"48c6de7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"428\" height=\"2560\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/02\/defence-column.jpg\" class=\"attachment-full size-full wp-image-4234\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c961c29\" data-id=\"c961c29\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d36d9a6 elementor-widget elementor-widget-heading\" data-id=\"d36d9a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">D\u00e9fense<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3086eea elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3086eea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a61d7b9 elementor-widget elementor-widget-text-editor\" data-id=\"a61d7b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les technologies d\u00e9velopp\u00e9es pour des applications de d\u00e9fense ont historiquement stimul\u00e9 un puissant avantage industriel et g\u00e9n\u00e9r\u00e9 de larges retomb\u00e9es pour la soci\u00e9t\u00e9. Des dispositifs m\u00e9dicaux implantables comme les stimulateurs cardiaques aux drones agricoles, en passant par les puces s\u00e9curis\u00e9es essentielles aux voitures autonomes, la cascade d\u2019impacts positifs sur la vie quotidienne est immense. <\/p><p>Les plateformes de d\u00e9fense modernes reposent fortement sur les semi\u2011conducteurs, ainsi que sur les technologies qu\u2019ils rendent possibles, notamment l\u2019intelligence artificielle (IA), l\u2019apprentissage automatique, l\u2019infonuage et le quantique. Assurer un approvisionnement en semi\u2011conducteurs de haute qualit\u00e9 et un \u00e9cosyst\u00e8me national robuste pour la conception et le d\u00e9veloppement de semi\u2011conducteurs est essentiel \u00e0 la souverainet\u00e9 du Canada et \u00e0 sa capacit\u00e9 de respecter ses engagements multinationaux en mati\u00e8re de d\u00e9fense, y compris au sein de l\u2019OTAN et du NORAD. <\/p><p>Les technologies \u00e0 double usage comprennent des innovations, des mat\u00e9riaux ou des syst\u00e8mes qui ont \u00e9t\u00e9 d\u00e9velopp\u00e9s soit pour des domaines militaires, soit pour des domaines civils, mais qui peuvent \u00eatre utilis\u00e9s dans les deux. Les exigences extr\u00eames des applications militaires et de s\u00e9curit\u00e9 \u2014 notamment en mati\u00e8re de robustesse et de fiabilit\u00e9 \u2014 en font des solutions id\u00e9ales pour des applications commerciales et soci\u00e9tales. Les semi\u2011conducteurs d\u00e9velopp\u00e9s pour les avions militaires sont souvent int\u00e9gr\u00e9s dans les avions commerciaux, les satellites ou m\u00eame les v\u00e9hicules automobiles, car ils am\u00e9liorent consid\u00e9rablement la s\u00e9curit\u00e9 et la durabilit\u00e9.  <\/p><p>Les technologies de semi\u2011conducteurs d\u00e9velopp\u00e9es pour des applications de d\u00e9fense et ayant un double usage se retrouvent dans un large \u00e9ventail d\u2019industries commerciales.<\/p><ul style=\"list-style-type: square;\"><li>Exploitation mini\u00e8re : Des processeurs s\u00e9curis\u00e9s et durcis contre les radiations, con\u00e7us pour soutenir l\u2019autonomie militaire gr\u00e2ce \u00e0 la fusion de capteurs en temps r\u00e9el pour la d\u00e9tection des dangers, peuvent \u00eatre r\u00e9utilis\u00e9s pour la maintenance pr\u00e9dictive sur les sites miniers.<br><br><\/li><li><strong>Agriculture<\/strong> : Les drones agricoles \u00e0 faible co\u00fbt peuvent \u00eatre modifi\u00e9s pour un usage militaire dans des zones de conflit, tandis que la navigation autonome et l\u2019IA d\u00e9velopp\u00e9es pour les drones militaires permettent des op\u00e9rations au\u2011del\u00e0 de la ligne de vis\u00e9e pour des t\u00e2ches commerciales, r\u00e9duisant ainsi les risques pour les humains. Les r\u00e9seaux IdO et les r\u00e9seaux de capteurs de pr\u00e9cision initialement cr\u00e9\u00e9s pour la gestion des exploitations agricoles sont utilis\u00e9s dans la logistique sur le champ de bataille et les syst\u00e8mes de connaissance de la situation. <br><br><\/li><li><strong>A\u00e9rospatiale<\/strong> : Les syst\u00e8mes radar et les r\u00e9seaux phas\u00e9s d\u00e9velopp\u00e9s pour les avions de chasse peuvent se retrouver dans les avions commerciaux. La technologie des semi\u2011conducteurs durcis contre les radiations est utile tant pour les applications militaires au sol que pour les missions spatiales. <br><br><\/li><li>T\u00e9l\u00e9communications : La technologie RF mmWave et le beamforming issus de la recherche en d\u00e9fense permettent des syst\u00e8mes de communication \u00e0 haute capacit\u00e9, directionnels et adaptatifs, y compris pour la 5G\/6G. Les convertisseurs analogique\u2011num\u00e9rique avanc\u00e9s et les processeurs de signaux num\u00e9riques provenant d\u2019applications de d\u00e9fense am\u00e9liorent la qualit\u00e9 du signal et la gestion de la bande passante dans les applications de t\u00e9l\u00e9communications commerciales. <br><br><\/li><li><strong>Automobile<\/strong> : La technologie des semi\u2011conducteurs initialement d\u00e9velopp\u00e9e pour la d\u00e9fense trouve de plus en plus un double usage dans l\u2019industrie automobile, qui exige des puces plus s\u00e9curis\u00e9es, plus durables et certifi\u00e9es pour la s\u00e9curit\u00e9 des v\u00e9hicules \u00e9lectriques et autonomes.<br><br><\/li><li><strong>Maritime<\/strong> : Les v\u00e9hicules sous\u2011marins sans \u00e9quipage (UUV) et la robotique sous\u2011marine con\u00e7us \u00e0 des fins de s\u00e9curit\u00e9 peuvent \u00eatre utilis\u00e9s pour l\u2019inspection des pipelines, la maintenance et les interventions en cas de catastrophe dans l\u2019industrie p\u00e9troli\u00e8re et gazi\u00e8re, tandis que les capteurs et les syst\u00e8mes sans \u00e9quipage d\u00e9velopp\u00e9s pour la recherche sur la biodiversit\u00e9 marine, la pollution et la gestion des \u00e9cosyst\u00e8mes peuvent \u00eatre employ\u00e9s pour des missions de d\u00e9fense en mer.<br><br><\/li><li><strong>M\u00e9dical<\/strong> : Les puces de qualit\u00e9 militaire con\u00e7ues pour le radar et les communications s\u00e9curis\u00e9es ont permis la cr\u00e9ation d\u2019appareils d\u2019imagerie m\u00e9dicale plus abordables et portatifs, tels que les syst\u00e8mes \u00e0 ultrasons. Les puces con\u00e7ues pour la durabilit\u00e9 sur le champ de bataille et l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique sont d\u00e9sormais utilis\u00e9es dans des dispositifs implantables tels que les stimulateurs cardiaques, les pompes \u00e0 insuline et les moniteurs de sant\u00e9 portables. Les processeurs et capteurs s\u00e9curis\u00e9s, initialement d\u00e9velopp\u00e9s pour un \u00e9quipement militaire fiable et inviolable, peuvent \u00eatre r\u00e9utilis\u00e9s pour des applications commerciales o\u00f9 l\u2019int\u00e9grit\u00e9, la s\u00e9curit\u00e9 et la conformit\u00e9 r\u00e9glementaire sont essentielles, notamment dans les secteurs de l\u2019\u00e9nergie, de l\u2019automobile, des soins de sant\u00e9, des services financiers et des infrastructures critiques.  <br><br><\/li><li><strong>Fabrication<\/strong> : Les puces durcies contre les radiations et les bo\u00eetiers avanc\u00e9s con\u00e7us pour des applications de d\u00e9fense dans des environnements extr\u00eames ont \u00e9t\u00e9 int\u00e9gr\u00e9s dans les secteurs de la fabrication, de l\u2019automatisation industrielle et de la robotique. Les architectures System\u2011on\u2011Chip (SoC) et les matrices logiques programmables sur le terrain (FPGA), dot\u00e9es d\u2019une durabilit\u00e9 accrue et d\u2019une meilleure gestion thermique, sont utilis\u00e9es pour les capteurs intelligents, la robotique et l\u2019automatisation des lignes de production dans les environnements manufacturiers modernes, en raison de leur s\u00e9curit\u00e9 et de leur soutien au long cycle de vie. <br><br><\/li><li><strong>\u00c9nergie<\/strong> : Les cellules de batterie b\u00eata\u2011volta\u00efques utilisant des semi\u2011conducteurs photovolta\u00efques pour des capteurs militaires autonomes pourraient potentiellement alimenter des r\u00e9seaux de capteurs industriels sans fil ayant une dur\u00e9e de vie de plusieurs d\u00e9cennies.<br><br><\/li><li><strong>Services d\u2019urgence \/ Pr\u00e9paration<\/strong> : Les deux domaines exigent des infrastructures de communication, d\u2019informatique et de soutien \u00e0 la d\u00e9cision qui demeurent s\u00e9curis\u00e9es, r\u00e9silientes et interop\u00e9rables entre organismes et juridictions, y compris dans des environnements d\u00e9grad\u00e9s ou hostiles. Les services d\u2019urgence et les syst\u00e8mes de d\u00e9fense traitent tous deux des informations sensibles personnelles, op\u00e9rationnelles ou classifi\u00e9es qui doivent \u00eatre prot\u00e9g\u00e9es au moyen d\u2019un chiffrement robuste, d\u2019un contr\u00f4le d\u2019acc\u00e8s strict et d\u2019une surveillance continue. <\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ee2faf2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ee2faf2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1e253a2\" data-id=\"1e253a2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab0c52a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ab0c52a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-267ed49 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"267ed49\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4fdf1d2\" data-id=\"4fdf1d2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-497cbb5 elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"497cbb5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/elementor\/thumbs\/iStock-1147796744-scaled-r6tt0upngr9ekkn8wpkjimg4irfdzennmm76ucrmqg.jpg\" title=\"MEMS\" alt=\"abstract\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a2b9439\" data-id=\"a2b9439\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39c78da elementor-widget elementor-widget-heading\" data-id=\"39c78da\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Les MEMS assurent une pr\u00e9cision militaire fiable <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f99a0ac elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f99a0ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30a215e elementor-widget elementor-widget-text-editor\" data-id=\"30a215e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les syst\u00e8mes micro\u2011\u00e9lectro\u2011m\u00e9caniques (MEMS) int\u00e8grent des \u00e9l\u00e9ments m\u00e9caniques, des capteurs, des actionneurs et de l\u2019\u00e9lectronique sur des puces de silicium afin de permettre des capacit\u00e9s de d\u00e9tection et de contr\u00f4le compactes et robustes dans des environnements difficiles, ce qui est b\u00e9n\u00e9fique pour les syst\u00e8mes de d\u00e9fense.<\/p><p>Les MEMS am\u00e9liorent la pr\u00e9cision et la fiabilit\u00e9 des op\u00e9rations militaires en constituant des composants \u00e0 faible co\u00fbt et haute performance pour les syst\u00e8mes de navigation, de synchronisation et de communication. Leur petite taille, leur faible poids et leur efficacit\u00e9 \u00e9nerg\u00e9tique sont id\u00e9aux pour l\u2019\u00e9quipement militaire portable et pour r\u00e9duire les charges d\u00e9ploy\u00e9es. <\/p><p>Les MEMS r\u00e9sistent \u00e9galement aux chocs, aux vibrations et aux temp\u00e9ratures extr\u00eames pour soutenir des applications telles que les capteurs inertiels pour les munitions \u00e0 guidage de pr\u00e9cision, les drones et la navigation personnelle dans des environnements brouill\u00e9s. Ils conviennent aussi parfaitement aux oscillateurs de synchronisation pour les communications s\u00e9curis\u00e9es, le traitement du signal et les radios d\u00e9finies par logiciel. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5fb1c77 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5fb1c77\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ceca97b\" data-id=\"ceca97b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a861d7 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2a861d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-39bb531 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"39bb531\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6751345\" data-id=\"6751345\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa8ad50 elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"aa8ad50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/elementor\/thumbs\/iStock-929318450-scaled-r6tt5cdw49dl4bfu0i3gd9zdxce47kj4dvf1c11yx4.jpg\" title=\"Semi-conducteurs\" alt=\"abstract\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-402792d\" data-id=\"402792d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b8066a6 elementor-widget elementor-widget-heading\" data-id=\"b8066a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Les mat\u00e9riaux font toute la diff\u00e9rence en mati\u00e8re de d\u00e9fense <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4133980 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4133980\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d59d0a elementor-widget elementor-widget-text-editor\" data-id=\"3d59d0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les semi\u2011conducteurs compos\u00e9s sont au c\u0153ur de nombreux syst\u00e8mes de d\u00e9fense parmi les plus avanc\u00e9s d\u2019aujourd\u2019hui, car ils permettent des dispositifs radiofr\u00e9quences, de puissance et photoniques plus puissants, plus rapides, plus efficaces et plus compacts que ce que le silicium peut offrir.<\/p><p>Une vari\u00e9t\u00e9 de semi\u2011conducteurs compos\u00e9s combinant diff\u00e9rents mat\u00e9riaux joue un r\u00f4le central dans les radars modernes, la guerre \u00e9lectronique, les communications s\u00e9curis\u00e9es, la d\u00e9tection infrarouge et la conversion de puissance, dans des plateformes allant des missiles et radars aux satellites et aux armes \u00e0 \u00e9nergie dirig\u00e9e.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1016f37 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1016f37\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1a6ff42\" data-id=\"1a6ff42\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c09cd9 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4c09cd9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-72b48ad elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"72b48ad\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f79c270\" data-id=\"f79c270\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-237c240 elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"237c240\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/elementor\/thumbs\/iStock-1073333042-scaled-r6tt3b2hb6omqag1x2hb5fhhwd4p6ib5opi6278ins.jpg\" title=\"Photoniques\" alt=\"abstract\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-41673f8\" data-id=\"41673f8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dc0df3b elementor-widget elementor-widget-heading\" data-id=\"dc0df3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La d\u00e9fense tire parti des technologies de semi\u2011conducteurs bas\u00e9es sur la lumi\u00e8re <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a0f4e0 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9a0f4e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39850bb elementor-widget elementor-widget-text-editor\" data-id=\"39850bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les technologies photoniques jouent un r\u00f4le essentiel dans la d\u00e9fense moderne en permettant une d\u00e9tection de haute pr\u00e9cision, des communications s\u00e9curis\u00e9es et des syst\u00e8mes \u00e0 \u00e9nergie dirig\u00e9e qui renforcent l\u2019efficacit\u00e9 militaire.<\/p><p>Gr\u00e2ce aux cam\u00e9ras infrarouges, au LIDAR et \u00e0 l\u2019imagerie hyperspectrale, la photonique soutient les capacit\u00e9s de renseignement, de surveillance et de reconnaissance. Les fibres optiques assurent un transfert de donn\u00e9es rapide et s\u00e9curis\u00e9, insensible aux interf\u00e9rences \u00e9lectromagn\u00e9tiques \u2014 des caract\u00e9ristiques vitales pour les sous\u2011marins, les drones et les syst\u00e8mes de commandement. <\/p><p>Les syst\u00e8mes bas\u00e9s sur la photonique sont souvent plus rapides, plus efficaces et plus durables que les alternatives \u00e9lectroniques, et ils soutiennent les r\u00e9seaux mondiaux d\u2019information, la stabilit\u00e9 du GPS et les syst\u00e8mes multi\u2011puces utilis\u00e9s dans les applications a\u00e9rospatiales.<\/p><p>Les technologies photoniques d\u00e9velopp\u00e9es pour la d\u00e9fense trouvent fr\u00e9quemment leur place dans les milieux civils et commerciaux. Les secteurs de la sant\u00e9, des infrastructures et des transports en offrent de nombreux exemples. Les principes derri\u00e8re les applications militaires de vision nocturne inspirent l\u2019endoscopie avanc\u00e9e et les cam\u00e9ras m\u00e9dicales \u00e0 faible luminosit\u00e9 pour des interventions minimalement invasives. Les fibres optiques des r\u00e9seaux militaires alimentent l\u2019internet haute vitesse et les infrastructures 5G.   <\/p><p>La photonique permet \u00e9galement les technologies quantiques. L\u2019informatique quantique utilise des photons comme qubits en exploitant les propri\u00e9t\u00e9s de la lumi\u00e8re pour des op\u00e9rations et des interconnexions \u00e0 faible bruit. La photonique aide aussi \u00e0 encoder l\u2019information quantique ; le chiffrement quantique et la d\u00e9tection avanc\u00e9e ont des applications \u00e0 la fois dans la d\u00e9fense et dans le secteur civil.   <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-470061f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"470061f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2b1c676\" data-id=\"2b1c676\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b5f22e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4b5f22e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-78a7ed4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"78a7ed4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-dffbfaa\" data-id=\"dffbfaa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-91f0b63 elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"91f0b63\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/elementor\/thumbs\/iStock-1204583853-scaled-rix2c66d278fire5m1vuyorq36mml7yi5yjk2wa28c.jpg\" title=\"IA\" alt=\"IA\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5b6a87e\" data-id=\"5b6a87e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39c6498 elementor-widget elementor-widget-heading\" data-id=\"39c6498\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Les semi\u2011conducteurs rendent les syst\u00e8mes de d\u00e9fense plus intelligents <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e6ee27 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1e6ee27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17f599d elementor-widget elementor-widget-text-editor\" data-id=\"17f599d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La technologie des semi\u2011conducteurs rend possibles les syst\u00e8mes d\u2019IA pour la d\u00e9fense.<\/p><p>Les semi\u2011conducteurs constituent le mat\u00e9riel fondamental des syst\u00e8mes qui entra\u00eenent de grands mod\u00e8les dans les centres de donn\u00e9es et qui ex\u00e9cutent des moteurs d\u2019inf\u00e9rence compacts et robustes dans les missiles, les drones et les syst\u00e8mes de commandement. Ils alimentent \u00e9galement les plateformes de renseignement, de surveillance et de reconnaissance. <\/p><p>Les semi\u2011conducteurs constituent le mat\u00e9riel fondamental des syst\u00e8mes qui entra\u00eenent de grands mod\u00e8les dans les centres de donn\u00e9es et qui ex\u00e9cutent des moteurs d\u2019inf\u00e9rence compacts et robustes dans les missiles, les drones et les syst\u00e8mes de commandement. Ils alimentent \u00e9galement les plateformes de renseignement, de surveillance et de reconnaissance.<\/p><p>Les syst\u00e8mes de d\u00e9fense int\u00e8grent des semi\u2011conducteurs de m\u00e9moire, de radiofr\u00e9quence et de capteurs dans des modules \u00e9troitement coupl\u00e9s. Cela permet \u00e0 l\u2019IA d\u2019ing\u00e9rer des donn\u00e9es provenant de multiples capteurs, de les fusionner et d\u2019agir en quelques millisecondes pour r\u00e9pondre aux menaces hostiles au sol, dans les airs et sous l\u2019eau.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b542585 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b542585\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-27647c3\" data-id=\"27647c3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d440423 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d440423\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b6a0a18 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b6a0a18\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a82b160\" data-id=\"a82b160\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63669d2 elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"63669d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/elementor\/thumbs\/iStock-594941494-scaled-r6tswynp6g0itn04awffcmyhxkuphy3kesh0gx65pc.jpg\" title=\"Quantique\" alt=\"Quantique\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7abd91c\" data-id=\"7abd91c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-06ee5ae elementor-widget elementor-widget-heading\" data-id=\"06ee5ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La d\u00e9fense franchit un saut quantique <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9fc537b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9fc537b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d929fdd elementor-widget elementor-widget-text-editor\" data-id=\"d929fdd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les technologies quantiques appliqu\u00e9es \u00e0 la d\u00e9fense et \u00e0 la s\u00e9curit\u00e9 couvrent la d\u00e9tection, les communications, l\u2019informatique et la simulation.<\/p><ul style=\"list-style-type: square;\"><li>Les gravim\u00e8tres, magn\u00e9tom\u00e8tres et capteurs inertiels quantiques peuvent d\u00e9tecter de tr\u00e8s faibles variations de gravit\u00e9 ou de champs magn\u00e9tiques, permettant le suivi des sous\u2011marins, la d\u00e9tection de structures souterraines et la navigation ind\u00e9pendante du GPS. <br><br><\/li><li>La distribution quantique de cl\u00e9s et les communications bas\u00e9es sur l\u2019intrication permettent des canaux s\u00e9curis\u00e9s pour les r\u00e9seaux strat\u00e9giques, les satellites et les infrastructures critiques.<br><br><\/li><li>Les simulations \u201cau niveau de la physique\u201d, acc\u00e9l\u00e9r\u00e9es par l\u2019informatique quantique, permettent une mod\u00e9lisation et une analyse d\u00e9taill\u00e9es des mat\u00e9riaux, des armes et des capteurs, soutenant des t\u00e2ches telles que l\u2019\u00e9valuation de nouveaux mat\u00e9riaux, les essais de performance des syst\u00e8mes d\u2019armes et l\u2019optimisation des technologies de capteurs.<br><br><\/li><li>Ces simulations soutiennent \u00e9galement des applications \u201cau niveau d\u00e9cisionnel\u201d pour la planification des op\u00e9rations, la gestion logistique et les sc\u00e9narios d\u2019entra\u00eenement.<\/li><\/ul><p>Les applications d\u00e9velopp\u00e9es pour la d\u00e9fense et ayant des retomb\u00e9es commerciales comprennent la d\u00e9tection quantique, la cryptographie quantique, l\u2019optimisation et la simulation.<\/p><p>Les capteurs quantiques sont d\u00e9j\u00e0 utilis\u00e9s dans des applications de niche mais r\u00e9elles, telles que la navigation ultrapr\u00e9 cise sans GPS, la prospection magn\u00e9tique pour l\u2019exploitation mini\u00e8re et les g\u00e9osciences, l\u2019inspection d\u2019infrastructures souterraines ou sous\u2011marines, ainsi que dans les sciences m\u00e9dicales.<\/p><p>Comme l\u2019informatique quantique repr\u00e9sente une menace pour la cybers\u00e9curit\u00e9 traditionnelle, la cryptographie quantique est d\u00e9velopp\u00e9e pour s\u00e9curiser les donn\u00e9es sensibles dans divers secteurs, dont les finances, la sant\u00e9 et la d\u00e9fense.<\/p><p>Les algorithmes quantiques d\u00e9velopp\u00e9s dans le secteur de la d\u00e9fense peuvent \u00eatre appliqu\u00e9s pour r\u00e9soudre des probl\u00e8mes d\u2019optimisation dans les industries commerciales, notamment pour la logistique des cha\u00eenes d\u2019approvisionnement, la planification de production, la gestion de portefeuilles financiers et les sciences des mat\u00e9riaux.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3569604 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3569604\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7f45256\" data-id=\"7f45256\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-720d2da elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"720d2da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dda00e2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dda00e2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-174745c\" data-id=\"174745c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9983d33 elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"9983d33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/elementor\/thumbs\/iStock-1296302999-scaled-rk0m24bpatzxpktqgq1h2hv7vq5he1md1umxrh47au.jpg\" title=\"Mobile military radar installation on the background of the sunset orange sky\" alt=\"Mobile military radar installation on the background of the sunset orange sky\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0e68a30\" data-id=\"0e68a30\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a76403a elementor-widget elementor-widget-heading\" data-id=\"a76403a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Une double opportunit\u00e9 pour une r\u00e9ussite mondiale <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1cb6c4f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1cb6c4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-135beb4 elementor-widget elementor-widget-text-editor\" data-id=\"135beb4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L\u2019intersection des technologies de d\u00e9fense et des technologies civiles, en particulier dans le domaine des semi\u2011conducteurs et de l\u2019innovation quantique, continue de stimuler des progr\u00e8s transformationnels dans un large \u00e9ventail de secteurs. En favorisant un \u00e9cosyst\u00e8me solide pour les applications \u00e0 double usage, le Canada peut renforcer sa souverainet\u00e9, consolider ses engagements multinationaux et stimuler la croissance \u00e9conomique tout en am\u00e9liorant la qualit\u00e9 de vie de ses citoyens. <\/p><p>Les exemples pr\u00e9sent\u00e9s ci\u2011dessus \u2014 qu\u2019il s\u2019agisse des secteurs de la sant\u00e9, des services d\u2019urgence, de la fabrication, de l\u2019\u00e9nergie ou des t\u00e9l\u00e9communications \u2014 d\u00e9montrent que les investissements r\u00e9alis\u00e9s dans la recherche militaire g\u00e9n\u00e8rent souvent d\u2019importants b\u00e9n\u00e9fices pour les civils. Ces innovations renforcent non seulement la s\u00e9curit\u00e9 et la r\u00e9silience, mais stimulent aussi le leadership technologique et la comp\u00e9titivit\u00e9 du Canada, tant \u00e0 l\u2019\u00e9chelle nationale que mondiale. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8756744 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8756744\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9ebca81\" data-id=\"9ebca81\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7eb1b4c elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7eb1b4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0319d7e elementor-widget elementor-widget-spacer\" data-id=\"0319d7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>D\u00e9fense.La puissante combinaison des applications de d\u00e9fense et civiles D\u00e9fense Les technologies d\u00e9velopp\u00e9es pour des applications de d\u00e9fense ont historiquement stimul\u00e9 un puissant avantage industriel et g\u00e9n\u00e9r\u00e9 de larges retomb\u00e9es [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-4236","page","type-page","status-publish","hentry"],"acf":[],"featured_image_src":null,"featured_image_src_square":null,"_links":{"self":[{"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/pages\/4236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/comments?post=4236"}],"version-history":[{"count":0,"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/pages\/4236\/revisions"}],"wp:attachment":[{"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/media?parent=4236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":4224,"date":"2026-01-29T15:09:06","date_gmt":"2026-01-29T20:09:06","guid":{"rendered":"https:\/\/fabricinnovation.ca\/icebreaker\/"},"modified":"2026-02-09T16:20:05","modified_gmt":"2026-02-09T21:20:05","slug":"icebreaker","status":"publish","type":"page","link":"https:\/\/fabricinnovation.ca\/fr\/icebreaker\/","title":{"rendered":"Semi\u2011conducteurs &#8211; Infrastructure souveraine essentielle"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4224\" class=\"elementor elementor-4224 elementor-4132\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9877c7a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9877c7a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e4b0bf3\" data-id=\"e4b0bf3\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f774651 elementor-widget elementor-widget-spacer\" data-id=\"f774651\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-685894f\" data-id=\"685894f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0bba132 elementor-widget elementor-widget-spacer\" data-id=\"0bba132\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d6d4d56\" data-id=\"d6d4d56\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;background_motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-de7a0c0 elementor-widget__width-initial elementor-widget elementor-widget-spacer\" data-id=\"de7a0c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bd6fb66 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bd6fb66\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-da77ed1\" data-id=\"da77ed1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c5a421 elementor-widget elementor-widget-heading\" data-id=\"6c5a421\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><b>Semi\u2011conducteurs.<\/b><br> \nInfrastructure souveraine essentielle.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6a7cc93 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6a7cc93\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4fd885b\" data-id=\"4fd885b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-99fc273 elementor-widget elementor-widget-spacer\" data-id=\"99fc273\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-924c5dc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"924c5dc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1678cee\" data-id=\"1678cee\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9b1b6a9 elementor-widget elementor-widget-text-editor\" data-id=\"9b1b6a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">La d\u00e9fense d\u00e9pend depuis longtemps des technologies des semi\u2011conducteurs. Leur vaste utilisation dans l\u2019industrie \u2014 a\u00e9rospatiale, transport, \u00e9nergie propre, applications m\u00e9dicales et environnements oc\u00e9aniques hostiles \u2014 a d\u00e9montr\u00e9 leur robustesse dans des syst\u00e8mes critiques o\u00f9 aucune d\u00e9faillance n\u2019est tol\u00e9r\u00e9e. <\/p><p style=\"text-align: center;\">Alors que le Canada revitalise ses engagements nationaux et internationaux en mati\u00e8re de d\u00e9fense, le caract\u00e8re \u00e0 double usage de la technologie des semi\u2011conducteurs rend le financement de FABrIC particuli\u00e8rement digne d\u2019int\u00e9r\u00eat.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5fe195d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5fe195d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af0a9e4 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"af0a9e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"157\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/02\/FABrIC_CMC_logo-1024x157.png\" class=\"attachment-large size-large wp-image-4223\" alt=\"\" srcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/02\/FABrIC_CMC_logo-1024x157.png 1024w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/02\/FABrIC_CMC_logo-300x46.png 300w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/02\/FABrIC_CMC_logo-768x117.png 768w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/02\/FABrIC_CMC_logo-1536x235.png 1536w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/02\/FABrIC_CMC_logo-2048x313.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9213990 elementor-widget elementor-widget-spacer\" data-id=\"9213990\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9481eb6 elementor-widget elementor-widget-heading\" data-id=\"9481eb6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Suivez\u2011nous sur LinkedIn<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f34b492 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f34b492\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6e81177\" data-id=\"6e81177\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a1d57c elementor-widget elementor-widget-html\" data-id=\"3a1d57c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<style>\r\n    .center {\r\n        text-align: center;\r\n    }\r\n<\/style>\r\n\r\n<div class=\"center\">\r\n    <script src=\"https:\/\/platform.linkedin.com\/in.js\" type=\"text\/javascript\">\r\n        lang: en_US\r\n    <\/script>\r\n    <script type=\"IN\/FollowCompany\" data-id=\"549674\" data-counter=\"bottom\"><\/script>\r\n<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8fb15b1\" data-id=\"8fb15b1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ea930c0 elementor-shape-rounded elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"ea930c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin elementor-repeater-item-edcfec8\" href=\"\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-linkedin\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8b666ca\" data-id=\"8b666ca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-546c4f2 elementor-widget elementor-widget-text-editor\" data-id=\"546c4f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>Pour en savoir plus sur les possibilit\u00e9s de financement des D\u00e9fis pouvant atteindre 1\u202fM$ et sur les puissantes capacit\u00e9s qu\u2019offre le secteur canadien des semi\u2011conducteurs, abonnez\u2011vous \u00e0 notre infolettre. <\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ecf8b90 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ecf8b90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f5f727f elementor-widget elementor-widget-html\" data-id=\"f5f727f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<iframe src=\"https:\/\/go.cmc.ca\/l\/947082\/2024-07-10\/3mjdyn\" width=\"100%\" height=\"675\" type=\"text\/html\" frameborder=\"0\" allowtransparency=\"true\" style=\"border: 0\"><\/iframe>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5aa03e9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5aa03e9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e9e0ee4\" data-id=\"e9e0ee4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6be922d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6be922d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5975eb9\" data-id=\"5975eb9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cd04442 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"cd04442\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2fa9328 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2fa9328\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t<div class=\"make-column-clickable-elementor elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f3eb3d5 elementor-invisible\" style=\"cursor: pointer;\" data-column-clickable=\"https:\/\/fabricinnovation.ca\/about-fabric\/\" data-column-clickable-blank=\"_self\" data-id=\"f3eb3d5\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43c2ef3 elementor-widget elementor-widget-heading\" data-id=\"43c2ef3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00c0 Propos de FABrIC<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"make-column-clickable-elementor elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4dbf81f elementor-invisible\" style=\"cursor: pointer;\" data-column-clickable=\"https:\/\/fabricinnovation.ca\/funding\/\" data-column-clickable-blank=\"_self\" data-id=\"4dbf81f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-696e26c elementor-widget elementor-widget-heading\" data-id=\"696e26c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Financement<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"make-column-clickable-elementor elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b89ede4 elementor-invisible\" style=\"cursor: pointer;\" data-column-clickable=\"https:\/\/fabricinnovation.ca\/semiconductors-in-industry\/#defence\" data-column-clickable-blank=\"_self\" data-id=\"b89ede4\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a20f96 elementor-widget elementor-widget-heading\" data-id=\"8a20f96\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Semi\u2011conducteurs dans la d\u00e9fense<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e0dac15 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e0dac15\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1ae1e99\" data-id=\"1ae1e99\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a4327da elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a4327da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d969edd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d969edd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c185eb2\" data-id=\"c185eb2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35eb921 elementor-widget elementor-widget-spacer\" data-id=\"35eb921\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aa8a918 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aa8a918\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cab0f07\" data-id=\"cab0f07\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d10167 elementor-widget elementor-widget-spacer\" data-id=\"5d10167\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Semi\u2011conducteurs. Infrastructure souveraine essentielle. La d\u00e9fense d\u00e9pend depuis longtemps des technologies des semi\u2011conducteurs. Leur vaste utilisation dans l\u2019industrie \u2014 a\u00e9rospatiale, transport, \u00e9nergie propre, applications m\u00e9dicales et environnements oc\u00e9aniques hostiles \u2014 [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":2899,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-4224","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"featured_image_src":"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/07\/iStock-182062885-600x400.jpg","featured_image_src_square":"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/07\/iStock-182062885-600x600.jpg","_links":{"self":[{"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/pages\/4224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/comments?post=4224"}],"version-history":[{"count":0,"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/pages\/4224\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/media\/2899"}],"wp:attachment":[{"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/media?parent=4224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":4104,"date":"2026-01-19T16:59:30","date_gmt":"2026-01-19T21:59:30","guid":{"rendered":"https:\/\/fabricinnovation.ca\/events-cmc\/"},"modified":"2026-03-24T09:24:31","modified_gmt":"2026-03-24T14:24:31","slug":"events-cmc","status":"publish","type":"page","link":"https:\/\/fabricinnovation.ca\/fr\/events-cmc\/","title":{"rendered":"\u00c9v\u00e9nements CMC"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4104\" class=\"elementor elementor-4104 elementor-3903\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8241c4e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8241c4e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-da1cca8\" data-id=\"da1cca8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e0d178a elementor-widget elementor-widget-tec_elementor_widget_events_view\" data-id=\"e0d178a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tec_elementor_widget_events_view.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div\n\t class=\"tribe-common tribe-events tribe-events-view tribe-events-view--photo alignwide tribe-events-view--shortcode tribe-events-view--shortcode-ca316174 tribe-events-pro\" \tdata-js=\"tribe-events-view\"\n\tdata-view-rest-url=\"https:\/\/fabricinnovation.ca\/fr\/wp-json\/tribe\/views\/v2\/html\"\n\tdata-view-rest-method=\"GET\"\n\tdata-view-manage-url=\"\"\n\t\t\tdata-view-shortcode=\"ca316174\"\n\t\t\t\tdata-view-breakpoint-pointer=\"57c2e910-0f05-4ea0-a5b6-5de6b33560ae\"\n\t>\n\t<section class=\"tribe-common-l-container tribe-events-l-container\">\n\t\t<div\n\tclass=\"tribe-events-view-loader tribe-common-a11y-hidden\"\n\trole=\"alert\"\n\taria-live=\"polite\"\n>\n\t<span class=\"tribe-events-view-loader__text tribe-common-a11y-visual-hide\">\n\t\t14 \u00e9v\u00e8nements found.\t<\/span>\n\t<div class=\"tribe-events-view-loader__dots tribe-common-c-loader\">\n\t\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--dot tribe-common-c-loader__dot tribe-common-c-loader__dot--first\" \taria-hidden=\"true\"\n\tviewBox=\"0 0 15 15\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<circle cx=\"7.5\" cy=\"7.5\" r=\"7.5\"\/>\n<\/svg>\n\t\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--dot tribe-common-c-loader__dot tribe-common-c-loader__dot--second\" \taria-hidden=\"true\"\n\tviewBox=\"0 0 15 15\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<circle cx=\"7.5\" cy=\"7.5\" r=\"7.5\"\/>\n<\/svg>\n\t\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--dot tribe-common-c-loader__dot tribe-common-c-loader__dot--third\" \taria-hidden=\"true\"\n\tviewBox=\"0 0 15 15\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<circle cx=\"7.5\" cy=\"7.5\" r=\"7.5\"\/>\n<\/svg>\n\t<\/div>\n<\/div>\n\n\t\t<script type=\"application\/ld+json\">\r\n[{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Pour un Canada connect\\u00e9: objectifs, pressions et priorit\\u00e9s du secteur des t\\u00e9l\\u00e9communications du Canada\",\"description\":\"\",\"image\":\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/event_connecting_canada.jpg\",\"url\":\"https:\/\/connectingcanada.vfairs.com\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-05-20T00:00:00-05:00\",\"endDate\":\"2026-05-20T23:59:59-05:00\",\"location\":{\"@type\":\"Place\",\"name\":\"Ottawa, ON\",\"description\":\"\",\"url\":\"https:\/\/fabricinnovation.ca\/lieu\/ottawa-on\/\",\"address\":{\"@type\":\"PostalAddress\",\"addressLocality\":\"Ottawa\",\"addressRegion\":\"Ontario\",\"addressCountry\":\"Canada\"},\"telephone\":\"\",\"sameAs\":\"\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"COMSOL : mod\\u00e9lisation RF et optique des ondes\",\"description\":\"\",\"image\":\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/event_comsol_rf_wave.jpg\",\"url\":\"https:\/\/www.comsol.com\/events\/web-meeting\/rf-and-wave-optics-modeling-web-workshop-136062\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-05-20T14:00:00-05:00\",\"endDate\":\"2026-05-20T15:30:00-05:00\",\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Sommet mondial de la 6G\",\"description\":\"\",\"image\":\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/event_6g.jpg\",\"url\":\"https:\/\/global6gsummit.com\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-05-21T00:00:00-05:00\",\"endDate\":\"2026-05-22T23:59:59-05:00\",\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Conf\\u00e9rence AIC \\u2013 Innovation agroalimentaire 2026 \\u2013 L\\u2019avantage unique du Canada pour b\\u00e2tir la nation\",\"description\":\"\",\"image\":\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/event_aic_2026.jpg\",\"url\":\"https:\/\/www.aic.ca\/2026-conference\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-05-26T00:00:00-05:00\",\"endDate\":\"2026-05-27T23:59:59-05:00\",\"location\":{\"@type\":\"Place\",\"name\":\"Ottawa, ON\",\"description\":\"\",\"url\":\"https:\/\/fabricinnovation.ca\/lieu\/ottawa-on\/\",\"address\":{\"@type\":\"PostalAddress\",\"addressLocality\":\"Ottawa\",\"addressRegion\":\"Ontario\",\"addressCountry\":\"Canada\"},\"telephone\":\"\",\"sameAs\":\"\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"CMC basecamp\\u2122 : Atelier de fabrication en photonique sur silicium active SiEPIC\\u2011NUCLEUS 2026\",\"description\":\"\",\"image\":\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/03\/event_active_photonics.jpg\",\"url\":\"https:\/\/fabricinnovation.ca\/cmc-basecamp-active-silicon-photonics-fabrication-workshop-2026\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-05-28T09:00:00-05:00\",\"endDate\":\"2026-06-01T18:00:00-05:00\",\"location\":{\"@type\":\"Place\",\"name\":\"Quebec City\",\"description\":\"\",\"url\":\"https:\/\/fabricinnovation.ca\/lieu\/quebec-city\/\",\"address\":{\"@type\":\"PostalAddress\",\"addressLocality\":\"Quebec City\",\"addressRegion\":\"Quebec\",\"addressCountry\":\"Canada\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"CMC Microsystems\",\"description\":\"\",\"url\":\"\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Symposium annuel NUCLEUS 2026\",\"description\":\"\",\"image\":\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/event_nucleus_symposium.jpg\",\"url\":\"https:\/\/fabricinnovation.ca\/nucleus-annual-symposium-2026\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-06-01T09:00:00-05:00\",\"endDate\":\"2026-06-01T18:00:00-05:00\",\"location\":{\"@type\":\"Place\",\"name\":\"Quebec City\",\"description\":\"\",\"url\":\"https:\/\/fabricinnovation.ca\/lieu\/quebec-city\/\",\"address\":{\"@type\":\"PostalAddress\",\"addressLocality\":\"Quebec City\",\"addressRegion\":\"Quebec\",\"addressCountry\":\"Canada\"},\"telephone\":\"\",\"sameAs\":\"\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Photonique Nord 2026\",\"description\":\"\",\"image\":\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/PhotonicsNorth26.jpg\",\"url\":\"https:\/\/www.photonicsnorth.com\/en\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-06-02T00:00:00-05:00\",\"endDate\":\"2026-06-05T23:59:59-05:00\",\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"MMS 2026 \\u2013 29\\u1d49 Sommet mondial des micromachines\",\"description\":\"\",\"image\":\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/02\/mms2026.jpg\",\"url\":\"https:\/\/mms2026.soton.ac.uk\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-06-14T00:00:00-05:00\",\"endDate\":\"2026-06-17T23:59:59-05:00\",\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"COMSOL : Mod\\u00e9lisation acoustique\",\"description\":\"\",\"image\":\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/event_comsol_acoustics.jpg\",\"url\":\"https:\/\/www.comsol.com\/events\/web-meeting\/acoustics-modeling-web-workshop-136072\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-06-17T14:00:00-05:00\",\"endDate\":\"2026-06-17T15:30:00-05:00\",\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"24e conf\\u00e9rence internationale IEEE NEWCAS\",\"description\":\"\",\"image\":\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/03\/event_newcas_2026.png\",\"url\":\"https:\/\/newcas.org\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-06-21T08:00:00-05:00\",\"endDate\":\"2026-06-24T17:00:00-05:00\",\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Conf\\u00e9rence sur les MEMS optiques et la nanophotonique\",\"description\":\"\",\"image\":\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/03\/event_omn_2026.png\",\"url\":\"https:\/\/event.fourwaves.com\/omn2026\/pages\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-08-02T08:00:00-05:00\",\"endDate\":\"2026-08-06T17:00:00-05:00\",\"location\":{\"@type\":\"Place\",\"name\":\"H\\u00f4tel Sacacomie, Saint-Alexis-des-Monts, QC\",\"description\":\"\",\"url\":\"https:\/\/fabricinnovation.ca\/lieu\/hotel-sacacomie-saint-alexis-des-monts-qc\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"4000 Chem. Yvon-Plante\",\"addressLocality\":\"Saint-Alexis-des-Monts\",\"addressRegion\":\"Qu\\u00e9bec\",\"postalCode\":\"J0K 1V0\",\"addressCountry\":\"Canada\"},\"telephone\":\"\",\"sameAs\":\"\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"2e stage intensif canadien sur la conception de circuits int\\u00e9gr\\u00e9s analogiques et \\u00e0 signaux mixtes\",\"description\":\"\",\"image\":\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/03\/event_AnalogMixedSignalBootcamp.jpg\",\"url\":\"https:\/\/sites.grenadine.uqam.ca\/sites\/facultesciences\/en\/2ndams\/home\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-08-17T08:00:00-05:00\",\"endDate\":\"2026-08-21T17:00:00-05:00\",\"location\":{\"@type\":\"Place\",\"name\":\"Montr\\u00e9al, QC\",\"description\":\"\",\"url\":\"https:\/\/fabricinnovation.ca\/lieu\/montreal-qc\/\",\"address\":{\"@type\":\"PostalAddress\",\"addressLocality\":\"Montr\\u00e9al\",\"addressRegion\":\"Qu\\u00e9bec\",\"addressCountry\":\"Canada\"},\"telephone\":\"\",\"sameAs\":\"\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"21e Conf\\u00e9rence canadienne sur la science et la technologie des semi-conducteurs\",\"description\":\"&lt;p&gt;La 21e Conf\\u00e9rence canadienne sur la science et la technologie des semi-conducteurs se tiendra \\u00e0 l\\\\'Universit\\u00e9 d\\\\'Ottawa du 25 au 27 ao\\u00fbt 2026. Joignez-vous \\u00e0 la communaut\\u00e9 canadienne des semi-conducteurs pour trois jours de pr\\u00e9sentations scientifiques, de tutoriels et de r\\u00e9seautage. &lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/02\/event_csstc.jpg\",\"url\":\"https:\/\/uniweb.uottawa.ca\/sites\/csstc2026\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-08-25T08:00:00-05:00\",\"endDate\":\"2026-08-27T17:00:00-05:00\",\"location\":{\"@type\":\"Place\",\"name\":\"Ottawa, ON\",\"description\":\"\",\"url\":\"https:\/\/fabricinnovation.ca\/lieu\/ottawa-on\/\",\"address\":{\"@type\":\"PostalAddress\",\"addressLocality\":\"Ottawa\",\"addressRegion\":\"Ontario\",\"addressCountry\":\"Canada\"},\"telephone\":\"\",\"sameAs\":\"\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Symposium canadien sur les semi-conducteurs 2026 \\u2014 O\\u00f9 la souverainet\\u00e9 rencontre la prosp\\u00e9rit\\u00e9\",\"description\":\"\",\"image\":\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/03\/event_css2026.jpg\",\"url\":\"https:\/\/fabricinnovation.ca\/css2026\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-10-19T00:00:00-05:00\",\"endDate\":\"2026-10-21T23:59:59-05:00\",\"performer\":\"Organization\"}]\r\n<\/script>\n\t\t<script data-js=\"tribe-events-view-data\" type=\"application\/json\">\n\t{\"slug\":\"photo\",\"prev_url\":\"https:\\\/\\\/fabricinnovation.ca\\\/fr\\\/\\u00e9v\\u00e9nements\\\/photo\\\/?rest_route=%2Fwp%2Fv2%2Fpages&shortcode=ca316174&eventDisplay=past\",\"next_url\":\"\",\"view_class\":\"Tribe\\\\Events\\\\Pro\\\\Views\\\\V2\\\\Views\\\\Photo_View\",\"view_slug\":\"photo\",\"view_label\":\"Photo\",\"title\":\"\\u00c9v\\u00e8nements depuis mai 13 \\u2013 octobre 19 \\u2013 FABrIC\",\"events\":[10000163,10000167,10000162,10000159,10000147,10000169,10000068,10000127,10000170,10000139,10000140,10000144,10000130,10000133],\"url\":\"https:\\\/\\\/fabricinnovation.ca\\\/fr\\\/\\u00e9v\\u00e9nements\\\/photo\\\/?shortcode=ca316174\",\"url_event_date\":false,\"bar\":{\"keyword\":\"\",\"date\":\"\"},\"today\":\"2026-05-13 00:00:00\",\"now\":\"2026-05-13 11:35:06\",\"home_url\":\"https:\\\/\\\/fabricinnovation.ca\\\/fr\\\/\",\"rest_url\":\"https:\\\/\\\/fabricinnovation.ca\\\/fr\\\/wp-json\\\/tribe\\\/views\\\/v2\\\/html\",\"rest_method\":\"GET\",\"rest_nonce\":\"\",\"should_manage_url\":false,\"today_url\":\"https:\\\/\\\/fabricinnovation.ca\\\/fr\\\/\\u00e9v\\u00e9nements\\\/photo\\\/?rest_route=%2Fwp%2Fv2%2Fpages&shortcode=ca316174\",\"today_title\":\"Cliquer pour s\\u00e9lectionner la date du jour\",\"today_label\":\"Aujourd\\u2019hui\",\"prev_label\":\"\",\"next_label\":\"\",\"date_formats\":{\"compact\":\"n\\\/j\\\/Y\",\"month_and_year_compact\":\"n\\\/Y\",\"month_and_year\":\"F Y\",\"time_range_separator\":\" - \",\"date_time_separator\":\" @ \"},\"messages\":[],\"start_of_week\":\"1\",\"header_title\":\"\",\"header_title_element\":\"h1\",\"content_title\":\"\",\"show_content_title\":false,\"breadcrumbs\":[],\"backlink\":false,\"before_events\":\"\",\"after_events\":\"\",\"display_events_bar\":true,\"disable_event_search\":true,\"live_refresh\":true,\"ical\":{\"display_link\":true,\"link\":{\"url\":\"https:\\\/\\\/fabricinnovation.ca\\\/fr\\\/\\u00e9v\\u00e9nements\\\/photo\\\/?shortcode=ca316174&#038;ical=1\",\"text\":\"Exporter \\u00c9v\\u00e8nements\",\"title\":\"Utilisez ceci pour partager les donn\\u00e9es de calendrier avec Google Calendar, Apple iCal et d\\u2019autres applications compatibles\"}},\"container_classes\":[\"tribe-common\",\"tribe-events\",\"tribe-events-view\",\"tribe-events-view--photo\",\"alignwide\",\"tribe-events-view--shortcode\",\"tribe-events-view--shortcode-ca316174\",\"tribe-events-pro\"],\"container_data\":{\"shortcode\":\"ca316174\"},\"is_past\":false,\"breakpoints\":{\"xsmall\":500,\"medium\":768,\"full\":960},\"breakpoint_pointer\":\"57c2e910-0f05-4ea0-a5b6-5de6b33560ae\",\"is_initial_load\":false,\"public_views\":{\"list\":{\"view_class\":\"Tribe\\\\Events\\\\Views\\\\V2\\\\Views\\\\List_View\",\"view_url\":\"https:\\\/\\\/fabricinnovation.ca\\\/fr\\\/\\u00e9v\\u00e9nements\\\/liste\\\/?shortcode=ca316174\",\"view_label\":\"Liste\",\"aria_label\":\"Display \\u00c9v\\u00e8nements in Liste View\"},\"month\":{\"view_class\":\"Tribe\\\\Events\\\\Views\\\\V2\\\\Views\\\\Month_View\",\"view_url\":\"https:\\\/\\\/fabricinnovation.ca\\\/fr\\\/\\u00e9v\\u00e9nements\\\/mois\\\/?shortcode=ca316174\",\"view_label\":\"Mois\",\"aria_label\":\"Display \\u00c9v\\u00e8nements in Mois View\"},\"day\":{\"view_class\":\"Tribe\\\\Events\\\\Views\\\\V2\\\\Views\\\\Day_View\",\"view_url\":\"https:\\\/\\\/fabricinnovation.ca\\\/fr\\\/\\u00e9v\\u00e9nements\\\/aujourd\\u2019hui\\\/?shortcode=ca316174\",\"view_label\":\"Jour\",\"aria_label\":\"Display \\u00c9v\\u00e8nements in Jour View\"}},\"show_latest_past\":true,\"past\":false,\"category_colors_enabled\":false,\"category_colors_category_dropdown\":[{\"slug\":\"workshop\",\"name\":\"Workshop\",\"priority\":2,\"primary\":\"#373869\",\"hidden\":false},{\"slug\":\"webinar\",\"name\":\"Webinar\",\"priority\":1,\"primary\":\"#373869\",\"hidden\":false},{\"slug\":\"conference\",\"name\":\"Conference\",\"priority\":0,\"primary\":\"#0092cc\",\"hidden\":false},{\"slug\":\"training\",\"name\":\"Training\",\"priority\":0,\"primary\":\"#373869\",\"hidden\":false}],\"category_colors_super_power\":false,\"category_colors_show_reset_button\":false,\"placeholder_url\":\"https:\\\/\\\/fabricinnovation.ca\\\/fr\\\/wp-content\\\/plugins\\\/events-calendar-pro\\\/src\\\/resources\\\/images\\\/tribe-event-placeholder-image.svg\",\"show_now\":true,\"now_label\":\"\\u00c0 venir\",\"now_label_mobile\":\"\\u00c0 venir\",\"show_end\":false,\"selected_start_datetime\":\"2026-05-13\",\"selected_start_date_mobile\":\"5\\\/13\\\/2026\",\"selected_start_date_label\":\"mai 13\",\"selected_end_datetime\":\"2026-10-19\",\"selected_end_date_mobile\":\"10\\\/19\\\/2026\",\"selected_end_date_label\":\"octobre 19\",\"datepicker_date\":\"5\\\/13\\\/2026\",\"subscribe_links\":{\"gcal\":{\"label\":\"Google Agenda\",\"single_label\":\"Ajouter \\u00e0 Google Agenda\",\"visible\":true,\"block_slug\":\"hasGoogleCalendar\"},\"ical\":{\"label\":\"iCalendar\",\"single_label\":\"Ajouter \\u00e0 iCalendar\",\"visible\":true,\"block_slug\":\"hasiCal\"},\"outlook-365\":{\"label\":\"Outlook 365\",\"single_label\":\"Outlook 365\",\"visible\":true,\"block_slug\":\"hasOutlook365\"},\"outlook-live\":{\"label\":\"Outlook Live\",\"single_label\":\"Outlook Live\",\"visible\":true,\"block_slug\":\"hasOutlookLive\"},\"ics\":{\"label\":\"Exporter le fichier .ics\",\"single_label\":\"Exporter le fichier .ics\",\"visible\":true,\"block_slug\":null},\"outlook-ics\":{\"label\":\"Exporter le fichier Outlook .ics\",\"single_label\":\"Exporter le fichier Outlook .ics\",\"visible\":true,\"block_slug\":null}},\"display_recurring_toggle\":false,\"_context\":{\"slug\":\"photo\",\"should_manage_url\":false},\"text\":\"Chargement...\",\"classes\":[\"tribe-common-c-loader__dot\",\"tribe-common-c-loader__dot--third\"]}<\/script>\n\n\t\t\n\t\t\n<header  class=\"tribe-events-header\" >\n\t<div class=\"tribe-events-header__content-title\">\n\t<h1 class=\"screen-reader-text tec-a11y-title-hidden\">\u00c9v\u00e8nements<\/h1><\/div>\n\n\t\n\t\n\t<div\n\t class=\"tribe-events-header__events-bar tribe-events-c-events-bar\" \tdata-js=\"tribe-events-events-bar\"\n>\n\n\t<h2 class=\"tribe-common-a11y-visual-hide\">\n\t\tNavigation par consultations\t<\/h2>\n\n\t\n\t<div class=\"tribe-events-c-events-bar__views\">\n\t<h3 class=\"tribe-common-a11y-visual-hide\">\n\t\tNavigation de vues \u00c9v\u00e8nement\t<\/h3>\n\t<div  class=\"tribe-events-c-view-selector\"  data-js=\"tribe-events-view-selector\">\n\t\t<button\n\t\t\tclass=\"tribe-events-c-view-selector__button tribe-common-c-btn__clear\"\n\t\t\tdata-js=\"tribe-events-view-selector-button\"\n\t\t\taria-current=\"true\"\n\t\t\taria-description=\"Select Calendar View\"\n\t\t>\n\t\t\t<span class=\"tribe-events-c-view-selector__button-icon\">\n\t\t\t\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--photo tribe-events-c-view-selector__button-icon-svg\" \taria-hidden=\"true\"\n\tviewBox=\"0 0 19 18\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M17.536 0H.539a.484.484 0 00-.495.483v17.034c0 .27.218.483.495.483h16.997a.484.484 0 00.495-.483V.483A.484.484 0 0017.536 0zm-.515.986V13.73l-1.907-2.938c-.555-.58-1.584-.58-2.139 0l-1.327 1.41-3.841-4.31a1.548 1.548 0 00-1.169-.502c-.435 0-.871.193-1.148.522l-4.436 4.929V.986h15.967zM1.054 14.329v2.705h15.987v-1.835l-2.66-3.73c-.178-.175-.495-.175-.653 0l-1.703 1.816c-.1.097-.218.174-.377.155a.569.569 0 01-.376-.174L7.054 8.53a.577.577 0 00-.416-.174.504.504 0 00-.396.174l-5.188 5.798z\" class=\"tribe-common-c-svgicon__svg-fill\"\/><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M14.682 5.875c0 1.043-.825 1.875-1.82 1.875-.993 0-1.818-.832-1.818-1.875C11.044 4.83 11.85 4 12.863 4c1.012 0 1.819.831 1.819 1.875zm-.957 0c0-.483-.393-.89-.862-.89s-.863.407-.863.89c0 .483.394.889.863.889s.862-.406.862-.89z\" class=\"tribe-common-c-svgicon__svg-fill\"\/>\n<\/svg>\n\t\t\t<\/span>\n\t\t\t<span class=\"tribe-events-c-view-selector__button-text tribe-common-a11y-visual-hide\">\n\t\t\t\tPhoto\t\t\t<\/span>\n\t\t\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--caret-down tribe-events-c-view-selector__button-icon-caret-svg\" \taria-hidden=\"true\"\n\tviewBox=\"0 0 10 7\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M1.008.609L5 4.6 8.992.61l.958.958L5 6.517.05 1.566l.958-.958z\" class=\"tribe-common-c-svgicon__svg-fill\"\/>\n<\/svg>\n\t\t<\/button>\n\t\t<div\n\tclass=\"tribe-events-c-view-selector__content\"\n\tid=\"tribe-events-view-selector-content\"\n\tdata-js=\"tribe-events-view-selector-list-container\"\n>\n\t<ul class=\"tribe-events-c-view-selector__list\">\n\t\t\t\t\t<li\n\t class=\"tribe-events-c-view-selector__list-item tribe-events-c-view-selector__list-item--list\" >\n\t<a\n\t\thref=\"https:\/\/fabricinnovation.ca\/fr\/\u00e9v\u00e9nements\/liste\/?shortcode=ca316174\"\n\t\tclass=\"tribe-events-c-view-selector__list-item-link\"\n\t\tdata-js=\"tribe-events-view-link\"\n\t\taria-label=\"Display \u00c9v\u00e8nements in Liste View\"\n\t\t\t>\n\t\t<span class=\"tribe-events-c-view-selector__list-item-icon\">\n\t\t\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--list tribe-events-c-view-selector__list-item-icon-svg\" \taria-hidden=\"true\"\n\tviewBox=\"0 0 19 19\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M.451.432V17.6c0 .238.163.432.364.432H18.12c.2 0 .364-.194.364-.432V.432c0-.239-.163-.432-.364-.432H.815c-.2 0-.364.193-.364.432zm.993.81h16.024V3.56H1.444V1.24zM17.468 3.56H1.444v13.227h16.024V3.56z\" class=\"tribe-common-c-svgicon__svg-fill\"\/>\n\t<g clip-path=\"url(#tribe-events-c-view-selector__list-item-icon-svg-0)\" class=\"tribe-common-c-svgicon__svg-fill\">\n\t\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M11.831 4.912v1.825c0 .504.409.913.913.913h1.825a.913.913 0 00.912-.913V4.912A.913.913 0 0014.57 4h-1.825a.912.912 0 00-.913.912z\"\/>\n\t\t<path d=\"M8.028 7.66a.449.449 0 00.446-.448v-.364c0-.246-.2-.448-.446-.448h-4.13a.449.449 0 00-.447.448v.364c0 .246.201.448.447.448h4.13zM9.797 5.26a.449.449 0 00.447-.448v-.364c0-.246-.201-.448-.447-.448h-5.9a.449.449 0 00-.446.448v.364c0 .246.201.448.447.448h5.9z\"\/>\n\t<\/g>\n\t<g clip-path=\"url(#tribe-events-c-view-selector__list-item-icon-svg-1)\" class=\"tribe-common-c-svgicon__svg-fill\">\n\t\t\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M11.831 10.912v1.825c0 .505.409.913.913.913h1.825a.913.913 0 00.912-.912v-1.825A.913.913 0 0014.57 10h-1.825a.912.912 0 00-.913.912z\"\/>\n\t\t<path d=\"M8.028 13.66a.449.449 0 00.446-.448v-.364c0-.246-.2-.448-.446-.448h-4.13a.449.449 0 00-.447.448v.364c0 .246.201.448.447.448h4.13zM9.797 11.26a.449.449 0 00.447-.448v-.364c0-.246-.201-.448-.447-.448h-5.9a.449.449 0 00-.446.448v.364c0 .246.201.448.447.448h5.9z\"\/>\n\t<\/g>\n\t<defs>\n\t\t<clipPath id=\"tribe-events-c-view-selector__list-item-icon-svg-0\">\n\t\t\t<path transform=\"translate(3.451 4)\" d=\"M0 0h13v4H0z\"\/>\n\t\t<\/clipPath>\n\t\t<clipPath id=\"tribe-events-c-view-selector__list-item-icon-svg-1\">\n\t\t\t<path transform=\"translate(3.451 10)\" d=\"M0 0h13v4H0z\"\/>\n\t\t<\/clipPath>\n\t<\/defs>\n<\/svg>\n\t\t<\/span>\n\t\t<span class=\"tribe-events-c-view-selector__list-item-text\">\n\t\t\tListe\t\t<\/span>\n\t<\/a>\n<\/li>\n\t\t\t\t\t<li\n\t class=\"tribe-events-c-view-selector__list-item tribe-events-c-view-selector__list-item--month\" >\n\t<a\n\t\thref=\"https:\/\/fabricinnovation.ca\/fr\/\u00e9v\u00e9nements\/mois\/?shortcode=ca316174\"\n\t\tclass=\"tribe-events-c-view-selector__list-item-link\"\n\t\tdata-js=\"tribe-events-view-link\"\n\t\taria-label=\"Display \u00c9v\u00e8nements in Mois View\"\n\t\t\t>\n\t\t<span class=\"tribe-events-c-view-selector__list-item-icon\">\n\t\t\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--month tribe-events-c-view-selector__list-item-icon-svg\" \taria-hidden=\"true\"\n\tviewBox=\"0 0 18 19\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M0 .991v17.04c0 .236.162.428.361.428h17.175c.2 0 .361-.192.361-.429V.991c0-.237-.162-.428-.361-.428H.36C.161.563 0 .754 0 .99zm.985.803H16.89v2.301H.985v-2.3zM16.89 5.223H.985v12H16.89v-12zM6.31 7.366v.857c0 .237.192.429.429.429h.857a.429.429 0 00.428-.429v-.857a.429.429 0 00-.428-.429H6.74a.429.429 0 00-.429.429zm3.429.857v-.857c0-.237.191-.429.428-.429h.857c.237 0 .429.192.429.429v.857a.429.429 0 01-.429.429h-.857a.429.429 0 01-.428-.429zm3.428-.857v.857c0 .237.192.429.429.429h.857a.429.429 0 00.428-.429v-.857a.429.429 0 00-.428-.429h-.857a.429.429 0 00-.429.429zm-6.857 4.286v-.858c0-.236.192-.428.429-.428h.857c.236 0 .428.192.428.428v.858a.429.429 0 01-.428.428H6.74a.429.429 0 01-.429-.428zm3.429-.858v.858c0 .236.191.428.428.428h.857a.429.429 0 00.429-.428v-.858a.429.429 0 00-.429-.428h-.857a.428.428 0 00-.428.428zm3.428.858v-.858c0-.236.192-.428.429-.428h.857c.236 0 .428.192.428.428v.858a.429.429 0 01-.428.428h-.857a.429.429 0 01-.429-.428zm-10.286-.858v.858c0 .236.192.428.429.428h.857a.429.429 0 00.429-.428v-.858a.429.429 0 00-.429-.428h-.857a.429.429 0 00-.429.428zm0 4.286v-.857c0-.237.192-.429.429-.429h.857c.237 0 .429.192.429.429v.857a.429.429 0 01-.429.429h-.857a.429.429 0 01-.429-.429zm3.429-.857v.857c0 .237.192.429.429.429h.857a.429.429 0 00.428-.429v-.857a.429.429 0 00-.428-.429H6.74a.429.429 0 00-.429.429zm3.429.857v-.857c0-.237.191-.429.428-.429h.857c.237 0 .429.192.429.429v.857a.429.429 0 01-.429.429h-.857a.429.429 0 01-.428-.429z\" class=\"tribe-common-c-svgicon__svg-fill\"\/>\n<\/svg>\n\t\t<\/span>\n\t\t<span class=\"tribe-events-c-view-selector__list-item-text\">\n\t\t\tMois\t\t<\/span>\n\t<\/a>\n<\/li>\n\t\t\t\t\t<li\n\t class=\"tribe-events-c-view-selector__list-item tribe-events-c-view-selector__list-item--day\" >\n\t<a\n\t\thref=\"https:\/\/fabricinnovation.ca\/fr\/\u00e9v\u00e9nements\/aujourd\u2019hui\/?shortcode=ca316174\"\n\t\tclass=\"tribe-events-c-view-selector__list-item-link\"\n\t\tdata-js=\"tribe-events-view-link\"\n\t\taria-label=\"Display \u00c9v\u00e8nements in Jour View\"\n\t\t\t>\n\t\t<span class=\"tribe-events-c-view-selector__list-item-icon\">\n\t\t\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--day tribe-events-c-view-selector__list-item-icon-svg\" \taria-hidden=\"true\"\n\tviewBox=\"0 0 19 18\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M.363 17.569V.43C.363.193.526 0 .726 0H18c.201 0 .364.193.364.431V17.57c0 .238-.163.431-.364.431H.726c-.2 0-.363-.193-.363-.431zm16.985-16.33H1.354v2.314h15.994V1.24zM1.354 4.688h15.994v12.07H1.354V4.687zm11.164 9.265v-1.498c0-.413.335-.748.748-.748h1.498c.413 0 .748.335.748.748v1.498a.749.749 0 01-.748.748h-1.498a.749.749 0 01-.748-.748z\" class=\"tribe-common-c-svgicon__svg-fill\"\/>\n<\/svg>\n\t\t<\/span>\n\t\t<span class=\"tribe-events-c-view-selector__list-item-text\">\n\t\t\tJour\t\t<\/span>\n\t<\/a>\n<\/li>\n\t\t\t<\/ul>\n<\/div>\n\t<\/div>\n<\/div>\n\n<\/div>\n\n\t<div class=\"tribe-events-c-top-bar tribe-events-header__top-bar\">\n\n\t<nav class=\"tribe-events-c-top-bar__nav tribe-common-a11y-hidden\" aria-label=\"Top \u00e9v\u00e8nements list pagination\">\n\t<ul class=\"tribe-events-c-top-bar__nav-list\">\n\t\t<li class=\"tribe-events-c-top-bar__nav-list-item\">\n\t<a\n\t\thref=\"https:\/\/fabricinnovation.ca\/fr\/\u00e9v\u00e9nements\/photo\/?rest_route=%2Fwp%2Fv2%2Fpages&#038;shortcode=ca316174&#038;eventDisplay=past\"\n\t\tclass=\"tribe-common-c-btn-icon tribe-common-c-btn-icon--caret-left tribe-events-c-top-bar__nav-link tribe-events-c-top-bar__nav-link--prev\"\n\t\taria-label=\" \u00c9v\u00e8nements pr\u00e9c\u00e9dents\"\n\t\ttitle=\" \u00c9v\u00e8nements pr\u00e9c\u00e9dents\"\n\t\tdata-js=\"tribe-events-view-link\"\n\t>\n\t\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--caret-left tribe-common-c-btn-icon__icon-svg tribe-events-c-top-bar__nav-link-icon-svg\" \taria-hidden=\"true\"\n\tviewBox=\"0 0 10 16\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<path d=\"M9.7 14.4l-1.5 1.5L.3 8 8.2.1l1.5 1.5L3.3 8l6.4 6.4z\"\/>\n<\/svg>\n\t<\/a>\n<\/li>\n\n\t\t<li class=\"tribe-events-c-top-bar__nav-list-item\">\n\t<button\n\t\tclass=\"tribe-common-c-btn-icon tribe-common-c-btn-icon--caret-right tribe-events-c-top-bar__nav-link tribe-events-c-top-bar__nav-link--next\"\n\t\taria-label=\"\u00c9v\u00e8nements suivants\"\n\t\ttitle=\"\u00c9v\u00e8nements suivants\"\n\t\tdisabled\n\t>\n\t\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--caret-right tribe-common-c-btn-icon__icon-svg tribe-events-c-top-bar__nav-link-icon-svg\" \taria-hidden=\"true\"\n\tviewBox=\"0 0 10 16\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<path d=\"M.3 1.6L1.8.1 9.7 8l-7.9 7.9-1.5-1.5L6.7 8 .3 1.6z\"\/>\n<\/svg>\n\t<\/button>\n<\/li>\n\t<\/ul>\n<\/nav>\n\n\t<a\n\thref=\"https:\/\/fabricinnovation.ca\/fr\/\u00e9v\u00e9nements\/photo\/?rest_route=%2Fwp%2Fv2%2Fpages&#038;shortcode=ca316174\"\n\tclass=\"tribe-common-c-btn-border-small tribe-events-c-top-bar__today-button tribe-common-a11y-hidden\"\n\tdata-js=\"tribe-events-view-link\"\n\taria-description=\"Cliquer pour s\u00e9lectionner la date du jour\"\n>\n\tAujourd\u2019hui<\/a>\n\n\t<div class=\"tribe-events-c-top-bar__datepicker\">\n\t<button\n\t\tclass=\"tribe-common-c-btn__clear tribe-common-h3 tribe-common-h--alt tribe-events-c-top-bar__datepicker-button\"\n\t\tdata-js=\"tribe-events-top-bar-datepicker-button\"\n\t\ttype=\"button\"\n\t\taria-label=\"Cliquer pour basculer sur le s\u00e9lecteur de date\"\n\t\ttitle=\"Cliquer pour basculer sur le s\u00e9lecteur de date\"\n\t>\n\t\t<time\n\t\t\tdatetime=\"2026-05-13\"\n\t\t\tclass=\"tribe-events-c-top-bar__datepicker-time\"\n\t\t>\n\t\t\t\t\t\t\t<span class=\"tribe-events-c-top-bar__datepicker-mobile\">\n\t\t\t\t\t\u00c0 venir\t\t\t\t<\/span>\n\t\t\t\t<span class=\"tribe-events-c-top-bar__datepicker-desktop tribe-common-a11y-hidden\">\n\t\t\t\t\t\u00c0 venir\t\t\t\t<\/span>\n\t\t\t\t\t<\/time>\n\t\t\t\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--caret-down tribe-events-c-top-bar__datepicker-button-icon-svg\" \taria-hidden=\"true\"\n\tviewBox=\"0 0 10 7\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M1.008.609L5 4.6 8.992.61l.958.958L5 6.517.05 1.566l.958-.958z\" class=\"tribe-common-c-svgicon__svg-fill\"\/>\n<\/svg>\n\t<\/button>\n\t<label\n\t\tclass=\"tribe-events-c-top-bar__datepicker-label tribe-common-a11y-visual-hide\"\n\t\tfor=\"tribe-events-top-bar-date\"\n\t>\n\t\tS\u00e9lectionnez la date\t<\/label>\n\t<input\n\t\ttype=\"text\"\n\t\tclass=\"tribe-events-c-top-bar__datepicker-input tribe-common-a11y-visual-hide\"\n\t\tdata-js=\"tribe-events-top-bar-date\"\n\t\tid=\"tribe-events-top-bar-date\"\n\t\tname=\"tribe-events-views[tribe-bar-date]\"\n\t\tvalue=\"5\/13\/2026\"\n\t\ttabindex=\"-1\"\n\t\tautocomplete=\"off\"\n\t\treadonly=\"readonly\"\n\t\/>\n\t<div class=\"tribe-events-c-top-bar__datepicker-container\" data-js=\"tribe-events-top-bar-datepicker-container\"><\/div>\n\t<template class=\"tribe-events-c-top-bar__datepicker-template-prev-icon\">\n\t\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--caret-left tribe-events-c-top-bar__datepicker-nav-icon-svg\" \taria-hidden=\"true\"\n\tviewBox=\"0 0 10 16\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<path d=\"M9.7 14.4l-1.5 1.5L.3 8 8.2.1l1.5 1.5L3.3 8l6.4 6.4z\"\/>\n<\/svg>\n\t<\/template>\n\t<template class=\"tribe-events-c-top-bar__datepicker-template-next-icon\">\n\t\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--caret-right tribe-events-c-top-bar__datepicker-nav-icon-svg\" \taria-hidden=\"true\"\n\tviewBox=\"0 0 10 16\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<path d=\"M.3 1.6L1.8.1 9.7 8l-7.9 7.9-1.5-1.5L6.7 8 .3 1.6z\"\/>\n<\/svg>\n\t<\/template>\n<\/div>\n\n\t\n\t<div class=\"tribe-events-c-top-bar__actions tribe-common-a11y-hidden\">\n\t<\/div>\n\n<\/div>\n<\/header>\n\n\t\t\n\t\t<div class=\"tribe-events-pro-photo\">\n\t\t\t<h2\n\t\t\t\tid=\"tribe-events-photo-view-heading\"\n\t\t\t\tclass=\"tribe-common-a11y-visual-hide\"\n\t\t\t>\n\t\t\t\tList of events in Photo View\t\t\t<\/h2>\n\t\t\t<ul class=\"tribe-common-g-row tribe-common-g-row--gutters\" aria-labelledby=\"tribe-events-photo-view-heading\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<li  class=\"tribe-common-g-col tribe-events-pro-photo__event post-10000163 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tribe_events_cat-conference cat_conference ast-grid-common-col ast-full-width ast-article-post\" >\n\t<article>\n\t\t<div class=\"tribe-events-pro-photo__event-featured-image-wrapper\">\n\t<a\n\t\thref=\"https:\/\/connectingcanada.vfairs.com\/\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-pro-photo__event-featured-image-link\"\n\t>\n\t\t<span class=\"tribe-events-pro-photo__event-featured-image-link-inner tribe-common-a11y-hidden\">Pour un Canada connect\u00e9: objectifs, pressions et priorit\u00e9s du secteur des t\u00e9l\u00e9communications du Canada<\/span>\n\t\t<img\n\t\t\tclass=\"tribe-events-pro-photo__event-featured-image\"\n\t\t\tsrc=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/event_connecting_canada.jpg\"\n\t\t\trole=\"presentation\"\n\t\t\t\t\t\t\tsrcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/event_connecting_canada-300x170.jpg 300w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/event_connecting_canada-768x434.jpg 768w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/event_connecting_canada.jpg 800w\"\n\t\t\t\t\t\t\t\t\t\talt=\"\"\n\t\t\t\t\t\t\t\t\t\ttitle=\"event_connecting_canada\"\n\t\t\t\t\t\t\t\t\t\twidth=\"800\"\n\t\t\t\t\t\t\t\t\t\theight=\"452\"\n\t\t\t\t\t\/>\n\t<\/a>\n<\/div>\n\n\t\t<div class=\"tribe-events-pro-photo__event-details-wrapper\">\n\t\t\t<div class=\"tribe-events-pro-photo__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-pro-photo__event-date-tag-datetime\" datetime=\"2026-05-20\">\n\t\t<span class=\"tribe-events-pro-photo__event-date-tag-month\">\n\t\t\tMai\t\t<\/span>\n\t\t<span class=\"tribe-events-pro-photo__event-date-tag-daynum tribe-common-h5 tribe-common-h4--min-medium\">\n\t\t\t20\t\t<\/span>\n\t<\/time>\n<\/div>\n\t\t\t<div class=\"tribe-events-pro-photo__event-details\">\n\t\t\t\t<h3 class=\"tribe-events-pro-photo__event-title tribe-common-h6\">\n\t<a\n\t\thref=\"https:\/\/connectingcanada.vfairs.com\/\"\n\t\ttitle=\"Pour un Canada connect\u00e9: objectifs, pressions et priorit\u00e9s du secteur des t\u00e9l\u00e9communications du Canada\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-pro-photo__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tPour un Canada connect\u00e9: objectifs, pressions et priorit\u00e9s du secteur des t\u00e9l\u00e9communications du Canada\t<\/a>\n<\/h3>\n\t\t\t\t<div class=\"tribe-events-pro-photo__event-datetime tribe-common-b2\">\n\t\t\t\t<time datetime=\"2026-05-20\">\n\t\t\tToute la journ\u00e9e\t\t<\/time>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/article>\n<\/li>\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<li  class=\"tribe-common-g-col tribe-events-pro-photo__event post-10000167 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tribe_events_cat-atelier tribe_events_cat-formation cat_atelier cat_formation ast-grid-common-col ast-full-width ast-article-post\" >\n\t<article>\n\t\t<div class=\"tribe-events-pro-photo__event-featured-image-wrapper\">\n\t<a\n\t\thref=\"https:\/\/www.comsol.com\/events\/web-meeting\/rf-and-wave-optics-modeling-web-workshop-136062\/\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-pro-photo__event-featured-image-link\"\n\t>\n\t\t<span class=\"tribe-events-pro-photo__event-featured-image-link-inner tribe-common-a11y-hidden\">COMSOL : mod\u00e9lisation RF et optique des ondes<\/span>\n\t\t<img\n\t\t\tclass=\"tribe-events-pro-photo__event-featured-image\"\n\t\t\tsrc=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/event_comsol_rf_wave.jpg\"\n\t\t\trole=\"presentation\"\n\t\t\t\t\t\t\tsrcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/event_comsol_rf_wave-300x170.jpg 300w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/event_comsol_rf_wave-768x434.jpg 768w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/event_comsol_rf_wave.jpg 800w\"\n\t\t\t\t\t\t\t\t\t\talt=\"\"\n\t\t\t\t\t\t\t\t\t\ttitle=\"event_comsol_rf_wave\"\n\t\t\t\t\t\t\t\t\t\twidth=\"800\"\n\t\t\t\t\t\t\t\t\t\theight=\"452\"\n\t\t\t\t\t\/>\n\t<\/a>\n<\/div>\n\n\t\t<div class=\"tribe-events-pro-photo__event-details-wrapper\">\n\t\t\t<div class=\"tribe-events-pro-photo__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-pro-photo__event-date-tag-datetime\" datetime=\"2026-05-20\">\n\t\t<span class=\"tribe-events-pro-photo__event-date-tag-month\">\n\t\t\tMai\t\t<\/span>\n\t\t<span class=\"tribe-events-pro-photo__event-date-tag-daynum tribe-common-h5 tribe-common-h4--min-medium\">\n\t\t\t20\t\t<\/span>\n\t<\/time>\n<\/div>\n\t\t\t<div class=\"tribe-events-pro-photo__event-details\">\n\t\t\t\t<h3 class=\"tribe-events-pro-photo__event-title tribe-common-h6\">\n\t<a\n\t\thref=\"https:\/\/www.comsol.com\/events\/web-meeting\/rf-and-wave-optics-modeling-web-workshop-136062\/\"\n\t\ttitle=\"COMSOL : mod\u00e9lisation RF et optique des ondes\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-pro-photo__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tCOMSOL : mod\u00e9lisation RF et optique des ondes\t<\/a>\n<\/h3>\n\t\t\t\t<div class=\"tribe-events-pro-photo__event-datetime tribe-common-b2\">\n\t\t\t\t<time datetime=\"14:00\">\n\t\t\t14h00\t\t<\/time>\n\t\t\t\t\t<span class=\"tribe-events-events-pro-photo__event-datetime-separator\"> - <\/span>\n\t\t\t<time datetime=\"15:30\">\n\t\t\t\t15h30\t\t\t<\/time>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/article>\n<\/li>\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<li  class=\"tribe-common-g-col tribe-events-pro-photo__event post-10000162 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tribe_events_cat-conference cat_conference ast-grid-common-col ast-full-width ast-article-post\" >\n\t<article>\n\t\t<div class=\"tribe-events-pro-photo__event-featured-image-wrapper\">\n\t<a\n\t\thref=\"https:\/\/global6gsummit.com\/\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-pro-photo__event-featured-image-link\"\n\t>\n\t\t<span class=\"tribe-events-pro-photo__event-featured-image-link-inner tribe-common-a11y-hidden\">Sommet mondial de la 6G<\/span>\n\t\t<img\n\t\t\tclass=\"tribe-events-pro-photo__event-featured-image\"\n\t\t\tsrc=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/event_6g.jpg\"\n\t\t\trole=\"presentation\"\n\t\t\t\t\t\t\tsrcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/event_6g-300x170.jpg 300w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/event_6g-768x434.jpg 768w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/event_6g.jpg 800w\"\n\t\t\t\t\t\t\t\t\t\talt=\"\"\n\t\t\t\t\t\t\t\t\t\ttitle=\"event_6g\"\n\t\t\t\t\t\t\t\t\t\twidth=\"800\"\n\t\t\t\t\t\t\t\t\t\theight=\"452\"\n\t\t\t\t\t\/>\n\t<\/a>\n<\/div>\n\n\t\t<div class=\"tribe-events-pro-photo__event-details-wrapper\">\n\t\t\t<div class=\"tribe-events-pro-photo__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-pro-photo__event-date-tag-datetime\" datetime=\"2026-05-21\">\n\t\t<span class=\"tribe-events-pro-photo__event-date-tag-month\">\n\t\t\tMai\t\t<\/span>\n\t\t<span class=\"tribe-events-pro-photo__event-date-tag-daynum tribe-common-h5 tribe-common-h4--min-medium\">\n\t\t\t21\t\t<\/span>\n\t<\/time>\n<\/div>\n\t\t\t<div class=\"tribe-events-pro-photo__event-details\">\n\t\t\t\t<h3 class=\"tribe-events-pro-photo__event-title tribe-common-h6\">\n\t<a\n\t\thref=\"https:\/\/global6gsummit.com\/\"\n\t\ttitle=\"Sommet mondial de la 6G\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-pro-photo__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tSommet mondial de la 6G\t<\/a>\n<\/h3>\n\t\t\t\t<div class=\"tribe-events-pro-photo__event-datetime tribe-common-b2\">\n\t\t\t\t<span class=\"tribe-event-date-start\">mai 21<\/span> - <span class=\"tribe-event-date-end\">mai 22<\/span>\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/article>\n<\/li>\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<li  class=\"tribe-common-g-col tribe-events-pro-photo__event post-10000159 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tribe_events_cat-conference cat_conference ast-grid-common-col ast-full-width ast-article-post\" >\n\t<article>\n\t\t<div class=\"tribe-events-pro-photo__event-featured-image-wrapper\">\n\t<a\n\t\thref=\"https:\/\/www.aic.ca\/2026-conference\/\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-pro-photo__event-featured-image-link\"\n\t>\n\t\t<span class=\"tribe-events-pro-photo__event-featured-image-link-inner tribe-common-a11y-hidden\">Conf\u00e9rence AIC \u2013 Innovation agroalimentaire 2026 \u2013 L\u2019avantage unique du Canada pour b\u00e2tir la nation<\/span>\n\t\t<img\n\t\t\tclass=\"tribe-events-pro-photo__event-featured-image\"\n\t\t\tsrc=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/event_aic_2026.jpg\"\n\t\t\trole=\"presentation\"\n\t\t\t\t\t\t\tsrcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/event_aic_2026-300x170.jpg 300w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/event_aic_2026-768x434.jpg 768w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/event_aic_2026.jpg 800w\"\n\t\t\t\t\t\t\t\t\t\talt=\"\"\n\t\t\t\t\t\t\t\t\t\ttitle=\"event_aic_2026\"\n\t\t\t\t\t\t\t\t\t\twidth=\"800\"\n\t\t\t\t\t\t\t\t\t\theight=\"452\"\n\t\t\t\t\t\/>\n\t<\/a>\n<\/div>\n\n\t\t<div class=\"tribe-events-pro-photo__event-details-wrapper\">\n\t\t\t<div class=\"tribe-events-pro-photo__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-pro-photo__event-date-tag-datetime\" datetime=\"2026-05-26\">\n\t\t<span class=\"tribe-events-pro-photo__event-date-tag-month\">\n\t\t\tMai\t\t<\/span>\n\t\t<span class=\"tribe-events-pro-photo__event-date-tag-daynum tribe-common-h5 tribe-common-h4--min-medium\">\n\t\t\t26\t\t<\/span>\n\t<\/time>\n<\/div>\n\t\t\t<div class=\"tribe-events-pro-photo__event-details\">\n\t\t\t\t<h3 class=\"tribe-events-pro-photo__event-title tribe-common-h6\">\n\t<a\n\t\thref=\"https:\/\/www.aic.ca\/2026-conference\/\"\n\t\ttitle=\"Conf\u00e9rence AIC \u2013 Innovation agroalimentaire 2026 \u2013 L\u2019avantage unique du Canada pour b\u00e2tir la nation\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-pro-photo__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tConf\u00e9rence AIC \u2013 Innovation agroalimentaire 2026 \u2013 L\u2019avantage unique du Canada pour b\u00e2tir la nation\t<\/a>\n<\/h3>\n\t\t\t\t<div class=\"tribe-events-pro-photo__event-datetime tribe-common-b2\">\n\t\t\t\t<span class=\"tribe-event-date-start\">mai 26<\/span> - <span class=\"tribe-event-date-end\">mai 27<\/span>\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/article>\n<\/li>\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<li  class=\"tribe-common-g-col tribe-events-pro-photo__event post-10000147 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tribe_events_cat-atelier tribe_events_cat-formation cat_atelier cat_formation ast-grid-common-col ast-full-width ast-article-post\" >\n\t<article>\n\t\t<div class=\"tribe-events-pro-photo__event-featured-image-wrapper\">\n\t<a\n\t\thref=\"https:\/\/fabricinnovation.ca\/fr\/cmc-basecamp-active-silicon-photonics-fabrication-workshop-2026\/\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-pro-photo__event-featured-image-link\"\n\t>\n\t\t<span class=\"tribe-events-pro-photo__event-featured-image-link-inner tribe-common-a11y-hidden\">CMC basecamp\u2122 : Atelier de fabrication en photonique sur silicium active SiEPIC\u2011NUCLEUS 2026<\/span>\n\t\t<img\n\t\t\tclass=\"tribe-events-pro-photo__event-featured-image\"\n\t\t\tsrc=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/03\/event_active_photonics.jpg\"\n\t\t\trole=\"presentation\"\n\t\t\t\t\t\t\tsrcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/03\/event_active_photonics_2026-300x169.png 300w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/03\/event_active_photonics_2026-768x432.png 768w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/03\/event_active_photonics_2026.png 800w\"\n\t\t\t\t\t\t\t\t\t\talt=\"\"\n\t\t\t\t\t\t\t\t\t\ttitle=\"event_active_photonics_2026\"\n\t\t\t\t\t\t\t\t\t\twidth=\"800\"\n\t\t\t\t\t\t\t\t\t\theight=\"450\"\n\t\t\t\t\t\/>\n\t<\/a>\n<\/div>\n\n\t\t<div class=\"tribe-events-pro-photo__event-details-wrapper\">\n\t\t\t<div class=\"tribe-events-pro-photo__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-pro-photo__event-date-tag-datetime\" datetime=\"2026-05-28\">\n\t\t<span class=\"tribe-events-pro-photo__event-date-tag-month\">\n\t\t\tMai\t\t<\/span>\n\t\t<span class=\"tribe-events-pro-photo__event-date-tag-daynum tribe-common-h5 tribe-common-h4--min-medium\">\n\t\t\t28\t\t<\/span>\n\t<\/time>\n<\/div>\n\t\t\t<div class=\"tribe-events-pro-photo__event-details\">\n\t\t\t\t<h3 class=\"tribe-events-pro-photo__event-title tribe-common-h6\">\n\t<a\n\t\thref=\"https:\/\/fabricinnovation.ca\/fr\/cmc-basecamp-active-silicon-photonics-fabrication-workshop-2026\/\"\n\t\ttitle=\"CMC basecamp\u2122 : Atelier de fabrication en photonique sur silicium active SiEPIC\u2011NUCLEUS 2026\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-pro-photo__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tCMC basecamp\u2122 : Atelier de fabrication en photonique sur silicium active SiEPIC\u2011NUCLEUS 2026\t<\/a>\n<\/h3>\n\t\t\t\t<div class=\"tribe-events-pro-photo__event-datetime tribe-common-b2\">\n\t\t\t\t<span class=\"tribe-event-date-start\">mai 28 @ 9h00<\/span> - <span class=\"tribe-event-date-end\">juin 1 @ 18h00<\/span>\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/article>\n<\/li>\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<li  class=\"tribe-common-g-col tribe-events-pro-photo__event post-10000169 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tribe_events_cat-conference cat_conference ast-grid-common-col ast-full-width ast-article-post\" >\n\t<article>\n\t\t<div class=\"tribe-events-pro-photo__event-featured-image-wrapper\">\n\t<a\n\t\thref=\"https:\/\/fabricinnovation.ca\/fr\/nucleus-annual-symposium-2026\/\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-pro-photo__event-featured-image-link\"\n\t>\n\t\t<span class=\"tribe-events-pro-photo__event-featured-image-link-inner tribe-common-a11y-hidden\">Symposium annuel NUCLEUS 2026<\/span>\n\t\t<img\n\t\t\tclass=\"tribe-events-pro-photo__event-featured-image\"\n\t\t\tsrc=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/event_nucleus_symposium.jpg\"\n\t\t\trole=\"presentation\"\n\t\t\t\t\t\t\tsrcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/event_nucleus_symposium-300x170.jpg 300w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/event_nucleus_symposium-768x434.jpg 768w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/event_nucleus_symposium.jpg 800w\"\n\t\t\t\t\t\t\t\t\t\talt=\"\"\n\t\t\t\t\t\t\t\t\t\ttitle=\"event_nucleus_symposium\"\n\t\t\t\t\t\t\t\t\t\twidth=\"800\"\n\t\t\t\t\t\t\t\t\t\theight=\"452\"\n\t\t\t\t\t\/>\n\t<\/a>\n<\/div>\n\n\t\t<div class=\"tribe-events-pro-photo__event-details-wrapper\">\n\t\t\t<div class=\"tribe-events-pro-photo__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-pro-photo__event-date-tag-datetime\" datetime=\"2026-06-01\">\n\t\t<span class=\"tribe-events-pro-photo__event-date-tag-month\">\n\t\t\tJuin\t\t<\/span>\n\t\t<span class=\"tribe-events-pro-photo__event-date-tag-daynum tribe-common-h5 tribe-common-h4--min-medium\">\n\t\t\t1\t\t<\/span>\n\t<\/time>\n<\/div>\n\t\t\t<div class=\"tribe-events-pro-photo__event-details\">\n\t\t\t\t<h3 class=\"tribe-events-pro-photo__event-title tribe-common-h6\">\n\t<a\n\t\thref=\"https:\/\/fabricinnovation.ca\/fr\/nucleus-annual-symposium-2026\/\"\n\t\ttitle=\"Symposium annuel NUCLEUS 2026\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-pro-photo__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tSymposium annuel NUCLEUS 2026\t<\/a>\n<\/h3>\n\t\t\t\t<div class=\"tribe-events-pro-photo__event-datetime tribe-common-b2\">\n\t\t\t\t<time datetime=\"09:00\">\n\t\t\t9h00\t\t<\/time>\n\t\t\t\t\t<span class=\"tribe-events-events-pro-photo__event-datetime-separator\"> - <\/span>\n\t\t\t<time datetime=\"18:00\">\n\t\t\t\t18h00\t\t\t<\/time>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/article>\n<\/li>\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<li  class=\"tribe-common-g-col tribe-events-pro-photo__event post-10000068 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tribe_events_cat-conference cat_conference ast-grid-common-col ast-full-width ast-article-post\" >\n\t<article>\n\t\t<div class=\"tribe-events-pro-photo__event-featured-image-wrapper\">\n\t<a\n\t\thref=\"https:\/\/www.photonicsnorth.com\/en\/\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-pro-photo__event-featured-image-link\"\n\t>\n\t\t<span class=\"tribe-events-pro-photo__event-featured-image-link-inner tribe-common-a11y-hidden\">Photonique Nord 2026<\/span>\n\t\t<img\n\t\t\tclass=\"tribe-events-pro-photo__event-featured-image\"\n\t\t\tsrc=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/PhotonicsNorth26.jpg\"\n\t\t\trole=\"presentation\"\n\t\t\t\t\t\t\tsrcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/PhotonicsNorth26-300x169.jpg 300w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/PhotonicsNorth26-768x432.jpg 768w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/PhotonicsNorth26.jpg 800w\"\n\t\t\t\t\t\t\t\t\t\talt=\"\"\n\t\t\t\t\t\t\t\t\t\ttitle=\"PhotonicsNorth26\"\n\t\t\t\t\t\t\t\t\t\twidth=\"800\"\n\t\t\t\t\t\t\t\t\t\theight=\"450\"\n\t\t\t\t\t\/>\n\t<\/a>\n<\/div>\n\n\t\t<div class=\"tribe-events-pro-photo__event-details-wrapper\">\n\t\t\t<div class=\"tribe-events-pro-photo__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-pro-photo__event-date-tag-datetime\" datetime=\"2026-06-02\">\n\t\t<span class=\"tribe-events-pro-photo__event-date-tag-month\">\n\t\t\tJuin\t\t<\/span>\n\t\t<span class=\"tribe-events-pro-photo__event-date-tag-daynum tribe-common-h5 tribe-common-h4--min-medium\">\n\t\t\t2\t\t<\/span>\n\t<\/time>\n<\/div>\n\t\t\t<div class=\"tribe-events-pro-photo__event-details\">\n\t\t\t\t<h3 class=\"tribe-events-pro-photo__event-title tribe-common-h6\">\n\t<a\n\t\thref=\"https:\/\/www.photonicsnorth.com\/en\/\"\n\t\ttitle=\"Photonique Nord 2026\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-pro-photo__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tPhotonique Nord 2026\t<\/a>\n<\/h3>\n\t\t\t\t<div class=\"tribe-events-pro-photo__event-datetime tribe-common-b2\">\n\t\t\t\t<span class=\"tribe-event-date-start\">juin 2<\/span> - <span class=\"tribe-event-date-end\">juin 5<\/span>\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/article>\n<\/li>\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<li  class=\"tribe-common-g-col tribe-events-pro-photo__event post-10000127 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tribe_events_cat-conference cat_conference ast-grid-common-col ast-full-width ast-article-post\" >\n\t<article>\n\t\t<div class=\"tribe-events-pro-photo__event-featured-image-wrapper\">\n\t<a\n\t\thref=\"https:\/\/mms2026.soton.ac.uk\/\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-pro-photo__event-featured-image-link\"\n\t>\n\t\t<span class=\"tribe-events-pro-photo__event-featured-image-link-inner tribe-common-a11y-hidden\">MMS 2026 \u2013 29\u1d49 Sommet mondial des micromachines<\/span>\n\t\t<img\n\t\t\tclass=\"tribe-events-pro-photo__event-featured-image\"\n\t\t\tsrc=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/02\/mms2026.jpg\"\n\t\t\trole=\"presentation\"\n\t\t\t\t\t\t\tsrcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/02\/mms2026-300x169.jpg 300w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/02\/mms2026-768x432.jpg 768w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/02\/mms2026.jpg 800w\"\n\t\t\t\t\t\t\t\t\t\talt=\"\"\n\t\t\t\t\t\t\t\t\t\ttitle=\"mms2026\"\n\t\t\t\t\t\t\t\t\t\twidth=\"800\"\n\t\t\t\t\t\t\t\t\t\theight=\"450\"\n\t\t\t\t\t\/>\n\t<\/a>\n<\/div>\n\n\t\t<div class=\"tribe-events-pro-photo__event-details-wrapper\">\n\t\t\t<div class=\"tribe-events-pro-photo__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-pro-photo__event-date-tag-datetime\" datetime=\"2026-06-14\">\n\t\t<span class=\"tribe-events-pro-photo__event-date-tag-month\">\n\t\t\tJuin\t\t<\/span>\n\t\t<span class=\"tribe-events-pro-photo__event-date-tag-daynum tribe-common-h5 tribe-common-h4--min-medium\">\n\t\t\t14\t\t<\/span>\n\t<\/time>\n<\/div>\n\t\t\t<div class=\"tribe-events-pro-photo__event-details\">\n\t\t\t\t<h3 class=\"tribe-events-pro-photo__event-title tribe-common-h6\">\n\t<a\n\t\thref=\"https:\/\/mms2026.soton.ac.uk\/\"\n\t\ttitle=\"MMS 2026 \u2013 29\u1d49 Sommet mondial des micromachines\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-pro-photo__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tMMS 2026 \u2013 29\u1d49 Sommet mondial des micromachines\t<\/a>\n<\/h3>\n\t\t\t\t<div class=\"tribe-events-pro-photo__event-datetime tribe-common-b2\">\n\t\t\t\t<span class=\"tribe-event-date-start\">juin 14<\/span> - <span class=\"tribe-event-date-end\">juin 17<\/span>\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/article>\n<\/li>\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<li  class=\"tribe-common-g-col tribe-events-pro-photo__event post-10000170 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tribe_events_cat-formation tribe_events_cat-webinaire cat_formation cat_webinaire ast-grid-common-col ast-full-width ast-article-post\" >\n\t<article>\n\t\t<div class=\"tribe-events-pro-photo__event-featured-image-wrapper\">\n\t<a\n\t\thref=\"https:\/\/www.comsol.com\/events\/web-meeting\/acoustics-modeling-web-workshop-136072\/\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-pro-photo__event-featured-image-link\"\n\t>\n\t\t<span class=\"tribe-events-pro-photo__event-featured-image-link-inner tribe-common-a11y-hidden\">COMSOL : Mod\u00e9lisation acoustique<\/span>\n\t\t<img\n\t\t\tclass=\"tribe-events-pro-photo__event-featured-image\"\n\t\t\tsrc=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/event_comsol_acoustics.jpg\"\n\t\t\trole=\"presentation\"\n\t\t\t\t\t\t\tsrcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/event_comsol_acoustics-300x170.jpg 300w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/event_comsol_acoustics-768x434.jpg 768w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/04\/event_comsol_acoustics.jpg 800w\"\n\t\t\t\t\t\t\t\t\t\talt=\"\"\n\t\t\t\t\t\t\t\t\t\ttitle=\"event_comsol_acoustics\"\n\t\t\t\t\t\t\t\t\t\twidth=\"800\"\n\t\t\t\t\t\t\t\t\t\theight=\"452\"\n\t\t\t\t\t\/>\n\t<\/a>\n<\/div>\n\n\t\t<div class=\"tribe-events-pro-photo__event-details-wrapper\">\n\t\t\t<div class=\"tribe-events-pro-photo__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-pro-photo__event-date-tag-datetime\" datetime=\"2026-06-17\">\n\t\t<span class=\"tribe-events-pro-photo__event-date-tag-month\">\n\t\t\tJuin\t\t<\/span>\n\t\t<span class=\"tribe-events-pro-photo__event-date-tag-daynum tribe-common-h5 tribe-common-h4--min-medium\">\n\t\t\t17\t\t<\/span>\n\t<\/time>\n<\/div>\n\t\t\t<div class=\"tribe-events-pro-photo__event-details\">\n\t\t\t\t<h3 class=\"tribe-events-pro-photo__event-title tribe-common-h6\">\n\t<a\n\t\thref=\"https:\/\/www.comsol.com\/events\/web-meeting\/acoustics-modeling-web-workshop-136072\/\"\n\t\ttitle=\"COMSOL : Mod\u00e9lisation acoustique\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-pro-photo__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tCOMSOL : Mod\u00e9lisation acoustique\t<\/a>\n<\/h3>\n\t\t\t\t<div class=\"tribe-events-pro-photo__event-datetime tribe-common-b2\">\n\t\t\t\t<time datetime=\"14:00\">\n\t\t\t14h00\t\t<\/time>\n\t\t\t\t\t<span class=\"tribe-events-events-pro-photo__event-datetime-separator\"> - <\/span>\n\t\t\t<time datetime=\"15:30\">\n\t\t\t\t15h30\t\t\t<\/time>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/article>\n<\/li>\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<li  class=\"tribe-common-g-col tribe-events-pro-photo__event post-10000139 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tribe_events_cat-conference cat_conference ast-grid-common-col ast-full-width ast-article-post\" >\n\t<article>\n\t\t<div class=\"tribe-events-pro-photo__event-featured-image-wrapper\">\n\t<a\n\t\thref=\"https:\/\/newcas.org\/\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-pro-photo__event-featured-image-link\"\n\t>\n\t\t<span class=\"tribe-events-pro-photo__event-featured-image-link-inner tribe-common-a11y-hidden\">24e conf\u00e9rence internationale IEEE NEWCAS<\/span>\n\t\t<img\n\t\t\tclass=\"tribe-events-pro-photo__event-featured-image\"\n\t\t\tsrc=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/03\/event_newcas_2026.png\"\n\t\t\trole=\"presentation\"\n\t\t\t\t\t\t\tsrcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/03\/event_newcas_2026-300x169.png 300w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/03\/event_newcas_2026-768x432.png 768w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/03\/event_newcas_2026.png 800w\"\n\t\t\t\t\t\t\t\t\t\talt=\"\"\n\t\t\t\t\t\t\t\t\t\ttitle=\"event_newcas_2026\"\n\t\t\t\t\t\t\t\t\t\twidth=\"800\"\n\t\t\t\t\t\t\t\t\t\theight=\"450\"\n\t\t\t\t\t\/>\n\t<\/a>\n<\/div>\n\n\t\t<div class=\"tribe-events-pro-photo__event-details-wrapper\">\n\t\t\t<div class=\"tribe-events-pro-photo__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-pro-photo__event-date-tag-datetime\" datetime=\"2026-06-21\">\n\t\t<span class=\"tribe-events-pro-photo__event-date-tag-month\">\n\t\t\tJuin\t\t<\/span>\n\t\t<span class=\"tribe-events-pro-photo__event-date-tag-daynum tribe-common-h5 tribe-common-h4--min-medium\">\n\t\t\t21\t\t<\/span>\n\t<\/time>\n<\/div>\n\t\t\t<div class=\"tribe-events-pro-photo__event-details\">\n\t\t\t\t<h3 class=\"tribe-events-pro-photo__event-title tribe-common-h6\">\n\t<a\n\t\thref=\"https:\/\/newcas.org\/\"\n\t\ttitle=\"24e conf\u00e9rence internationale IEEE NEWCAS\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-pro-photo__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\t24e conf\u00e9rence internationale IEEE NEWCAS\t<\/a>\n<\/h3>\n\t\t\t\t<div class=\"tribe-events-pro-photo__event-datetime tribe-common-b2\">\n\t\t\t\t<span class=\"tribe-event-date-start\">juin 21 @ 8h00<\/span> - <span class=\"tribe-event-date-end\">juin 24 @ 17h00<\/span>\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/article>\n<\/li>\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<li  class=\"tribe-common-g-col tribe-events-pro-photo__event post-10000140 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tribe_events_cat-conference cat_conference ast-grid-common-col ast-full-width ast-article-post\" >\n\t<article>\n\t\t<div class=\"tribe-events-pro-photo__event-featured-image-wrapper\">\n\t<a\n\t\thref=\"https:\/\/event.fourwaves.com\/omn2026\/pages\/\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-pro-photo__event-featured-image-link\"\n\t>\n\t\t<span class=\"tribe-events-pro-photo__event-featured-image-link-inner tribe-common-a11y-hidden\">Conf\u00e9rence sur les MEMS optiques et la nanophotonique<\/span>\n\t\t<img\n\t\t\tclass=\"tribe-events-pro-photo__event-featured-image\"\n\t\t\tsrc=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/03\/event_omn_2026.png\"\n\t\t\trole=\"presentation\"\n\t\t\t\t\t\t\tsrcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/03\/event_omn_2026-300x169.png 300w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/03\/event_omn_2026-768x432.png 768w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/03\/event_omn_2026.png 800w\"\n\t\t\t\t\t\t\t\t\t\talt=\"\"\n\t\t\t\t\t\t\t\t\t\ttitle=\"event_omn_2026\"\n\t\t\t\t\t\t\t\t\t\twidth=\"800\"\n\t\t\t\t\t\t\t\t\t\theight=\"450\"\n\t\t\t\t\t\/>\n\t<\/a>\n<\/div>\n\n\t\t<div class=\"tribe-events-pro-photo__event-details-wrapper\">\n\t\t\t<div class=\"tribe-events-pro-photo__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-pro-photo__event-date-tag-datetime\" datetime=\"2026-08-02\">\n\t\t<span class=\"tribe-events-pro-photo__event-date-tag-month\">\n\t\t\tAo\u00fbt\t\t<\/span>\n\t\t<span class=\"tribe-events-pro-photo__event-date-tag-daynum tribe-common-h5 tribe-common-h4--min-medium\">\n\t\t\t2\t\t<\/span>\n\t<\/time>\n<\/div>\n\t\t\t<div class=\"tribe-events-pro-photo__event-details\">\n\t\t\t\t<h3 class=\"tribe-events-pro-photo__event-title tribe-common-h6\">\n\t<a\n\t\thref=\"https:\/\/event.fourwaves.com\/omn2026\/pages\/\"\n\t\ttitle=\"Conf\u00e9rence sur les MEMS optiques et la nanophotonique\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-pro-photo__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tConf\u00e9rence sur les MEMS optiques et la nanophotonique\t<\/a>\n<\/h3>\n\t\t\t\t<div class=\"tribe-events-pro-photo__event-datetime tribe-common-b2\">\n\t\t\t\t<span class=\"tribe-event-date-start\">ao\u00fbt 2 @ 8h00<\/span> - <span class=\"tribe-event-date-end\">ao\u00fbt 6 @ 17h00<\/span>\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/article>\n<\/li>\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<li  class=\"tribe-common-g-col tribe-events-pro-photo__event post-10000144 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tribe_events_cat-formation cat_formation ast-grid-common-col ast-full-width ast-article-post\" >\n\t<article>\n\t\t<div class=\"tribe-events-pro-photo__event-featured-image-wrapper\">\n\t<a\n\t\thref=\"https:\/\/sites.grenadine.uqam.ca\/sites\/facultesciences\/en\/2ndams\/home\/\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-pro-photo__event-featured-image-link\"\n\t>\n\t\t<span class=\"tribe-events-pro-photo__event-featured-image-link-inner tribe-common-a11y-hidden\">2e stage intensif canadien sur la conception de circuits int\u00e9gr\u00e9s analogiques et \u00e0 signaux mixtes<\/span>\n\t\t<img\n\t\t\tclass=\"tribe-events-pro-photo__event-featured-image\"\n\t\t\tsrc=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/03\/event_AnalogMixedSignalBootcamp.jpg\"\n\t\t\trole=\"presentation\"\n\t\t\t\t\t\t\tsrcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/03\/event_AnalogMixedSignalBootcamp-300x169.jpg 300w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/03\/event_AnalogMixedSignalBootcamp-768x432.jpg 768w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/03\/event_AnalogMixedSignalBootcamp.jpg 800w\"\n\t\t\t\t\t\t\t\t\t\talt=\"\"\n\t\t\t\t\t\t\t\t\t\ttitle=\"event_AnalogMixedSignalBootcamp\"\n\t\t\t\t\t\t\t\t\t\twidth=\"800\"\n\t\t\t\t\t\t\t\t\t\theight=\"450\"\n\t\t\t\t\t\/>\n\t<\/a>\n<\/div>\n\n\t\t<div class=\"tribe-events-pro-photo__event-details-wrapper\">\n\t\t\t<div class=\"tribe-events-pro-photo__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-pro-photo__event-date-tag-datetime\" datetime=\"2026-08-17\">\n\t\t<span class=\"tribe-events-pro-photo__event-date-tag-month\">\n\t\t\tAo\u00fbt\t\t<\/span>\n\t\t<span class=\"tribe-events-pro-photo__event-date-tag-daynum tribe-common-h5 tribe-common-h4--min-medium\">\n\t\t\t17\t\t<\/span>\n\t<\/time>\n<\/div>\n\t\t\t<div class=\"tribe-events-pro-photo__event-details\">\n\t\t\t\t<h3 class=\"tribe-events-pro-photo__event-title tribe-common-h6\">\n\t<a\n\t\thref=\"https:\/\/sites.grenadine.uqam.ca\/sites\/facultesciences\/en\/2ndams\/home\/\"\n\t\ttitle=\"2e stage intensif canadien sur la conception de circuits int\u00e9gr\u00e9s analogiques et \u00e0 signaux mixtes\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-pro-photo__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\t2e stage intensif canadien sur la conception de circuits int\u00e9gr\u00e9s analogiques et \u00e0 signaux mixtes\t<\/a>\n<\/h3>\n\t\t\t\t<div class=\"tribe-events-pro-photo__event-datetime tribe-common-b2\">\n\t\t\t\t<span class=\"tribe-event-date-start\">ao\u00fbt 17 @ 8h00<\/span> - <span class=\"tribe-event-date-end\">ao\u00fbt 21 @ 17h00<\/span>\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/article>\n<\/li>\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<li  class=\"tribe-common-g-col tribe-events-pro-photo__event post-10000130 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tribe_events_cat-conference cat_conference ast-grid-common-col ast-full-width ast-article-post\" >\n\t<article>\n\t\t<div class=\"tribe-events-pro-photo__event-featured-image-wrapper\">\n\t<a\n\t\thref=\"https:\/\/uniweb.uottawa.ca\/sites\/csstc2026\/\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-pro-photo__event-featured-image-link\"\n\t>\n\t\t<span class=\"tribe-events-pro-photo__event-featured-image-link-inner tribe-common-a11y-hidden\">21e Conf\u00e9rence canadienne sur la science et la technologie des semi-conducteurs<\/span>\n\t\t<img\n\t\t\tclass=\"tribe-events-pro-photo__event-featured-image\"\n\t\t\tsrc=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/02\/event_csstc.jpg\"\n\t\t\trole=\"presentation\"\n\t\t\t\t\t\t\tsrcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/02\/CSSTC_2026-300x169.jpg 300w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/02\/CSSTC_2026-768x432.jpg 768w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/02\/CSSTC_2026.jpg 800w\"\n\t\t\t\t\t\t\t\t\t\talt=\"\"\n\t\t\t\t\t\t\t\t\t\ttitle=\"CSSTC_2026\"\n\t\t\t\t\t\t\t\t\t\twidth=\"800\"\n\t\t\t\t\t\t\t\t\t\theight=\"450\"\n\t\t\t\t\t\/>\n\t<\/a>\n<\/div>\n\n\t\t<div class=\"tribe-events-pro-photo__event-details-wrapper\">\n\t\t\t<div class=\"tribe-events-pro-photo__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-pro-photo__event-date-tag-datetime\" datetime=\"2026-08-25\">\n\t\t<span class=\"tribe-events-pro-photo__event-date-tag-month\">\n\t\t\tAo\u00fbt\t\t<\/span>\n\t\t<span class=\"tribe-events-pro-photo__event-date-tag-daynum tribe-common-h5 tribe-common-h4--min-medium\">\n\t\t\t25\t\t<\/span>\n\t<\/time>\n<\/div>\n\t\t\t<div class=\"tribe-events-pro-photo__event-details\">\n\t\t\t\t<h3 class=\"tribe-events-pro-photo__event-title tribe-common-h6\">\n\t<a\n\t\thref=\"https:\/\/uniweb.uottawa.ca\/sites\/csstc2026\/\"\n\t\ttitle=\"21e Conf\u00e9rence canadienne sur la science et la technologie des semi-conducteurs\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-pro-photo__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\t21e Conf\u00e9rence canadienne sur la science et la technologie des semi-conducteurs\t<\/a>\n<\/h3>\n\t\t\t\t<div class=\"tribe-events-pro-photo__event-datetime tribe-common-b2\">\n\t\t\t\t<span class=\"tribe-event-date-start\">ao\u00fbt 25 @ 8h00<\/span> - <span class=\"tribe-event-date-end\">ao\u00fbt 27 @ 17h00<\/span>\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/article>\n<\/li>\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<li  class=\"tribe-common-g-col tribe-events-pro-photo__event post-10000133 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tribe_events_cat-conference cat_conference ast-grid-common-col ast-full-width ast-article-post\" >\n\t<article>\n\t\t<div class=\"tribe-events-pro-photo__event-featured-image-wrapper\">\n\t<a\n\t\thref=\"https:\/\/fabricinnovation.ca\/fr\/css2026\/\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-pro-photo__event-featured-image-link\"\n\t>\n\t\t<span class=\"tribe-events-pro-photo__event-featured-image-link-inner tribe-common-a11y-hidden\">Symposium canadien sur les semi-conducteurs 2026 \u2014 O\u00f9 la souverainet\u00e9 rencontre la prosp\u00e9rit\u00e9<\/span>\n\t\t<img\n\t\t\tclass=\"tribe-events-pro-photo__event-featured-image\"\n\t\t\tsrc=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/03\/event_css2026.jpg\"\n\t\t\trole=\"presentation\"\n\t\t\t\t\t\t\tsrcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/03\/CSS_2025-300x169.png 300w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/03\/CSS_2025-768x432.png 768w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/03\/CSS_2025.png 800w\"\n\t\t\t\t\t\t\t\t\t\talt=\"\"\n\t\t\t\t\t\t\t\t\t\ttitle=\"CSS_2025\"\n\t\t\t\t\t\t\t\t\t\twidth=\"800\"\n\t\t\t\t\t\t\t\t\t\theight=\"450\"\n\t\t\t\t\t\/>\n\t<\/a>\n<\/div>\n\n\t\t<div class=\"tribe-events-pro-photo__event-details-wrapper\">\n\t\t\t<div class=\"tribe-events-pro-photo__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-pro-photo__event-date-tag-datetime\" datetime=\"2026-10-19\">\n\t\t<span class=\"tribe-events-pro-photo__event-date-tag-month\">\n\t\t\tOct\t\t<\/span>\n\t\t<span class=\"tribe-events-pro-photo__event-date-tag-daynum tribe-common-h5 tribe-common-h4--min-medium\">\n\t\t\t19\t\t<\/span>\n\t<\/time>\n<\/div>\n\t\t\t<div class=\"tribe-events-pro-photo__event-details\">\n\t\t\t\t<h3 class=\"tribe-events-pro-photo__event-title tribe-common-h6\">\n\t<a\n\t\thref=\"https:\/\/fabricinnovation.ca\/fr\/css2026\/\"\n\t\ttitle=\"Symposium canadien sur les semi-conducteurs 2026 \u2014 O\u00f9 la souverainet\u00e9 rencontre la prosp\u00e9rit\u00e9\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-pro-photo__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tSymposium canadien sur les semi-conducteurs 2026 \u2014 O\u00f9 la souverainet\u00e9 rencontre la prosp\u00e9rit\u00e9\t<\/a>\n<\/h3>\n\t\t\t\t<div class=\"tribe-events-pro-photo__event-datetime tribe-common-b2\">\n\t\t\t\t<span class=\"tribe-event-date-start\">octobre 19<\/span> - <span class=\"tribe-event-date-end\">octobre 21<\/span>\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/article>\n<\/li>\n\n\t\t\t\t\n\t\t\t<\/ul>\n\n\t\t<\/div>\n\n\t\t<nav class=\"tribe-events-pro-photo-nav tribe-events-c-nav\" aria-label=\"Bottom \u00e9v\u00e8nements list pagination\">\n\t<ul class=\"tribe-events-c-nav__list\">\n\t\t<li class=\"tribe-events-c-nav__list-item tribe-events-c-nav__list-item--prev\">\n\t<a\n\t\thref=\"https:\/\/fabricinnovation.ca\/fr\/\u00e9v\u00e9nements\/photo\/?rest_route=%2Fwp%2Fv2%2Fpages&#038;shortcode=ca316174&#038;eventDisplay=past\"\n\t\trel=\"prev\"\n\t\tclass=\"tribe-events-c-nav__prev tribe-common-b2 tribe-common-b1--min-medium\"\n\t\tdata-js=\"tribe-events-view-link\"\n\t\taria-label=\" \u00c9v\u00e8nements pr\u00e9c\u00e9dents\"\n\t\ttitle=\" \u00c9v\u00e8nements pr\u00e9c\u00e9dents\"\n\t>\n\t\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--caret-left tribe-events-c-nav__prev-icon-svg\" \taria-hidden=\"true\"\n\tviewBox=\"0 0 10 16\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<path d=\"M9.7 14.4l-1.5 1.5L.3 8 8.2.1l1.5 1.5L3.3 8l6.4 6.4z\"\/>\n<\/svg>\n\t\t<span class=\"tribe-events-c-nav__prev-label\">\n\t\t\t <span class=\"tribe-events-c-nav__prev-label-plural tribe-common-a11y-visual-hide\">\u00c9v\u00e8nements<\/span> pr\u00e9c\u00e9dents\t\t<\/span>\n\t<\/a>\n<\/li>\n\n\t\t<li class=\"tribe-events-c-nav__list-item tribe-events-c-nav__list-item--today\">\n\t<a\n\t\thref=\"https:\/\/fabricinnovation.ca\/fr\/\u00e9v\u00e9nements\/photo\/?rest_route=%2Fwp%2Fv2%2Fpages&#038;shortcode=ca316174\"\n\t\tclass=\"tribe-events-c-nav__today tribe-common-b2\"\n\t\tdata-js=\"tribe-events-view-link\"\n\t\taria-label=\"Cliquer pour s\u00e9lectionner la date du jour\"\n\t\ttitle=\"Cliquer pour s\u00e9lectionner la date du jour\"\n\t>\n\t\tAujourd\u2019hui\t<\/a>\n<\/li>\n\n\t\t<li class=\"tribe-events-c-nav__list-item tribe-events-c-nav__list-item--next\">\n\t<button\n\t\tclass=\"tribe-events-c-nav__next tribe-common-b2 tribe-common-b1--min-medium\"\n\t\taria-label=\"\u00c9v\u00e8nements suivants\"\n\t\ttitle=\"\u00c9v\u00e8nements suivants\"\n\t\tdisabled\n\t>\n\t\t<span class=\"tribe-events-c-nav__next-label\">\n\t\t\t<span class=\"tribe-events-c-nav__next-label-plural tribe-common-a11y-visual-hide\">\u00c9v\u00e8nements<\/span> suivants\t\t<\/span>\n\t\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--caret-right tribe-events-c-nav__next-icon-svg\" \taria-hidden=\"true\"\n\tviewBox=\"0 0 10 16\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<path d=\"M.3 1.6L1.8.1 9.7 8l-7.9 7.9-1.5-1.5L6.7 8 .3 1.6z\"\/>\n<\/svg>\n\t<\/button>\n<\/li>\n\t<\/ul>\n<\/nav>\n\n\t\t<div class=\"tribe-events-c-subscribe-dropdown__container\">\n\t<div class=\"tribe-events-c-subscribe-dropdown\">\n\t\t<div class=\"tribe-common-c-btn-border tribe-events-c-subscribe-dropdown__button\">\n\t\t\t<button\n\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__button-text tribe-common-c-btn--clear\"\n\t\t\t\taria-expanded=\"false\"\n\t\t\t\taria-controls=\"tribe-events-subscribe-dropdown-content\"\n\t\t\t\taria-label=\"\"\n\t\t\t>\n\t\t\t\tS\u2019abonner au calendrier\t\t\t<\/button>\n\t\t\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--caret-down tribe-events-c-subscribe-dropdown__button-icon\" \taria-hidden=\"true\"\n\tviewBox=\"0 0 10 7\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M1.008.609L5 4.6 8.992.61l.958.958L5 6.517.05 1.566l.958-.958z\" class=\"tribe-common-c-svgicon__svg-fill\"\/>\n<\/svg>\n\t\t<\/div>\n\t\t<div id=\"tribe-events-c-subscribe-dropdown-content\" class=\"tribe-events-c-subscribe-dropdown__content\">\n\t\t\t<ul class=\"tribe-events-c-subscribe-dropdown__list\">\n\t\t\t\t\t\t\t\t\t\n<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--gcal\">\n\t<a\n\t\thref=\"https:\/\/www.google.com\/calendar\/render?cid=webcal%3A%2F%2Ffabricinnovation.ca%2Ffr%2F%3Fpost_type%3Dtribe_events%26ical%3D1%26eventDisplay%3Dlist\"\n\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\ttarget=\"_blank\"\n\t\trel=\"noopener noreferrer nofollow noindex\"\n\t>\n\t\tGoogle Agenda\t<\/a>\n<\/li>\n\t\t\t\t\t\t\t\t\t\n<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--ical\">\n\t<a\n\t\thref=\"webcal:\/\/fabricinnovation.ca\/fr\/?post_type=tribe_events&#038;ical=1&#038;eventDisplay=list\"\n\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\ttarget=\"_blank\"\n\t\trel=\"noopener noreferrer nofollow noindex\"\n\t>\n\t\tiCalendar\t<\/a>\n<\/li>\n\t\t\t\t\t\t\t\t\t\n<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--outlook-365\">\n\t<a\n\t\thref=\"https:\/\/outlook.office.com\/owa?path=\/calendar\/action\/compose&#038;rru=addsubscription&#038;url=webcal%3A%2F%2Ffabricinnovation.ca%2Ffr%2F%3Fpost_type%3Dtribe_events%26ical%3D1%26eventDisplay%3Dlist&#038;name=FABrIC+Prochains+\u00c9v\u00e8nements+\u2013+FABrIC\"\n\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\ttarget=\"_blank\"\n\t\trel=\"noopener noreferrer nofollow noindex\"\n\t>\n\t\tOutlook 365\t<\/a>\n<\/li>\n\t\t\t\t\t\t\t\t\t\n<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--outlook-live\">\n\t<a\n\t\thref=\"https:\/\/outlook.live.com\/owa?path=\/calendar\/action\/compose&#038;rru=addsubscription&#038;url=webcal%3A%2F%2Ffabricinnovation.ca%2Ffr%2F%3Fpost_type%3Dtribe_events%26ical%3D1%26eventDisplay%3Dlist&#038;name=FABrIC+Prochains+\u00c9v\u00e8nements+\u2013+FABrIC\"\n\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\ttarget=\"_blank\"\n\t\trel=\"noopener noreferrer nofollow noindex\"\n\t>\n\t\tOutlook Live\t<\/a>\n<\/li>\n\t\t\t\t\t\t\t\t\t\n<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--ics\">\n\t<a\n\t\thref=\"https:\/\/fabricinnovation.ca\/fr\/\u00e9v\u00e9nements\/photo\/?shortcode=ca316174&#038;ical=1\"\n\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\ttarget=\"_blank\"\n\t\trel=\"noopener noreferrer nofollow noindex\"\n\t>\n\t\tExporter le fichier .ics\t<\/a>\n<\/li>\n\t\t\t\t\t\t\t\t\t\n<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--outlook-ics\">\n\t<a\n\t\thref=\"https:\/\/fabricinnovation.ca\/fr\/\u00e9v\u00e9nements\/photo\/?shortcode=ca316174&#038;outlook-ical=1#038;ical=1\"\n\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\ttarget=\"_blank\"\n\t\trel=\"noopener noreferrer nofollow noindex\"\n\t>\n\t\tExporter le fichier Outlook .ics\t<\/a>\n<\/li>\n\t\t\t\t\t\t\t<\/ul>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\t\t\t<\/section>\n<\/div>\n\n<script data-js='tribe-events-view-nonce-data' type='application\/json'>{\"tvn1\":\"fad349d8d0\",\"tvn2\":\"\"}<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f91ee79 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-tec_elementor_widget_events_list_widget\" data-id=\"f91ee79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tec_elementor_widget_events_list_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"tribe-compatibility-container\" >\n\t<div\n\t\t class=\"tribe-common tribe-events tribe-events-view tribe-events-view--widget-events-list tribe-events-widget\" \t\tdata-js=\"tribe-events-view\"\n\t\tdata-view-rest-url=\"https:\/\/fabricinnovation.ca\/fr\/wp-json\/tribe\/views\/v2\/html\"\n\t\tdata-view-manage-url=\"1\"\n\t\t\t\t\t\t\tdata-view-breakpoint-pointer=\"ac4d218a-ceb3-4015-872c-38f0b35bd862\"\n\t\t\t>\n\t\t<div class=\"tribe-events-widget-events-list\">\n\n\t\t\t\n\t\t\t<script data-js=\"tribe-events-view-data\" type=\"application\/json\">\n\t{\"slug\":\"widget-events-list\",\"prev_url\":\"\",\"next_url\":\"\",\"view_class\":\"Tribe\\\\Events\\\\Views\\\\V2\\\\Views\\\\Widgets\\\\Widget_List_View\",\"view_slug\":\"widget-events-list\",\"view_label\":\"View\",\"view\":null,\"should_manage_url\":true,\"id\":null,\"alias-slugs\":null,\"title\":\"\\u00c9v\\u00e8nements depuis mai 13 \\u2013 octobre 19 \\u2013 FABrIC\",\"limit\":\"100\",\"no_upcoming_events\":false,\"featured_events_only\":null,\"jsonld_enable\":false,\"tribe_is_list_widget\":true,\"admin_fields\":{\"title\":{\"label\":\"Titre\\u00a0:\",\"type\":\"text\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-title\",\"name\":\"widget-tribe-widget-events-list[-1][title]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"limit\":{\"label\":\"Afficher\\u00a0:\",\"type\":\"number\",\"default\":5,\"min\":1,\"max\":10,\"step\":1,\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-limit\",\"name\":\"widget-tribe-widget-events-list[-1][limit]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"metadata_section\":{\"type\":\"fieldset\",\"classes\":\"tribe-common-form-control-checkbox-checkbox-group\",\"label\":\"Affichage\",\"children\":{\"cost\":{\"type\":\"checkbox\",\"label\":\"Prix\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-cost\",\"name\":\"widget-tribe-widget-events-list[-1][cost]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"venue\":{\"type\":\"checkbox\",\"label\":\"Emplacement\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-venue\",\"name\":\"widget-tribe-widget-events-list[-1][venue]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"street\":{\"type\":\"checkbox\",\"label\":\"Rue\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-street\",\"name\":\"widget-tribe-widget-events-list[-1][street]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"city\":{\"type\":\"checkbox\",\"label\":\"Ville\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-city\",\"name\":\"widget-tribe-widget-events-list[-1][city]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"region\":{\"type\":\"checkbox\",\"label\":\"\\u00c9tat (US) ou Province (Int.)\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-region\",\"name\":\"widget-tribe-widget-events-list[-1][region]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"zip\":{\"type\":\"checkbox\",\"label\":\"Code Postal\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-zip\",\"name\":\"widget-tribe-widget-events-list[-1][zip]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"country\":{\"type\":\"checkbox\",\"label\":\"Pays\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-country\",\"name\":\"widget-tribe-widget-events-list[-1][country]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"phone\":{\"type\":\"checkbox\",\"label\":\"Num. de tel.\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-phone\",\"name\":\"widget-tribe-widget-events-list[-1][phone]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"organizer\":{\"type\":\"checkbox\",\"label\":\"Organisateur\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-organizer\",\"name\":\"widget-tribe-widget-events-list[-1][organizer]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"website\":{\"type\":\"checkbox\",\"label\":\"Site internet\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-website\",\"name\":\"widget-tribe-widget-events-list[-1][website]\",\"options\":[],\"placeholder\":\"\",\"value\":null}},\"parent_classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-metadata_section\",\"name\":\"widget-tribe-widget-events-list[-1][metadata_section]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"taxonomy_section\":{\"type\":\"section\",\"classes\":[\"calendar-widget-filters-container\"],\"label\":\"Filtres:\",\"children\":{\"filters\":{\"type\":\"taxonomy-filters\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-filters\",\"label\":\"\",\"name\":\"widget-tribe-widget-events-list[-1][filters]\",\"options\":[],\"placeholder\":\"\",\"value\":null,\"list_items\":[]},\"operand\":{\"type\":\"fieldset\",\"classes\":\"tribe-common-form-control-checkbox-radio-group\",\"label\":\"Op\\u00e9rande:\",\"selected\":\"OR\",\"children\":[{\"type\":\"radio\",\"label\":\"Match any\",\"button_value\":\"OR\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-operand\",\"name\":\"widget-tribe-widget-events-list[-1][operand]\",\"options\":[],\"placeholder\":\"\",\"value\":null},{\"type\":\"radio\",\"label\":\"Match all\",\"button_value\":\"AND\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-operand\",\"name\":\"widget-tribe-widget-events-list[-1][operand]\",\"options\":[],\"placeholder\":\"\",\"value\":null}],\"parent_classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-operand\",\"name\":\"widget-tribe-widget-events-list[-1][operand]\",\"options\":[],\"placeholder\":\"\",\"value\":null}},\"parent_classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-taxonomy_section\",\"name\":\"widget-tribe-widget-events-list[-1][taxonomy_section]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"taxonomy\":{\"type\":\"taxonomy\",\"classes\":\"calendar-widget-add-filter\",\"label\":\"Ajouter un filtre:\",\"placeholder\":\"Choisir une Classification\",\"parent_classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-taxonomy\",\"name\":\"widget-tribe-widget-events-list[-1][taxonomy]\",\"options\":[],\"value\":null},\"no_upcoming_events\":{\"label\":\"Cacher ce widget s\\u2019il n\\u2019y a pas d\\u2019\\u00e9v\\u00e8nements \\u00e0 venir.\",\"type\":\"checkbox\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-no_upcoming_events\",\"name\":\"widget-tribe-widget-events-list[-1][no_upcoming_events]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"featured_events_only\":{\"label\":\"Limiter uniquement pour les \\u00e9v\\u00e8nements mis en avant\",\"type\":\"checkbox\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-featured_events_only\",\"name\":\"widget-tribe-widget-events-list[-1][featured_events_only]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"jsonld_enable\":{\"label\":\"G\\u00e9n\\u00e9rer les donn\\u00e9es JSON-LD\",\"type\":\"checkbox\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-jsonld_enable\",\"name\":\"widget-tribe-widget-events-list[-1][jsonld_enable]\",\"options\":[],\"placeholder\":\"\",\"value\":null}},\"venue\":\"no\",\"country\":\"no\",\"street\":\"no\",\"city\":\"no\",\"region\":\"no\",\"zip\":\"no\",\"phone\":\"no\",\"cost\":\"no\",\"organizer\":\"no\",\"website\":\"\",\"operand\":\"OR\",\"filters\":{\"post_tag\":\"\",\"tribe_events_cat\":\"\"},\"address\":false,\"events\":[10000163,10000167,10000162,10000159,10000147,10000169,10000068,10000127,10000170,10000139,10000140,10000144,10000130,10000133],\"url\":\"https:\\\/\\\/fabricinnovation.ca\\\/fr\\\/?post_type=tribe_events&eventDisplay=widget-events-list\",\"url_event_date\":false,\"bar\":{\"keyword\":\"\",\"date\":\"\"},\"today\":\"2026-05-13 00:00:00\",\"now\":\"2026-05-13 11:35:06\",\"home_url\":\"https:\\\/\\\/fabricinnovation.ca\\\/fr\\\/\",\"rest_url\":\"https:\\\/\\\/fabricinnovation.ca\\\/fr\\\/wp-json\\\/tribe\\\/views\\\/v2\\\/html\",\"rest_method\":\"GET\",\"rest_nonce\":\"\",\"today_url\":\"https:\\\/\\\/fabricinnovation.ca\\\/fr\\\/?post_type=tribe_events&eventDisplay=widget-events-list&rest_route=%2Fwp%2Fv2%2Fpages\",\"today_title\":\"Cliquer pour s\\u00e9lectionner la date du jour\",\"today_label\":\"Aujourd\\u2019hui\",\"prev_label\":\"\",\"next_label\":\"\",\"date_formats\":{\"compact\":\"n\\\/j\\\/Y\",\"month_and_year_compact\":\"n\\\/Y\",\"month_and_year\":\"F Y\",\"time_range_separator\":\" - \",\"date_time_separator\":\" @ \"},\"messages\":[],\"start_of_week\":\"1\",\"header_title\":\"\",\"header_title_element\":\"h1\",\"content_title\":\"\",\"show_content_title\":false,\"breadcrumbs\":[],\"backlink\":false,\"before_events\":\"\",\"after_events\":\"\\n<!--\\nThis calendar is powered by The Events Calendar.\\nhttp:\\\/\\\/evnt.is\\\/18wn\\n-->\\n\",\"display_events_bar\":false,\"disable_event_search\":true,\"live_refresh\":true,\"ical\":{\"display_link\":true,\"link\":{\"url\":\"https:\\\/\\\/fabricinnovation.ca\\\/fr\\\/?post_type=tribe_events&#038;eventDisplay=widget-events-list&#038;ical=1\",\"text\":\"Exporter \\u00c9v\\u00e8nements\",\"title\":\"Utilisez ceci pour partager les donn\\u00e9es de calendrier avec Google Calendar, Apple iCal et d\\u2019autres applications compatibles\"}},\"container_classes\":[\"tribe-common\",\"tribe-events\",\"tribe-events-view\",\"tribe-events-view--widget-events-list\",\"tribe-events-widget\"],\"container_data\":[],\"is_past\":false,\"breakpoints\":{\"xsmall\":500,\"medium\":768,\"full\":960},\"breakpoint_pointer\":\"ac4d218a-ceb3-4015-872c-38f0b35bd862\",\"is_initial_load\":false,\"public_views\":{\"list\":{\"view_class\":\"Tribe\\\\Events\\\\Views\\\\V2\\\\Views\\\\List_View\",\"view_url\":\"https:\\\/\\\/fabricinnovation.ca\\\/fr\\\/\\u00e9v\\u00e9nements\\\/liste\\\/\",\"view_label\":\"Liste\",\"aria_label\":\"Display \\u00c9v\\u00e8nements in Liste View\"},\"month\":{\"view_class\":\"Tribe\\\\Events\\\\Views\\\\V2\\\\Views\\\\Month_View\",\"view_url\":\"https:\\\/\\\/fabricinnovation.ca\\\/fr\\\/\\u00e9v\\u00e9nements\\\/mois\\\/\",\"view_label\":\"Mois\",\"aria_label\":\"Display \\u00c9v\\u00e8nements in Mois View\"},\"day\":{\"view_class\":\"Tribe\\\\Events\\\\Views\\\\V2\\\\Views\\\\Day_View\",\"view_url\":\"https:\\\/\\\/fabricinnovation.ca\\\/fr\\\/\\u00e9v\\u00e9nements\\\/aujourd\\u2019hui\\\/\",\"view_label\":\"Jour\",\"aria_label\":\"Display \\u00c9v\\u00e8nements in Jour View\"}},\"show_latest_past\":false,\"past\":false,\"category_colors_enabled\":false,\"category_colors_category_dropdown\":[{\"slug\":\"workshop\",\"name\":\"Workshop\",\"priority\":2,\"primary\":\"#373869\",\"hidden\":false},{\"slug\":\"webinar\",\"name\":\"Webinar\",\"priority\":1,\"primary\":\"#373869\",\"hidden\":false},{\"slug\":\"conference\",\"name\":\"Conference\",\"priority\":0,\"primary\":\"#0092cc\",\"hidden\":false},{\"slug\":\"training\",\"name\":\"Training\",\"priority\":0,\"primary\":\"#373869\",\"hidden\":false}],\"category_colors_super_power\":false,\"category_colors_show_reset_button\":false,\"compatibility_classes\":[\"tribe-compatibility-container\"],\"view_more_text\":\"Voir le calendrier\",\"view_more_title\":\"Voir plus d\\u2019\\u00e9v\\u00e8nements.\",\"view_more_link\":\"https:\\\/\\\/fabricinnovation.ca\\\/fr\\\/\\u00e9v\\u00e9nements\\\/\",\"widget_title\":\"\",\"hide_if_no_upcoming_events\":false,\"display\":{\"cost\":false,\"venue\":false,\"street\":false,\"city\":false,\"region\":false,\"zip\":false,\"country\":false,\"phone\":false,\"organizer\":false,\"website\":false},\"subscribe_links\":{\"gcal\":{\"label\":\"Google Agenda\",\"single_label\":\"Ajouter \\u00e0 Google Agenda\",\"visible\":true,\"block_slug\":\"hasGoogleCalendar\"},\"ical\":{\"label\":\"iCalendar\",\"single_label\":\"Ajouter \\u00e0 iCalendar\",\"visible\":true,\"block_slug\":\"hasiCal\"},\"outlook-365\":{\"label\":\"Outlook 365\",\"single_label\":\"Outlook 365\",\"visible\":true,\"block_slug\":\"hasOutlook365\"},\"outlook-live\":{\"label\":\"Outlook Live\",\"single_label\":\"Outlook Live\",\"visible\":true,\"block_slug\":\"hasOutlookLive\"},\"ics\":{\"label\":\"Exporter le fichier .ics\",\"single_label\":\"Exporter le fichier .ics\",\"visible\":true,\"block_slug\":null},\"outlook-ics\":{\"label\":\"Exporter le fichier Outlook .ics\",\"single_label\":\"Exporter le fichier Outlook .ics\",\"visible\":true,\"block_slug\":null}},\"display_recurring_toggle\":false,\"_context\":{\"slug\":\"widget-events-list\"}}<\/script>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<div class=\"tribe-events-widget-events-list__events\">\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-05-20\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tMai\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t20\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10000163 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tribe_events_cat-conference cat_conference\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-05-20\">\n\t\tToute la journ\u00e9e\t<\/time>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/connectingcanada.vfairs.com\/\"\n\t\ttitle=\"Pour un Canada connect\u00e9: objectifs, pressions et priorit\u00e9s du secteur des t\u00e9l\u00e9communications du Canada\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tPour un Canada connect\u00e9: objectifs, pressions et priorit\u00e9s du secteur des t\u00e9l\u00e9communications du Canada\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-05-20\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tMai\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t20\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10000167 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tribe_events_cat-atelier tribe_events_cat-formation cat_conference\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-05-20\">\n\t\t<span class=\"tribe-event-date-start\">14h00<\/span> - <span class=\"tribe-event-time\">15h30<\/span>\t<\/time>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/www.comsol.com\/events\/web-meeting\/rf-and-wave-optics-modeling-web-workshop-136062\/\"\n\t\ttitle=\"COMSOL : mod\u00e9lisation RF et optique des ondes\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tCOMSOL : mod\u00e9lisation RF et optique des ondes\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-05-21\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tMai\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t21\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10000162 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tribe_events_cat-conference cat_conference\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-05-21\">\n\t\t<span class=\"tribe-event-date-start\">mai 21<\/span> - <span class=\"tribe-event-date-end\">mai 22<\/span>\t<\/time>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/global6gsummit.com\/\"\n\t\ttitle=\"Sommet mondial de la 6G\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tSommet mondial de la 6G\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-05-26\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tMai\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t26\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10000159 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tribe_events_cat-conference cat_conference\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-05-26\">\n\t\t<span class=\"tribe-event-date-start\">mai 26<\/span> - <span class=\"tribe-event-date-end\">mai 27<\/span>\t<\/time>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/www.aic.ca\/2026-conference\/\"\n\t\ttitle=\"Conf\u00e9rence AIC \u2013 Innovation agroalimentaire 2026 \u2013 L\u2019avantage unique du Canada pour b\u00e2tir la nation\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tConf\u00e9rence AIC \u2013 Innovation agroalimentaire 2026 \u2013 L\u2019avantage unique du Canada pour b\u00e2tir la nation\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-05-28\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tMai\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t28\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10000147 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tribe_events_cat-atelier tribe_events_cat-formation cat_conference\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-05-28\">\n\t\t<span class=\"tribe-event-date-start\">mai 28 @ 9h00<\/span> - <span class=\"tribe-event-date-end\">juin 1 @ 18h00<\/span>\t<\/time>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/fabricinnovation.ca\/fr\/cmc-basecamp-active-silicon-photonics-fabrication-workshop-2026\/\"\n\t\ttitle=\"CMC basecamp\u2122 : Atelier de fabrication en photonique sur silicium active SiEPIC\u2011NUCLEUS 2026\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tCMC basecamp\u2122 : Atelier de fabrication en photonique sur silicium active SiEPIC\u2011NUCLEUS 2026\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-06-01\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tJuin\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t1\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10000169 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tribe_events_cat-conference cat_conference\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-06-01\">\n\t\t<span class=\"tribe-event-date-start\">9h00<\/span> - <span class=\"tribe-event-time\">18h00<\/span>\t<\/time>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/fabricinnovation.ca\/fr\/nucleus-annual-symposium-2026\/\"\n\t\ttitle=\"Symposium annuel NUCLEUS 2026\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tSymposium annuel NUCLEUS 2026\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-06-02\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tJuin\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t2\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10000068 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tribe_events_cat-conference cat_conference\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-06-02\">\n\t\t<span class=\"tribe-event-date-start\">juin 2<\/span> - <span class=\"tribe-event-date-end\">juin 5<\/span>\t<\/time>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/www.photonicsnorth.com\/en\/\"\n\t\ttitle=\"Photonique Nord 2026\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tPhotonique Nord 2026\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-06-14\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tJuin\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t14\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10000127 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tribe_events_cat-conference cat_conference\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-06-14\">\n\t\t<span class=\"tribe-event-date-start\">juin 14<\/span> - <span class=\"tribe-event-date-end\">juin 17<\/span>\t<\/time>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/mms2026.soton.ac.uk\/\"\n\t\ttitle=\"MMS 2026 \u2013 29\u1d49 Sommet mondial des micromachines\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tMMS 2026 \u2013 29\u1d49 Sommet mondial des micromachines\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-06-17\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tJuin\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t17\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10000170 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tribe_events_cat-formation tribe_events_cat-webinaire cat_conference\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-06-17\">\n\t\t<span class=\"tribe-event-date-start\">14h00<\/span> - <span class=\"tribe-event-time\">15h30<\/span>\t<\/time>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/www.comsol.com\/events\/web-meeting\/acoustics-modeling-web-workshop-136072\/\"\n\t\ttitle=\"COMSOL : Mod\u00e9lisation acoustique\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tCOMSOL : Mod\u00e9lisation acoustique\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-06-21\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tJuin\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t21\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10000139 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tribe_events_cat-conference cat_conference\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-06-21\">\n\t\t<span class=\"tribe-event-date-start\">juin 21 @ 8h00<\/span> - <span class=\"tribe-event-date-end\">juin 24 @ 17h00<\/span>\t<\/time>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/newcas.org\/\"\n\t\ttitle=\"24e conf\u00e9rence internationale IEEE NEWCAS\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\t24e conf\u00e9rence internationale IEEE NEWCAS\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-08-02\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tAo\u00fbt\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t2\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10000140 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tribe_events_cat-conference cat_conference\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-08-02\">\n\t\t<span class=\"tribe-event-date-start\">ao\u00fbt 2 @ 8h00<\/span> - <span class=\"tribe-event-date-end\">ao\u00fbt 6 @ 17h00<\/span>\t<\/time>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/event.fourwaves.com\/omn2026\/pages\/\"\n\t\ttitle=\"Conf\u00e9rence sur les MEMS optiques et la nanophotonique\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tConf\u00e9rence sur les MEMS optiques et la nanophotonique\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-08-17\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tAo\u00fbt\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t17\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10000144 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tribe_events_cat-formation cat_conference\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-08-17\">\n\t\t<span class=\"tribe-event-date-start\">ao\u00fbt 17 @ 8h00<\/span> - <span class=\"tribe-event-date-end\">ao\u00fbt 21 @ 17h00<\/span>\t<\/time>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/sites.grenadine.uqam.ca\/sites\/facultesciences\/en\/2ndams\/home\/\"\n\t\ttitle=\"2e stage intensif canadien sur la conception de circuits int\u00e9gr\u00e9s analogiques et \u00e0 signaux mixtes\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\t2e stage intensif canadien sur la conception de circuits int\u00e9gr\u00e9s analogiques et \u00e0 signaux mixtes\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-08-25\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tAo\u00fbt\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t25\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10000130 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tribe_events_cat-conference cat_conference\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-08-25\">\n\t\t<span class=\"tribe-event-date-start\">ao\u00fbt 25 @ 8h00<\/span> - <span class=\"tribe-event-date-end\">ao\u00fbt 27 @ 17h00<\/span>\t<\/time>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/uniweb.uottawa.ca\/sites\/csstc2026\/\"\n\t\ttitle=\"21e Conf\u00e9rence canadienne sur la science et la technologie des semi-conducteurs\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\t21e Conf\u00e9rence canadienne sur la science et la technologie des semi-conducteurs\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-10-19\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tOct\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t19\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10000133 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tribe_events_cat-conference cat_conference\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-10-19\">\n\t\t<span class=\"tribe-event-date-start\">octobre 19<\/span> - <span class=\"tribe-event-date-end\">octobre 21<\/span>\t<\/time>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/fabricinnovation.ca\/fr\/css2026\/\"\n\t\ttitle=\"Symposium canadien sur les semi-conducteurs 2026 \u2014 O\u00f9 la souverainet\u00e9 rencontre la prosp\u00e9rit\u00e9\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tSymposium canadien sur les semi-conducteurs 2026 \u2014 O\u00f9 la souverainet\u00e9 rencontre la prosp\u00e9rit\u00e9\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"tribe-events-widget-events-list__view-more tribe-common-b1 tribe-common-b2--min-medium\">\n\t<a\n\t\thref=\"https:\/\/fabricinnovation.ca\/fr\/\u00e9v\u00e9nements\/\"\n\t\tclass=\"tribe-events-widget-events-list__view-more-link tribe-common-anchor-thin\"\n\t\ttitle=\"Voir plus d\u2019\u00e9v\u00e8nements.\"\n\t>\n\t\tVoir le calendrier\t<\/a>\n<\/div>\n\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<script data-js='tribe-events-view-nonce-data' type='application\/json'>{\"tvn1\":\"fad349d8d0\",\"tvn2\":\"\"}<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>15 events found. Events Views Navigation Event Views Navigation Photo List Month Day Today Upcoming Upcoming Select date. List of events in Photo View The Role of MEMS in the [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-4104","page","type-page","status-publish","hentry","cat_conference"],"acf":[],"featured_image_src":null,"featured_image_src_square":null,"_links":{"self":[{"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/pages\/4104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/comments?post=4104"}],"version-history":[{"count":0,"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/pages\/4104\/revisions"}],"wp:attachment":[{"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/media?parent=4104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":4535,"date":"2025-11-25T21:23:16","date_gmt":"2025-11-26T02:23:16","guid":{"rendered":"https:\/\/fabricinnovation.ca\/highlights-acss\/"},"modified":"2026-03-24T09:32:24","modified_gmt":"2026-03-24T14:32:24","slug":"highlights-acss","status":"publish","type":"page","link":"https:\/\/fabricinnovation.ca\/fr\/highlights-acss\/","title":{"rendered":"Points saillants"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4535\" class=\"elementor elementor-4535 elementor-3677\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d2ed9b2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d2ed9b2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8a88636\" data-id=\"8a88636\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-771e6e5 elementor-widget elementor-widget-spacer\" data-id=\"771e6e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6261673\" data-id=\"6261673\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2866307 elementor-widget elementor-widget-spacer\" data-id=\"2866307\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5767c03\" data-id=\"5767c03\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;background_motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-caafc36 elementor-widget__width-initial elementor-widget elementor-widget-spacer\" data-id=\"caafc36\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-85008e2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"85008e2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a73a060\" data-id=\"a73a060\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-97085ae elementor-widget elementor-widget-heading\" data-id=\"97085ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\"><b>Acc\u00e9l\u00e9r\u00e9.<\/b> Symposium canadien sur les semi-conducteurs 2025.<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de2881d elementor-widget elementor-widget-heading\" data-id=\"de2881d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Points saillants<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6e713ca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6e713ca\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3dc1e08\" data-id=\"3dc1e08\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5706120 elementor-widget elementor-widget-template\" data-id=\"5706120\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"2993\" class=\"elementor elementor-2993\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f97ecfc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f97ecfc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1aa2fb9\" data-id=\"1aa2fb9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef95ed6 elementor-nav-menu__align-center elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"ef95ed6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-underline e--animation-fade\">\n\t\t\t\t<ul id=\"menu-1-ef95ed6\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3015\"><a href=\"https:\/\/fabricinnovation.ca\/accelerated\/\" class=\"elementor-item menu-link\">Acc\u00e9l\u00e9r\u00e9<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4359\"><a href=\"https:\/\/fabricinnovation.ca\/highlights-acss\/\" class=\"elementor-item menu-link\">Points saillants<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3013\"><a href=\"https:\/\/fabricinnovation.ca\/accelerated\/about-acss\/\" class=\"elementor-item menu-link\">\u00c0 Propos<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3069\"><a href=\"https:\/\/fabricinnovation.ca\/accelerated\/agenda\/\" class=\"elementor-item menu-link\">Programme<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3012\"><a href=\"https:\/\/fabricinnovation.ca\/accelerated\/speakers\/\" class=\"elementor-item menu-link\">Conf\u00e9renciers<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3014\"><a href=\"https:\/\/fabricinnovation.ca\/texpo-2025\/\" class=\"elementor-item menu-link\">TEXPO 2025<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3496\"><a href=\"https:\/\/fabricinnovation.ca\/facility-tours\/\" class=\"elementor-item menu-link\">Visites d&rsquo;installations<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Permuter le menu\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-ef95ed6\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3015\"><a href=\"https:\/\/fabricinnovation.ca\/accelerated\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Acc\u00e9l\u00e9r\u00e9<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4359\"><a href=\"https:\/\/fabricinnovation.ca\/highlights-acss\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Points saillants<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3013\"><a href=\"https:\/\/fabricinnovation.ca\/accelerated\/about-acss\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">\u00c0 Propos<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3069\"><a href=\"https:\/\/fabricinnovation.ca\/accelerated\/agenda\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Programme<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3012\"><a href=\"https:\/\/fabricinnovation.ca\/accelerated\/speakers\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Conf\u00e9renciers<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3014\"><a href=\"https:\/\/fabricinnovation.ca\/texpo-2025\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">TEXPO 2025<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3496\"><a href=\"https:\/\/fabricinnovation.ca\/facility-tours\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Visites d&rsquo;installations<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba91426 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ba91426\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-88633fa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"88633fa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2e47022\" data-id=\"2e47022\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5147911 elementor-widget elementor-widget-heading\" data-id=\"5147911\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Points saillants<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-528fb43 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"528fb43\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-417281c\" data-id=\"417281c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-06dbe0d elementor-widget elementor-widget-gallery\" data-id=\"06dbe0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;gallery_layout&quot;:&quot;masonry&quot;,&quot;columns_tablet&quot;:3,&quot;columns_mobile&quot;:2,&quot;lazyload&quot;:&quot;yes&quot;,&quot;columns&quot;:4,&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;file&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/CeesDOpeningReception-154-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDUxNywidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9DZWVzRE9wZW5pbmdSZWNlcHRpb24tMTU0LXNjYWxlZC5qcGciLCJzbGlkZXNob3ciOiIwNmRiZTBkIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/CeesDOpeningReception-154-768x587.jpg\" data-width=\"768\" data-height=\"587\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Listening-Day2-060-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDQ5NSwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9MaXN0ZW5pbmctRGF5Mi0wNjAtc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6IjA2ZGJlMGQifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Listening-Day2-060-768x419.jpg\" data-width=\"768\" data-height=\"419\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/RAY27342.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDQ4NCwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9SQVkyNzM0Mi5qcGciLCJzbGlkZXNob3ciOiIwNmRiZTBkIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/RAY27342-768x512.jpg\" data-width=\"768\" data-height=\"512\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/AcceleratedDay1_Quantum-342-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDUyNywidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9BY2NlbGVyYXRlZERheTFfUXVhbnR1bS0zNDItc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6IjA2ZGJlMGQifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/AcceleratedDay1_Quantum-342-768x430.jpg\" data-width=\"768\" data-height=\"430\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Students-OpeningReception-068-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDQ4MiwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9TdHVkZW50cy1PcGVuaW5nUmVjZXB0aW9uLTA2OC1zY2FsZWQuanBnIiwic2xpZGVzaG93IjoiMDZkYmUwZCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Students-OpeningReception-068-768x834.jpg\" data-width=\"768\" data-height=\"834\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Attentive-Day1-043-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDUyNSwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9BdHRlbnRpdmUtRGF5MS0wNDMtc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6IjA2ZGJlMGQifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Attentive-Day1-043-768x512.jpg\" data-width=\"768\" data-height=\"512\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Inference_at_the_Edge_27342.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDUwMiwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9JbmZlcmVuY2VfYXRfdGhlX0VkZ2VfMjczNDIuanBnIiwic2xpZGVzaG93IjoiMDZkYmUwZCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Inference_at_the_Edge_27342-768x477.jpg\" data-width=\"768\" data-height=\"477\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/interesting-Day2-273-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDUwMCwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9pbnRlcmVzdGluZy1EYXkyLTI3My1zY2FsZWQuanBnIiwic2xpZGVzaG93IjoiMDZkYmUwZCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/interesting-Day2-273-768x403.jpg\" data-width=\"768\" data-height=\"403\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Wei-AJP-Day1-382-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDUzMywidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9XZWktQUpQLURheTEtMzgyLXNjYWxlZC5qcGciLCJzbGlkZXNob3ciOiIwNmRiZTBkIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Wei-AJP-Day1-382-768x509.jpg\" data-width=\"768\" data-height=\"509\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Nice-Day2-188-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDQ4OSwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9OaWNlLURheTItMTg4LXNjYWxlZC5qcGciLCJzbGlkZXNob3ciOiIwNmRiZTBkIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Nice-Day2-188-768x449.jpg\" data-width=\"768\" data-height=\"449\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Avinash-OpeningReception-0019-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDUyMiwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9BdmluYXNoLU9wZW5pbmdSZWNlcHRpb24tMDAxOS1zY2FsZWQuanBnIiwic2xpZGVzaG93IjoiMDZkYmUwZCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Avinash-OpeningReception-0019-768x578.jpg\" data-width=\"768\" data-height=\"578\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/ErikH-talkig-Day1-152-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDUwNywidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9FcmlrSC10YWxraWctRGF5MS0xNTItc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6IjA2ZGJlMGQifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/ErikH-talkig-Day1-152-768x451.jpg\" data-width=\"768\" data-height=\"451\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/CMC-Paish-smiles-Day2-192-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDUxMSwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9DTUMtUGFpc2gtc21pbGVzLURheTItMTkyLXNjYWxlZC5qcGciLCJzbGlkZXNob3ciOiIwNmRiZTBkIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/CMC-Paish-smiles-Day2-192-768x544.jpg\" data-width=\"768\" data-height=\"544\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Chami-Debjani-Day2-258-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDUxNSwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9DaGFtaS1EZWJqYW5pLURheTItMjU4LXNjYWxlZC5qcGciLCJzbGlkZXNob3ciOiIwNmRiZTBkIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Chami-Debjani-Day2-258-768x402.jpg\" data-width=\"768\" data-height=\"402\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Juilien-Day2-345-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDQ5OSwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9KdWlsaWVuLURheTItMzQ1LXNjYWxlZC5qcGciLCJzbGlkZXNob3ciOiIwNmRiZTBkIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Juilien-Day2-345-768x596.jpg\" data-width=\"768\" data-height=\"596\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/MikeS-Velko-TCC-Day1-385-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDQ5MCwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9NaWtlUy1WZWxrby1UQ0MtRGF5MS0zODUtc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6IjA2ZGJlMGQifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/MikeS-Velko-TCC-Day1-385-768x512.jpg\" data-width=\"768\" data-height=\"512\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/ChrisDoosy-Day2-037-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDUxMywidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9DaHJpc0Rvb3N5LURheTItMDM3LXNjYWxlZC5qcGciLCJzbGlkZXNob3ciOiIwNmRiZTBkIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/ChrisDoosy-Day2-037-768x455.jpg\" data-width=\"768\" data-height=\"455\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/2.JeromeB-Qubic-Day1-418-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDUzMSwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC8yLkplcm9tZUItUXViaWMtRGF5MS00MTgtc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6IjA2ZGJlMGQifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/2.JeromeB-Qubic-Day1-418-768x716.jpg\" data-width=\"768\" data-height=\"716\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/4A-MikeSDay1-435-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDUyOSwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC80QS1NaWtlU0RheTEtNDM1LXNjYWxlZC5qcGciLCJzbGlkZXNob3ciOiIwNmRiZTBkIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/4A-MikeSDay1-435-768x485.jpg\" data-width=\"768\" data-height=\"485\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/AcceleratedDay2-208-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDUzNCwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9BY2NlbGVyYXRlZERheTItMjA4LXNjYWxlZC5qcGciLCJzbGlkZXNob3ciOiIwNmRiZTBkIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/AcceleratedDay2-208-768x816.jpg\" data-width=\"768\" data-height=\"816\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/PawnaLitt-Day2-125-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDQ4NywidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9QYXduYUxpdHQtRGF5Mi0xMjUtc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6IjA2ZGJlMGQifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/PawnaLitt-Day2-125-768x552.jpg\" data-width=\"768\" data-height=\"552\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Vanessa-2-Day1-041-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDQ4MCwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9WYW5lc3NhLTItRGF5MS0wNDEtc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6IjA2ZGJlMGQifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Vanessa-2-Day1-041-768x735.jpg\" data-width=\"768\" data-height=\"735\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/3.AndreFDay1-427-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDUzMCwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC8zLkFuZHJlRkRheTEtNDI3LXNjYWxlZC5qcGciLCJzbGlkZXNob3ciOiIwNmRiZTBkIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/3.AndreFDay1-427-768x603.jpg\" data-width=\"768\" data-height=\"603\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Audience-Day2-146-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDUyNCwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9BdWRpZW5jZS1EYXkyLTE0Ni1zY2FsZWQuanBnIiwic2xpZGVzaG93IjoiMDZkYmUwZCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Audience-Day2-146-768x328.jpg\" data-width=\"768\" data-height=\"328\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Chami-TIm-Day2-105-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDUxNCwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9DaGFtaS1USW0tRGF5Mi0xMDUtc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6IjA2ZGJlMGQifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Chami-TIm-Day2-105-768x787.jpg\" data-width=\"768\" data-height=\"787\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Godard-Jean-Francois-MIchelD-MeizMDay2-291-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDUwNSwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9Hb2RhcmQtSmVhbi1GcmFuY29pcy1NSWNoZWxELU1laXpNRGF5Mi0yOTEtc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6IjA2ZGJlMGQifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Godard-Jean-Francois-MIchelD-MeizMDay2-291-768x421.jpg\" data-width=\"768\" data-height=\"421\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/CalvinCheung-Chris-JOyce-Day2-133-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDUxOSwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9DYWx2aW5DaGV1bmctQ2hyaXMtSk95Y2UtRGF5Mi0xMzMtc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6IjA2ZGJlMGQifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/CalvinCheung-Chris-JOyce-Day2-133-768x561.jpg\" data-width=\"768\" data-height=\"561\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/LIstening-2Day2-032-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDQ5NywidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9MSXN0ZW5pbmctMkRheTItMDMyLXNjYWxlZC5qcGciLCJzbGlkZXNob3ciOiIwNmRiZTBkIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/LIstening-2Day2-032-768x327.jpg\" data-width=\"768\" data-height=\"327\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/CeesD-Day2-018-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDUxOCwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9DZWVzRC1EYXkyLTAxOC1zY2FsZWQuanBnIiwic2xpZGVzaG93IjoiMDZkYmUwZCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/CeesD-Day2-018-768x1092.jpg\" data-width=\"768\" data-height=\"1092\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Manon-Marie-Josee-Stephane-Day1-109-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDQ5MiwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9NYW5vbi1NYXJpZS1Kb3NlZS1TdGVwaGFuZS1EYXkxLTEwOS1zY2FsZWQuanBnIiwic2xpZGVzaG93IjoiMDZkYmUwZCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Manon-Marie-Josee-Stephane-Day1-109-768x367.jpg\" data-width=\"768\" data-height=\"367\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Audience-Day2-314-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDUyMywidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9BdWRpZW5jZS1EYXkyLTMxNC1zY2FsZWQuanBnIiwic2xpZGVzaG93IjoiMDZkYmUwZCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Audience-Day2-314-768x319.jpg\" data-width=\"768\" data-height=\"319\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Tony-Day1-169-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDQ4MSwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9Ub255LURheTEtMTY5LXNjYWxlZC5qcGciLCJzbGlkZXNob3ciOiIwNmRiZTBkIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Tony-Day1-169-768x739.jpg\" data-width=\"768\" data-height=\"739\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/5.Sudip-DreamPhotonics-Day1-451-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDUyOCwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC81LlN1ZGlwLURyZWFtUGhvdG9uaWNzLURheTEtNDUxLXNjYWxlZC5qcGciLCJzbGlkZXNob3ciOiIwNmRiZTBkIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/5.Sudip-DreamPhotonics-Day1-451-768x660.jpg\" data-width=\"768\" data-height=\"660\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Global-Success-fufull-panel-Day1-069-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDUwNiwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9HbG9iYWwtU3VjY2Vzcy1mdWZ1bGwtcGFuZWwtRGF5MS0wNjktc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6IjA2ZGJlMGQifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Global-Success-fufull-panel-Day1-069-768x450.jpg\" data-width=\"768\" data-height=\"450\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Interesting-Day2-156-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDUwMSwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9JbnRlcmVzdGluZy1EYXkyLTE1Ni1zY2FsZWQuanBnIiwic2xpZGVzaG93IjoiMDZkYmUwZCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Interesting-Day2-156-768x476.jpg\" data-width=\"768\" data-height=\"476\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Michael-Godard-MeizDay2-293-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDQ5MSwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9NaWNoYWVsLUdvZGFyZC1NZWl6RGF5Mi0yOTMtc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6IjA2ZGJlMGQifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Michael-Godard-MeizDay2-293-768x328.jpg\" data-width=\"768\" data-height=\"328\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Lynn-nice-Day2-107-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDQ5NCwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9MeW5uLW5pY2UtRGF5Mi0xMDctc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6IjA2ZGJlMGQifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Lynn-nice-Day2-107-768x465.jpg\" data-width=\"768\" data-height=\"465\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/11\/acss_RAY164961.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzY4NSwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzExXC9hY3NzX1JBWTE2NDk2MS5qcGciLCJzbGlkZXNob3ciOiIwNmRiZTBkIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/11\/acss_RAY164961-768x512.jpg\" data-width=\"768\" data-height=\"512\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Crowd-OpeningReception-057-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDUxMCwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9Dcm93ZC1PcGVuaW5nUmVjZXB0aW9uLTA1Ny1zY2FsZWQuanBnIiwic2xpZGVzaG93IjoiMDZkYmUwZCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Crowd-OpeningReception-057-768x512.jpg\" data-width=\"768\" data-height=\"512\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Hamid-A-question.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDUwMywidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9IYW1pZC1BLXF1ZXN0aW9uLmpwZyIsInNsaWRlc2hvdyI6IjA2ZGJlMGQifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Hamid-A-question-768x749.jpg\" data-width=\"768\" data-height=\"749\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Avinash-Rakesh-Craig-Day1-081-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDUyMSwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9BdmluYXNoLVJha2VzaC1DcmFpZy1EYXkxLTA4MS1zY2FsZWQuanBnIiwic2xpZGVzaG93IjoiMDZkYmUwZCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Avinash-Rakesh-Craig-Day1-081-768x481.jpg\" data-width=\"768\" data-height=\"481\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Rakesh-P-OpeningReception-065-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDQ4NSwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9SYWtlc2gtUC1PcGVuaW5nUmVjZXB0aW9uLTA2NS1zY2FsZWQuanBnIiwic2xpZGVzaG93IjoiMDZkYmUwZCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Rakesh-P-OpeningReception-065-768x777.jpg\" data-width=\"768\" data-height=\"777\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Listening-Day2-022-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDQ5NiwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9MaXN0ZW5pbmctRGF5Mi0wMjItc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6IjA2ZGJlMGQifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Listening-Day2-022-768x355.jpg\" data-width=\"768\" data-height=\"355\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Kamal-Peter-Day1-296-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDQ5OCwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9LYW1hbC1QZXRlci1EYXkxLTI5Ni1zY2FsZWQuanBnIiwic2xpZGVzaG93IjoiMDZkYmUwZCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Kamal-Peter-Day1-296-768x499.jpg\" data-width=\"768\" data-height=\"499\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/BrianJ-Stuart-RobP-Day2-247-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDUyMCwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9CcmlhbkotU3R1YXJ0LVJvYlAtRGF5Mi0yNDctc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6IjA2ZGJlMGQifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/BrianJ-Stuart-RobP-Day2-247-768x385.jpg\" data-width=\"768\" data-height=\"385\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Lynn-Sue-Lisa-Day2-326-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDQ5MywidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9MeW5uLVN1ZS1MaXNhLURheTItMzI2LXNjYWxlZC5qcGciLCJzbGlkZXNob3ciOiIwNmRiZTBkIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Lynn-Sue-Lisa-Day2-326-768x426.jpg\" data-width=\"768\" data-height=\"426\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/AcceleratedDay1-283.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDUyNiwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9BY2NlbGVyYXRlZERheTEtMjgzLmpwZyIsInNsaWRlc2hvdyI6IjA2ZGJlMGQifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/AcceleratedDay1-283-768x492.jpg\" data-width=\"768\" data-height=\"492\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Chris-Rampersand-Day2-047-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDUxMiwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9DaHJpcy1SYW1wZXJzYW5kLURheTItMDQ3LXNjYWxlZC5qcGciLCJzbGlkZXNob3ciOiIwNmRiZTBkIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Chris-Rampersand-Day2-047-768x424.jpg\" data-width=\"768\" data-height=\"424\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Chami-Nyabeze-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDUxNiwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9DaGFtaS1OeWFiZXplLXNjYWxlZC5qcGciLCJzbGlkZXNob3ciOiIwNmRiZTBkIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Chami-Nyabeze-768x445.jpg\" data-width=\"768\" data-height=\"445\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Darrell-Day2-361-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDUwOSwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9EYXJyZWxsLURheTItMzYxLXNjYWxlZC5qcGciLCJzbGlkZXNob3ciOiIwNmRiZTBkIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Darrell-Day2-361-768x357.jpg\" data-width=\"768\" data-height=\"357\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Stephane-Philippe-JeanLuc-Day1-120-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDQ4MywidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9TdGVwaGFuZS1QaGlsaXBwZS1KZWFuTHVjLURheTEtMTIwLXNjYWxlZC5qcGciLCJzbGlkZXNob3ciOiIwNmRiZTBkIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Stephane-Philippe-JeanLuc-Day1-120-768x533.jpg\" data-width=\"768\" data-height=\"533\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Panel-smiles-Day2-166-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDQ4OCwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9QYW5lbC1zbWlsZXMtRGF5Mi0xNjYtc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6IjA2ZGJlMGQifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Panel-smiles-Day2-166-768x344.jpg\" data-width=\"768\" data-height=\"344\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Great-shot-RobertS-Lisa-May-Day2-171-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDUwNCwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9HcmVhdC1zaG90LVJvYmVydFMtTGlzYS1NYXktRGF5Mi0xNzEtc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6IjA2ZGJlMGQifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Great-shot-RobertS-Lisa-May-Day2-171-768x512.jpg\" data-width=\"768\" data-height=\"512\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/1.Philippe-Aeponyx-Day1-408-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDUzMiwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC8xLlBoaWxpcHBlLUFlcG9ueXgtRGF5MS00MDgtc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6IjA2ZGJlMGQifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/1.Philippe-Aeponyx-Day1-408-768x550.jpg\" data-width=\"768\" data-height=\"550\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Debjani-ColinDay2-263-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDUwOCwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9EZWJqYW5pLUNvbGluRGF5Mi0yNjMtc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6IjA2ZGJlMGQifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Debjani-ColinDay2-263-768x488.jpg\" data-width=\"768\" data-height=\"488\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Questions-2-Day2-065-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"06dbe0d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDQ4NiwidXJsIjoiaHR0cHM6XC9cL2ZhYnJpY2lubm92YXRpb24uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzAxXC9RdWVzdGlvbnMtMi1EYXkyLTA2NS1zY2FsZWQuanBnIiwic2xpZGVzaG93IjoiMDZkYmUwZCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2026\/01\/Questions-2-Day2-065-768x623.jpg\" data-width=\"768\" data-height=\"623\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d2d50ac elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d2d50ac\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9933346\" data-id=\"9933346\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c63ded1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c63ded1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2a5ff73 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2a5ff73\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2e1bb49\" data-id=\"2e1bb49\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cfcf119 elementor-widget elementor-widget-template\" data-id=\"cfcf119\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"3368\" class=\"elementor elementor-3368 elementor-3290 elementor-3290\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6ec28fea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6ec28fea\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1c8d7a0f\" data-id=\"1c8d7a0f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71fda329 elementor-widget elementor-widget-heading\" data-id=\"71fda329\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Merci d'\u00eatre venu.<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30307f39 elementor-align-center elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"30307f39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.eventbrite.ca\/e\/accelerated-canadas-semiconductor-symposium-2025-tickets-1559404223009\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Inscrivez-vous d\u00e8s aujourd\u2019hui\u202f!<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f3867ec elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-icon-box\" data-id=\"5f3867ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tLe lien s\u2019ouvre dans une nouvelle fen\u00eatre\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-756c11c6\" data-id=\"756c11c6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-483594d6 elementor-widget elementor-widget-heading\" data-id=\"483594d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">O\u00f9<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68b798f7 elementor-widget elementor-widget-text-editor\" data-id=\"68b798f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Sheraton Vancouver Wall Centre<br>1000 rue Burrard <br>Vancouver, C.-B.<br> V6Z 2R9<br>(604) 331-1000<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75f44c23 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"75f44c23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.marriott.com\/event-reservations\/reservation-link.mi?id=1664315739084&amp;key=CORP&amp;app=resvlink\"><span data-olk-copy-source=\"MessageBody\">Restez sur place \u2013 R\u00e9servez votre chambre d\u00e8s maintenant<\/span><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-267dde54 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"267dde54\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-797db9dc\" data-id=\"797db9dc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52b16d9 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"52b16d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5118be0 elementor-widget elementor-widget-heading\" data-id=\"5118be0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Merci \u00e0 nos g\u00e9n\u00e9reux sponsors<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32c23f1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"32c23f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50bc200 elementor-widget elementor-widget-heading\" data-id=\"50bc200\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">ARGENT<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-303ae65d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"303ae65d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-25c292f5\" data-id=\"25c292f5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d10e855 elementor-widget elementor-widget-image\" data-id=\"d10e855\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ranovus.com\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1001\" height=\"420\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/Ranovus-tag-logo-t.jpg\" class=\"attachment-large size-large wp-image-3504\" alt=\"\" srcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/Ranovus-tag-logo-t.jpg 1001w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/Ranovus-tag-logo-t-300x126.jpg 300w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/Ranovus-tag-logo-t-768x322.jpg 768w\" sizes=\"(max-width: 1001px) 100vw, 1001px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-9d55c35\" data-id=\"9d55c35\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-5a7422b7\" data-id=\"5a7422b7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5b3519a elementor-widget elementor-widget-image\" data-id=\"5b3519a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.teledynemems.com\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"72\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/teledyne_mems.png\" class=\"attachment-full size-full wp-image-3367\" alt=\"\" srcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/teledyne_mems.png 900w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/teledyne_mems-300x24.png 300w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/teledyne_mems-768x61.png 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-7e44993\" data-id=\"7e44993\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-84e34f0\" data-id=\"84e34f0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39405c49 elementor-widget elementor-widget-image\" data-id=\"39405c49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tenstorrent.com\/en\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/elementor\/thumbs\/tenstorrent_logo-rcbrq9rdke899j96yikptjet5t275u07fvceoaz9jc.png\" title=\"tenstorrent_logo\" alt=\"tenstorrent_logo\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-778e75ff elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"778e75ff\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-48b679ab\" data-id=\"48b679ab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f789adf elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f789adf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d66b1be elementor-widget elementor-widget-heading\" data-id=\"d66b1be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">BRONZE<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ddf45c6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ddf45c6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-f3476c9\" data-id=\"f3476c9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-af3ac70\" data-id=\"af3ac70\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc68d2b elementor-widget elementor-widget-image\" data-id=\"cc68d2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.canadassemiconductorcouncil.com\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/elementor\/thumbs\/CSC-logo-rdjjban7jbnd07e5z2kvfp7687gwrux87q0bxy6btu.png\" title=\"CSC-logo\" alt=\"CSC-logo\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-0101c69\" data-id=\"0101c69\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-26bbd03\" data-id=\"26bbd03\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6689b393 elementor-widget elementor-widget-image\" data-id=\"6689b393\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.venturelab.ca\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/ventureLAB_logo.png\" class=\"attachment-full size-full wp-image-3458\" alt=\"\" srcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/ventureLAB_logo.png 1920w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/ventureLAB_logo-300x169.png 300w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/ventureLAB_logo-1024x576.png 1024w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/ventureLAB_logo-768x432.png 768w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/ventureLAB_logo-1536x864.png 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-1d1fdfb\" data-id=\"1d1fdfb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1a35a09 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1a35a09\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-435cead\" data-id=\"435cead\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fc30154 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"fc30154\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5297be elementor-widget elementor-widget-heading\" data-id=\"c5297be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">TEXPO COMMANDITAIRE PRINCIPAL<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aff6fc9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aff6fc9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-de266a4\" data-id=\"de266a4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-d175585\" data-id=\"d175585\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-7e2ead1\" data-id=\"7e2ead1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8c3729d elementor-widget elementor-widget-image\" data-id=\"8c3729d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/gf.com\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"200\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/10\/GF_logo_orange-1024x200.png\" class=\"attachment-large size-large wp-image-3538\" alt=\"\" srcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/10\/GF_logo_orange-1024x200.png 1024w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/10\/GF_logo_orange-300x59.png 300w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/10\/GF_logo_orange-768x150.png 768w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/10\/GF_logo_orange.png 1148w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-e3eccaa\" data-id=\"e3eccaa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-87f932b\" data-id=\"87f932b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c12afaa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c12afaa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-49dc391\" data-id=\"49dc391\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cac5768 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"cac5768\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5fc8b12 elementor-widget elementor-widget-heading\" data-id=\"5fc8b12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Sponsors des prix<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7e394d0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7e394d0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-6657905\" data-id=\"6657905\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-d662519\" data-id=\"d662519\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-cecfe62\" data-id=\"cecfe62\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e42d23 elementor-widget elementor-widget-image\" data-id=\"4e42d23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/11\/Logo_CMC_RGB_Fr-1024x683.jpg\" class=\"attachment-large size-large wp-image-705\" alt=\"\" srcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/11\/Logo_CMC_RGB_Fr-1024x683.jpg 1024w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/11\/Logo_CMC_RGB_Fr-300x200.jpg 300w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/11\/Logo_CMC_RGB_Fr-768x512.jpg 768w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/11\/Logo_CMC_RGB_Fr-1536x1024.jpg 1536w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/11\/Logo_CMC_RGB_Fr-600x400.jpg 600w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/11\/Logo_CMC_RGB_Fr.jpg 1651w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-d00466c\" data-id=\"d00466c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cbc3519 elementor-widget elementor-widget-image\" data-id=\"cbc3519\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/gf.com\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"55\" src=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/Comsol_logo.jpg\" class=\"attachment-large size-large wp-image-3288\" alt=\"\" srcset=\"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/Comsol_logo.jpg 600w, https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/09\/Comsol_logo-300x28.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-7dd2e8c\" data-id=\"7dd2e8c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-c51d98e\" data-id=\"c51d98e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6f95a6cc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6f95a6cc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ead81b1\" data-id=\"ead81b1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-291af0e7 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"291af0e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-528e0a9d elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"528e0a9d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2c6fb691\" data-id=\"2c6fb691\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-dab6e22 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dab6e22\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c4c7800\" data-id=\"c4c7800\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-559c8248 elementor-widget elementor-widget-heading\" data-id=\"559c8248\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Parrainage Acc\u00e9l\u00e9r\u00e9<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b2d92d3 elementor-widget elementor-widget-text-editor\" data-id=\"6b2d92d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\"><span data-olk-copy-source=\"MessageBody\">Contactez-nous pour en savoir plus sur les possibilit\u00e9s de parrainage et d&rsquo;exposition.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-35375468\" data-id=\"35375468\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-240b5819 elementor-widget elementor-widget-html\" data-id=\"240b5819\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<iframe title=\"Contact\" width=\"300\" height=\"240\" src=\"https:\/\/go.cmc.ca\/l\/947082\/2025-09-25\/3n9ykd\">\n<\/iframe>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b6f8df7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b6f8df7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9c160bc\" data-id=\"9c160bc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b172e73 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b172e73\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Acc\u00e9l\u00e9r\u00e9. Symposium canadien sur les semi-conducteurs 2025. Points saillants Points saillants<\/p>\n","protected":false},"author":6,"featured_media":2905,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-4535","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"featured_image_src":"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/07\/website-box-accelerated-800x400-FRE-600x400.jpg","featured_image_src_square":"https:\/\/fabricinnovation.ca\/wp-content\/uploads\/2025\/07\/website-box-accelerated-800x400-FRE-600x400.jpg","_links":{"self":[{"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/pages\/4535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/comments?post=4535"}],"version-history":[{"count":0,"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/pages\/4535\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/media\/2905"}],"wp:attachment":[{"href":"https:\/\/fabricinnovation.ca\/fr\/wp-json\/wp\/v2\/media?parent=4535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}]